{"id":2255,"date":"2021-05-28T10:34:13","date_gmt":"2021-05-28T10:34:13","guid":{"rendered":"https:\/\/blogs.uned.es\/sociologia2\/?p=2255"},"modified":"2021-05-28T10:40:05","modified_gmt":"2021-05-28T10:40:05","slug":"el-proyecto-mic-en-radio-3","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/sociologia2\/2021\/05\/28\/el-proyecto-mic-en-radio-3\/","title":{"rendered":"El proyecto MiC en Radio 3"},"content":{"rendered":"<p>Recientemente, el espacio de la UNED en Radio 3 (\u201cSin distancias\u201d) emiti\u00f3 un <a href=\"https:\/\/www.rtve.es\/alacarta\/audios\/uned\/uned-16-05-21\/5914441\/\">coloquio<\/a> entre los investigadores <a href=\"http:\/\/blogs.uned.es\/sociologia2\/irina-fernandez-lozano\/\">Irina Fern\u00e1ndez<\/a> (de Sociolog\u00eda II), <a href=\"http:\/\/portal.uned.es\/portal\/page?_pageid=93,66571276&amp;_dad=portal&amp;_schema=PORTAL\">Cristina Castellanos<\/a> y <a href=\"https:\/\/www.udg.edu\/ca\/directori\/pagina-personal?ID=4000414\">Paco Abril<\/a> sobre el proyecto europeo <a href=\"https:\/\/www.men-in-care.eu\/about\">Men in Care (MiC)<\/a>, que dirige <a href=\"http:\/\/blogs.uned.es\/sociologia2\/teresa-jurado\/\">Teresa Jurado<\/a>, tambi\u00e9n profesora de Sociolog\u00eda II. El proyecto MiC analiza las pol\u00edticas p\u00fablicas y empresariales que favorecen que los hombres participen en los cuidados de los menores o adultos dependientes de su familia o entorno cercano, y los obst\u00e1culos que a\u00fan encuentran para hacerlo. Como parte de la investigaci\u00f3n, se ha entrevistado a m\u00e1s de 150 personas, entre hombres trabajadores, directivos\/as de empresas y representantes sindicales de 18 organizaciones en los 7 pa\u00edses participantes. Los resultados de esta investigaci\u00f3n se pueden leer ya <a href=\"https:\/\/www.men-in-care.eu\/results\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recientemente, el espacio de la UNED en Radio 3 (\u201cSin distancias\u201d) emiti\u00f3 un coloquio entre los investigadores Irina Fern\u00e1ndez (de Sociolog\u00eda II), Cristina Castellanos y Paco Abril sobre el proyecto europeo Men in Care (MiC), que dirige Teresa Jurado, tambi\u00e9n profesora de Sociolog\u00eda II. El proyecto MiC analiza las pol\u00edticas p\u00fablicas y empresariales que favorecen &hellip; <a href=\"https:\/\/blogs.uned.es\/sociologia2\/2021\/05\/28\/el-proyecto-mic-en-radio-3\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">El proyecto MiC en Radio 3<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7157,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[27,19,5],"class_list":["post-2255","post","type-post","status-publish","format-standard","hentry","category-en-la-radio","tag-conciliacion","tag-familia","tag-genero"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/posts\/2255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/users\/7157"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/comments?post=2255"}],"version-history":[{"count":1,"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/posts\/2255\/revisions"}],"predecessor-version":[{"id":2257,"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/posts\/2255\/revisions\/2257"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/media?parent=2255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/categories?post=2255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/sociologia2\/wp-json\/wp\/v2\/tags?post=2255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}