{"id":1401,"date":"2020-05-19T11:33:41","date_gmt":"2020-05-19T11:33:41","guid":{"rendered":"http:\/\/blogs.uned.es\/salidasprofesionales\/?page_id=1401"},"modified":"2020-06-01T14:29:38","modified_gmt":"2020-06-01T14:29:38","slug":"ocupaciones-puestos-ciencia-politica-y-de-la-administracion","status":"publish","type":"page","link":"https:\/\/blogs.uned.es\/salidasprofesionales\/grados\/ciencias-sociales-y-juridicas\/grado-en-ciencia-politica-y-de-la-administracion\/ocupaciones-puestos-ciencia-politica-y-de-la-administracion\/","title":{"rendered":"Ocupaciones\/puestos (Ciencia Pol\u00edtica y de la Administraci\u00f3n)"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-1409 alignleft\" src=\"http:\/\/blogs.uned.es\/salidasprofesionales\/wp-content\/uploads\/sites\/165\/2020\/05\/puestos-1-300x168.png\" alt=\"\" width=\"300\" height=\"168\" \/><\/p>\n<p>&#8211; <strong>T\u00e9cnicos de las Administraciones P\u00fablicas<\/strong>: desarrolla tareas de direcci\u00f3n, gesti\u00f3n, inspecci\u00f3n, coordinaci\u00f3n, control y estudio, as\u00ed como el dise\u00f1o y planeamiento de propuestas de mejora para las Administraciones p\u00fablicas, \u00f3rganos constitucionales e instituciones y organizaciones de car\u00e1cter p\u00fablico que operan en el \u00e1mbito europeo, estatal, auton\u00f3mico y local, a las cu\u00e1les se accede mediante oposici\u00f3n o contrataci\u00f3n. El nivel territorial de actuaci\u00f3n es: europeo, estatal, auton\u00f3mico y local.<\/p>\n<p>&#8211;<strong>Gestor de organizaciones:<\/strong> desarrolla tareas de direcci\u00f3n, planificaci\u00f3n y gesti\u00f3n que garanticen los objetivos y fines de organizaciones y\/o entes instrumentales, as\u00ed como tareas de comunicaci\u00f3n y transmisi\u00f3n entre el nivel directivo y el operativo. Facilita las relaciones interinstitucionales, interadministrativas, con los medios de comunicaci\u00f3n y los agentes sociales. Su \u00e1mbito de actuaci\u00f3n lo constituyen los organismos aut\u00f3nomos, entidades p\u00fablicas empresariales, sociedades p\u00fablicas, fundaciones p\u00fablicas y tercer sector. El nivel territorial de actuaci\u00f3n es: internacional, estatal, auton\u00f3mico y local.<\/p>\n<p>&#8211;<strong>Analista de pol\u00edticas p\u00fablicas:<\/strong> analiza las pol\u00edticas p\u00fablicas en las respectivas fases de: identificaci\u00f3n y definici\u00f3n de problemas, as\u00ed como de formulaci\u00f3n e implementaci\u00f3n de programas y acciones. Eval\u00faa pol\u00edticas p\u00fablicas y plantea alternativas para mejorar actuaciones p\u00fablicas sucesivas. El nivel territorial de actuaci\u00f3n es: internacional, europeo, estatal, auton\u00f3mico y local.<\/p>\n<p><strong>-T\u00e9cnico en investigaci\u00f3n social aplicada y estudios de opini\u00f3n p\u00fablica:<\/strong> Se encarga de planificar y llevar a cabo la recogida y an\u00e1lisis de la informaci\u00f3n relacionada con los fen\u00f3menos sociales contempor\u00e1neos en sus m\u00faltiples dimensiones (pol\u00edtica, econ\u00f3mica, cultural, comunicacional), con los procesos de cambio en las pr\u00e1cticas, formas y organizaciones sociales y, en general, con la articulaci\u00f3n entre los diferentes \u00e1mbitos de la actividad humana. Parte importante de estos estudios tienen como objetivo que la Administraci\u00f3n, los partidos pol\u00edticos y las organizaciones no gubernamentales tomen las decisiones adecuadas, para lo cual necesitan contar con informaci\u00f3n que explique cu\u00e1l es el impacto de cada decisi\u00f3n en la opini\u00f3n p\u00fablica.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1411 alignright\" src=\"http:\/\/blogs.uned.es\/salidasprofesionales\/wp-content\/uploads\/sites\/165\/2020\/05\/puesto-2.jpg\" alt=\"\" width=\"183\" height=\"174\" \/><\/p>\n<p>Investigan la relaci\u00f3n o el impacto de la ciencia y la tecnolog\u00eda en la sociedad, los fen\u00f3menos asociados a la globalizaci\u00f3n, la inmigraci\u00f3n, los movimientos sociales, las identidades sociales, la implicaci\u00f3n social del g\u00e9nero o el medioambiente y el uso de los espacios urbanos y rurales. Fundamentalmente, se sirven de dos metodolog\u00edas de recogida y an\u00e1lisis de los datos: los m\u00e9todos cualitativos (entrevista en profundidad, grupo de discusi\u00f3n, entrevista semiestructurada) y los m\u00e9todos cuantitativos (entrevista personal, telef\u00f3nica o postal, panel de informadores).<\/p>\n<p><strong>-Agente de desarrollo local:<\/strong> Define, programa y ejecuta acciones orientadas al desarrollo integral a nivel local. Dise\u00f1a estrategias para la promoci\u00f3n de la actividad empresarial, la creaci\u00f3n de empleo y el desarrollo sostenible. Participa en la gesti\u00f3n de programas europeos. Dise\u00f1a planes comunitarios para fomentar la participaci\u00f3n ciudadana y dinamizar el tejido asociativo local.<\/p>\n<p><strong>-Analista pol\u00edtico:<\/strong> analiza e interpreta la realidad pol\u00edtica y social. Analiza las opiniones, los valores y las actitudes de los ciudadanos as\u00ed como las posiciones y las din\u00e1micas de los diferentes actores pol\u00edticos. Analiza resultados electorales. Define escenarios pol\u00edticos, eval\u00faa objetivos, dise\u00f1a estrategias pol\u00edticas y campa\u00f1as electorales de organizaciones pol\u00edticas, sociales e institucionales. Supervisa y prueba la calidad y fiabilidad de los indicadores sociopol\u00edticos para la toma de decisiones.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1413 alignleft\" src=\"http:\/\/blogs.uned.es\/salidasprofesionales\/wp-content\/uploads\/sites\/165\/2020\/05\/puesto-3.jpg\" alt=\"\" width=\"260\" height=\"160\" \/><\/p>\n<p><strong>-Asesor y Consultor:<\/strong> desempe\u00f1a funciones de asesoramiento y asistencia t\u00e9cnica a las Administraciones P\u00fablicas e instituciones pol\u00edticas; a las organizaciones pol\u00edticas de representaci\u00f3n de intereses y no gubernamentales; as\u00ed como al sector privado en sus relaciones con el sector p\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>-Consultor Sector P\u00fablico.<\/strong> Se encarga de implementar proyectos y programas subcontratados con administraciones p\u00fablicas de diversos \u00e1mbitos como pueden ser la evaluaci\u00f3n de pol\u00edticas p\u00fablicas, la implantaci\u00f3n de Oficinas de Atenci\u00f3n al Ciudadano (OAC) por parte de ayuntamientos, la introducci\u00f3n de software en la administraci\u00f3n p\u00fablica, etc.<\/p>\n<p><strong>-Consultor internacional:<\/strong> desarrolla funciones de asesoramiento y asistencia t\u00e9cnica en materia de pol\u00edticas nacionales e internacionales a responsables p\u00fablicos y pol\u00edticos de instituciones nacionales e internacionales, organizaciones del Tercer Sector y empresas con proyecci\u00f3n internacional. Planifica, desarrolla, coordina y eval\u00faa proyectos de cooperaci\u00f3n y desarrollo en otros pa\u00edses. Realiza funciones de observador internacional en procesos de paz y de democratizaci\u00f3n. Media en la gesti\u00f3n de crisis y en la resoluci\u00f3n de conflictos.<\/p>\n<p><strong>-Docente e Investigador:<\/strong> desarrolla actividades que tienen por objeto impartir docencia en procesos formativos de ense\u00f1anza reglada y no reglada. Desarrolla actividades encaminadas a aportar nuevos avances al conocimiento cient\u00edfico de los fen\u00f3menos pol\u00edticos. Elabora documentos de car\u00e1cter cient\u00edfico y materiales did\u00e1cticos. Profesional que practica la docencia en los centros de ense\u00f1anza de secundaria y universitaria.<\/p>\n<p>En funci\u00f3n de la materia a impartir ser\u00e1 necesaria la titulaci\u00f3n asociada a la misma; programaci\u00f3n did\u00e1ctica de la materia a impartir; selecci\u00f3n, elaboraci\u00f3n, adaptaci\u00f3n y utilizaci\u00f3n de materiales, medios y recursos did\u00e1cticos; evaluaci\u00f3n del proceso de ense\u00f1anza-aprendizaje.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1415 alignright\" src=\"http:\/\/blogs.uned.es\/salidasprofesionales\/wp-content\/uploads\/sites\/165\/2020\/05\/puesto-4-300x164.png\" alt=\"\" width=\"300\" height=\"164\" \/><\/p>\n<p>Los graduados en Ciencia Pol\u00edtica y de la Administraci\u00f3n podr\u00e1n ejercer como docentes en la Ense\u00f1anza Secundaria, Bachillerato y Formaci\u00f3n Profesional una vez obtenido el M\u00e1ster de Formaci\u00f3n del Profesorado, y podr\u00e1n impartir asignaturas relacionadas con la especialidad de Especialidad de Formaci\u00f3n y Orientaci\u00f3n Laboral. Ser Profesor Titular de Universidad acreditado exige poseer el t\u00edtulo de Doctor. Los candidatos deber\u00e1n presentar la correspondiente solicitud a la que acompa\u00f1ar\u00e1n la justificaci\u00f3n de los m\u00e9ritos que aduzcan de car\u00e1cter acad\u00e9mico, profesional, docente e investigador y de gesti\u00f3n acad\u00e9mica y cient\u00edfica.<\/p>\n<p>El investigador analiza de manera sistem\u00e1tica y organizada una cuesti\u00f3n (concepto, teor\u00eda o modelo), con el objetivo de responder a una hip\u00f3tesis para tener m\u00e1s conocimiento o informaci\u00f3n sobre algo desconocido. Se investiga a trav\u00e9s de la simulaci\u00f3n y con m\u00e9todos de campo o laboratorio. Las actividades principales de una investigaci\u00f3n son la medici\u00f3n de fen\u00f3menos, la comparaci\u00f3n de resultados obtenidos y la interpretaci\u00f3n de los resultados con relaci\u00f3n a lo que se conoce en la actualidad. Para iniciar la formaci\u00f3n investigadora es necesario estar en posesi\u00f3n del t\u00edtulo de Graduado, Arquitecto, Ingeniero o equivalente, completar los cr\u00e9ditos necesarios dentro de un programa de Doctorado y presentar un proyecto original de investigaci\u00f3n que tras su defensa y aprobaci\u00f3n supondr\u00e1 la obtenci\u00f3n del t\u00edtulo de Doctor.<\/p>\n<p><strong>Administradores civiles y t\u00e9cnicos\/as superiores de las administraciones p\u00fablicas y \u00f3rganos constitucionales:\u00a0<\/strong> estos profesionales desarrollan tareas de gesti\u00f3n, inspecci\u00f3n, control, estudio, y propuesta de car\u00e1cter administrativo de nivel superior en las Administraciones p\u00fablicas, \u00f3rganos constitucionales e instituciones y organizaciones de car\u00e1cter p\u00fablico que operan en el \u00e1mbito europeo, estatal, auton\u00f3mico y local, a las cu\u00e1les se accede mediante oposici\u00f3n o contrataci\u00f3n.<\/p>\n<p><strong>-Agente de igualdad de oportunidades.<\/strong> Profesional que dise\u00f1a, dirige, coordina, dinamiza, implementa, gestiona y eval\u00faa planes, programas, proyectos y campa\u00f1as de acci\u00f3n positiva referidos a la igualdad de oportunidades entre mujeres y hombres en diferentes \u00e1reas y escenarios profesionales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1417 alignleft\" src=\"http:\/\/blogs.uned.es\/salidasprofesionales\/wp-content\/uploads\/sites\/165\/2020\/05\/puesto-5-300x153.jpg\" alt=\"\" width=\"300\" height=\"153\" \/><\/p>\n<p><strong>-Agente de participaci\u00f3n ciudadana Responsable de dise\u00f1ar, difundir e impulsar estrategias encaminadas a fomentar la participaci\u00f3n ciudadana.<\/strong> Lideran e implementan las tareas del voluntariado y mundo asociativo, al igual que es el responsable de evaluar sus resultados.<\/p>\n<p><strong>-Asesor\/a en comportamiento pol\u00edtico.<\/strong> Profesional que asesora a pol\u00edticos y pol\u00edticas sobre las decisiones y conductas que m\u00e1s les beneficien en funci\u00f3n del momento y posici\u00f3n global en las que se encuentren. Ha de poseer una gran capacidad de observaci\u00f3n y an\u00e1lisis, facilitando las decisiones que deben tomar aquellos y aquellas para los que trabajan.<\/p>\n<p><strong>-Diplom\u00e1tico\/a<\/strong>. Profesional al servicio de la Administraci\u00f3n del Estado, que representa oficialmente a su pa\u00eds en el exterior, bien sea en una misi\u00f3n permanente (ante otro estado o ante un organismo internacional) o en una misi\u00f3n especial. Aparte de la funci\u00f3n de representaci\u00f3n, tambi\u00e9n debe asumir la de informar y negociar, especialmente en situaciones de conflicto. Para llegar a ser diplom\u00e1tico hay que superar la oposici\u00f3n que anualmente convoca el Ministerio de Asuntos Exteriores a trav\u00e9s de la Escuela Diplom\u00e1tica.<\/p>\n<p>En Espa\u00f1a existen diferentes categor\u00edas de diplom\u00e1ticos seg\u00fan el escalaf\u00f3n en la carrera diplom\u00e1tica: Embajador, Ministro plenipotenciario, Ministro Consejero (de 1\u00aa, 2\u00aa y 3\u00aa), Secretario de Embajada (de 1\u00aa, 2\u00aa y 3\u00aa). Esta profesi\u00f3n lleva aparejados constantes traslados de destino y lugar de residencia, la necesidad del dominio de varios idiomas, as\u00ed como el inter\u00e9s y conocimiento profundo de la complejidad de las relaciones y la pol\u00edtica internacional.<\/p>\n<p><strong>-Experto\/a en opini\u00f3n p\u00fablica.<\/strong> Profesional encargado de planificar, coordinar y analizar los estudios encaminados a conocer las percepciones de los ciudadanos respecto a cuestiones de car\u00e1cter pol\u00edtico y social. Entre sus actividades, supervisa y prueba la calidad y la fiabilidad de los indicadores para la toma de decisiones.<\/p>\n<p><strong>-Gestor\/a o asesor\/a de ayudas y subvenciones.<\/strong> Profesional que se encarga de la b\u00fasqueda de informaci\u00f3n, tramitaci\u00f3n, cobro y justificaci\u00f3n de las ayudas y subvenciones que conceden la Uni\u00f3n Europea, la Administraci\u00f3n Central, las Comunidades Aut\u00f3nomas y otras entidades regionales y locales. Trabaja tanto para proyectos de inversi\u00f3n y financiaci\u00f3n de entidades privadas, como para la obtenci\u00f3n de financiaci\u00f3n p\u00fablica para proyectos de corporaciones locales y otras entidades p\u00fablicas, en el \u00e1mbito del desarrollo local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; T\u00e9cnicos de las Administraciones P\u00fablicas: desarrolla tareas de direcci\u00f3n, gesti\u00f3n, inspecci\u00f3n, coordinaci\u00f3n, control y estudio, as\u00ed como el dise\u00f1o y planeamiento de propuestas de mejora para las Administraciones p\u00fablicas, \u00f3rganos constitucionales e instituciones y organizaciones de car\u00e1cter p\u00fablico que operan en el \u00e1mbito europeo, estatal, auton\u00f3mico y local, a las cu\u00e1les se accede mediante [&hellip;]<\/p>\n","protected":false},"author":5997,"featured_media":0,"parent":211,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1401","page","type-page","status-publish","czr-hentry"],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/pages\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/users\/5997"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/comments?post=1401"}],"version-history":[{"count":4,"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/pages\/1401\/revisions"}],"predecessor-version":[{"id":1419,"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/pages\/1401\/revisions\/1419"}],"up":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/pages\/211"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/salidasprofesionales\/wp-json\/wp\/v2\/media?parent=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}