{"id":463,"date":"2022-09-15T18:22:00","date_gmt":"2022-09-15T18:22:00","guid":{"rendered":"https:\/\/blogs.uned.es\/lhfc\/?p=463"},"modified":"2022-10-13T10:51:29","modified_gmt":"2022-10-13T10:51:29","slug":"master-universitario-en-filosofia-teorica-y-practica-calendario-de-defensas-de-tfm-convocatoria-septiembre-2022-especialidad-logica-historia-y-filosofia-de-la-ciencia","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/lhfc\/2022\/09\/15\/master-universitario-en-filosofia-teorica-y-practica-calendario-de-defensas-de-tfm-convocatoria-septiembre-2022-especialidad-logica-historia-y-filosofia-de-la-ciencia\/","title":{"rendered":"M\u00c1STER UNIVERSITARIO EN FILOSOF\u00cdA TE\u00d3RICA Y PR\u00c1CTICA   CALENDARIO DE DEFENSAS DE TFM CONVOCATORIA SEPTIEMBRE 2022   Especialidad: L\u00d3GICA, HISTORIA Y FILOSOF\u00cdA DE LA CIENCIA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">M\u00c1STER UNIVERSITARIO EN FILOSOF\u00cdA TE\u00d3RICA Y PR\u00c1CTICA<br> <br>CALENDARIO DE DEFENSAS DE TFM CONVOCATORIA SEPTIEMBRE 2022<br> <br>Especialidad: L\u00d3GICA, HISTORIA Y FILOSOF\u00cdA DE LA CIENCIA<br> <br>  <br>1.<br>Estudiante:  \u00c1ngel Luis Ortigosa Canca<br>T\u00edtulo: Organicismo vs. genocentrismo (evolutivos). Las s\u00edntesis evolutivas y sus compromisos ontoepistemol\u00f3gicos<br>Tutor:  V\u00edctor Luque Mart\u00edn<br>Tribunal: Cristian Saborido, V\u00edctor Luque y Giorgio Airoldi<br>D\u00eda y hora: 3 de octubre, 11:00 (online)<br> <br>2.<br>Estudiante:  Alberto S\u00e1nchez \u00c1lvarez<br>T\u00edtulo: Entre la filosof\u00eda continental y la filosof\u00eda anal\u00edtica. La constituci\u00f3n de los objetos<br>Tutor: Amparo D\u00edez<br>Tribunal: Cristian Saborido, Umberto Rivieccio, Amparo D\u00edez<br>D\u00eda y hora: 4 de octubre a las 11:00 (online)<br><br>3.<br>Estudiante:  Noelia Felpeto Rodr\u00edguez<br>T\u00edtulo: Habilidades ling\u00fc\u00edsticas en aves psitaciformes<br>Tutor: Susana Mons\u00f3<br>Tribunal: Javier Gonz\u00e1lez de Prado, Claudia Picazo, Susana Mons\u00f3<br>D\u00eda y hora:  4 octubre, 17:00 (online)<br><br>4.<br>Estudiante:  Ra\u00fal Santamar\u00eda Dom\u00ednguez<br>T\u00edtulo: Dimensi\u00f3n Evolutiva de la Racionalidad. Una Aproximaci\u00f3n a la Racionalidad Humana<br>Tutor:  J. Francisco \u00c1lvarez<br>Tribunal: Eduardo Bustos, Mar\u00eda Jim\u00e9nez, J. Francisco \u00c1lvarez.  <br>D\u00eda y hora:  6 de octubre a las 11:00 (online)<br><br>5.<br>Estudiante:  Montserrat Vega Fern\u00e1ndez<br>T\u00edtulo: La relevancia de los Ciberfeminismos en la era de la Inteligencia Artificial. Una aproximaci\u00f3n a la situaci\u00f3n actual<br>Tutor: J. Francisco \u00c1lvarez<br>Tribunal: Mar\u00eda Jim\u00e9nez, Eduardo Bustos, J. Francisco \u00c1lvarez.    <br>D\u00eda y hora: 6 de octubre, 12:00 (online)<br><br>6.<br>Estudiante:  Ana Maillo Mart\u00edn<br>T\u00edtulo: El papel del experto ante la pseudociencia<br>Tutor: Mar\u00eda Jim\u00e9nez Buedo<br>Tribunal: J. Francisco \u00c1lvarez, Javier Gonz\u00e1lez de Prado, Mar\u00eda Jimenez Buedo<br>D\u00eda y hora: 7 de octubre , 10:45 (online)<br><br>7.<br>Estudiante:  Javier Hern\u00e1ndez Tenorio<br>T\u00edtulo: Las estrategias explicativas de J. Elster y G.A. Cohen para las ciencias sociales: un debate sobre la explicaci\u00f3n funcional<br>Tutor: Mar\u00eda Jim\u00e9nez Buedo<br>Tribunal: J. Francisco \u00c1lvarez, Javier Gonz\u00e1lez de Prado, Mar\u00eda Jimenez Buedo<br>D\u00eda y hora: 7 de octubre, 11:30 (online)<br><br>8.<br>Estudiante:  Francisco de Borja Ibarrondo Hern\u00e1ndez<br>T\u00edtulo: Historia de la navegaci\u00f3n astron\u00f3mica en el siglo XX. Sus antecedentes tecnol\u00f3gicos e impacto socio-cultural. <br>Tutor: Manuel Sell\u00e9s<br>Tribunal: David Teira, Javier Gonz\u00e1lez de Prado, Manuel Sell\u00e9s<br>D\u00eda y hora:  10 de octubre, 10:00 (online)<br><br>9.<br>Estudiante:  Ana P\u00e9rez Almeida<br>T\u00edtulo: \u00bfSon suficientes las medidas de bienestar animal para justificar el uso de animales en la industria c\u00e1rnica?<br>Tutor: Susana Mons\u00f3<br>Tribunal:  Jes\u00fas Zamora, Cristian Saborido, Susana Mons\u00f3<br>D\u00eda, hora y lugar: 10 de octubre a las 11:00 (online)<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.<br>Estudiante:  Ana Isabel S\u00e1nchez Merino<br>T\u00edtulo: La desmitificaci\u00f3n del mito del genio loco y la pr\u00e1ctica creativa como terapia<br>Tutor: Paloma Atencia<br>Tribunal: David Teira, Cristian Saborido, Paloma Atencia (online)<br>D\u00eda y hora: 10 de octubre. 12:00.<br><br>11.<br>Estudiante:  Helena Zapata Zer\u00f3n<br>T\u00edtulo:  La hip\u00f3tesis explicativa de las propiedades de la luz tratadas en diferentes escritos a partir de \u2018La vegetaci\u00f3n de los metales\u2019 de Newton.<br>Tutor: Manuel Sell\u00e9s<br>Tribunal: Jes\u00fas Zamora, Susana Mons\u00f3, Manuel Sell\u00e9s<br>D\u00eda y hora:  10 de octubre, 16:00 (online)<br><br>12.<br>Estudiante:  Manuel Cigales Garc\u00eda<br>T\u00edtulo: Filosof\u00eda de la psicopatolog\u00eda: Sobre el modelo naturalista, la antipsiquiatr\u00eda y los riesgos del reduccionismo <br>Tutor: Cristian Saborido <br>Tribunal:  Ferm\u00edn Go\u00f1i, Paloma Atencia y Cristian Saborido<br>D\u00eda y hora: 12 de octubre, 17:30 (online). <br><br>13.<br>Estudiante:  Mar\u00eda Dolores Garc\u00eda Arnaldos<br>T\u00edtulo: Algunos problemas de la teor\u00eda de Agust\u00edn Rayo sobre la construcci\u00f3n del espacio l\u00f3gico: Contextualismo, deflacionismo y desacuerdos profundos Tutor:  Cristina Corredor<br>Tribunal: Concha Mart\u00ednez Vidal, David Teira, Cristina Corredor<br>D\u00eda y hora:  13 de octubre, 12:00 (online).<br><br>14.<br>Estudiante:  Francesc Roig Loscertales<br>T\u00edtulo: La industria farmac\u00e9utica y el conocimiento m\u00e9dico<br>Tutor:  David Teira<br>Tribunal: Inmaculada De Melo, Manuel Sell\u00e9s y David Teira<br>D\u00eda y hora: 13 de octubre. 18:00 (online)<br><br>15.<br>Estudiante:  Jes\u00fas Toribio Rodr\u00edguez<br>T\u00edtulo: Los artefactos t\u00e9cnicos en Filosof\u00eda de la Tecnolog\u00eda. Cuestiones Ontol\u00f3gicas y epistemol\u00f3gicas.<br>Tutor: Manuel Sell\u00e9s<br>Tribunal: Cristian Saborido, Paloma Atencia, Manuel Sell\u00e9s<br>D\u00eda y hora:  14 de octubre a las 10:00 (online)<br><br>16.<br>Estudiante:  Rub\u00e9n Pintado Gonz\u00e1lez<br>T\u00edtulo:  Evoluci\u00f3n de la idea de racionalidad en la econom\u00eda ortodoxa: Una visi\u00f3n desde Xavier Zubiri <br>Tutor: Javier Gonz\u00e1lez de Prado<br>Tribunal:  Jes\u00fas Zamora, David Teira, Javier Gonz\u00e1lez de Prado.<br> D\u00eda y hora: 14 de octubre, 10:00 (online)<br><br>17.<br>Estudiante:  Jakob William Bu\u0308hlmann Quero<br>T\u00edtulo: La teor\u00eda de las emociones de Jesse Prinz como intersecci\u00f3n. Un recorrido en la filosof\u00eda de las emociones<br>Tutor: Jes\u00fas Zamora Bonilla<br>Tribunal: David Teira, Javier Gonz\u00e1lez de Prado, Jes\u00fas Zamora<br>D\u00eda y hora: 14 de octubre, 10:45 (online)<br><br>18.<br>Estudiante:  Luis Carballo Gil<br>T\u00edtulo: Teor\u00edas de las probabilidades y su conceptualizaci\u00f3n en teor\u00eda de las categor\u00edas.<br>Tutor: Jes\u00fas Zamora Bonilla<br>Tribunal: David Teira, Javier Gonz\u00e1lez de Prado, Jes\u00fas Zamora<br>D\u00eda y hora:  14 de octubre. 11:30. (online)<br><br>19.<br>Estudiante:  Marta Mancebo Boix<br>T\u00edtulo: C\u00f3mo hacemos cosas con clics. An\u00e1lisis filos\u00f3fico de la comunicaci\u00f3n en redes sociales<br>Tutor: Javier Gonz\u00e1lez de Prado<br>Tribunal: Cristina Corredor, Claudia Picazo, Javier Gonz\u00e1lez de Prado<br>D\u00eda y hora: 14 de octubre, 13:00 (online)<br><br><br>NOTA: Para obtener el link a las defensas online se debe solicitar por email a la siguiente direcci\u00f3n: cristian.saborido@fsof.uned.es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00c1STER UNIVERSITARIO EN FILOSOF\u00cdA TE\u00d3RICA Y PR\u00c1CTICA CALENDARIO DE DEFENSAS DE TFM CONVOCATORIA SEPTIEMBRE 2022 Especialidad: L\u00d3GICA, HISTORIA Y FILOSOF\u00cdA DE LA CIENCIA 1.Estudiante: \u00c1ngel Luis Ortigosa CancaT\u00edtulo: Organicismo vs. genocentrismo (evolutivos). Las s\u00edntesis evolutivas y sus compromisos ontoepistemol\u00f3gicosTutor: V\u00edctor <a class=\"more-link\" href=\"https:\/\/blogs.uned.es\/lhfc\/2022\/09\/15\/master-universitario-en-filosofia-teorica-y-practica-calendario-de-defensas-de-tfm-convocatoria-septiembre-2022-especialidad-logica-historia-y-filosofia-de-la-ciencia\/\">Seguir leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":293,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-463","post","type-post","status-publish","format-standard","hentry","category-tfm"],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":3,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/463\/revisions"}],"predecessor-version":[{"id":471,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/463\/revisions\/471"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/media?parent=463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/categories?post=463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/tags?post=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}