{"id":371,"date":"2021-10-05T14:58:12","date_gmt":"2021-10-05T14:58:12","guid":{"rendered":"https:\/\/blogs.uned.es\/lhfc\/?p=371"},"modified":"2021-10-15T09:43:08","modified_gmt":"2021-10-15T09:43:08","slug":"master-universitario-en-filosofia-teorica-y-practica-calendario-de-defensas-de-tfm-convocatoria-septiembre-2021-especialidad-logica-historia-y-filosofia-de-la-ciencia","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/lhfc\/2021\/10\/05\/master-universitario-en-filosofia-teorica-y-practica-calendario-de-defensas-de-tfm-convocatoria-septiembre-2021-especialidad-logica-historia-y-filosofia-de-la-ciencia\/","title":{"rendered":"M\u00c1STER UNIVERSITARIO EN FILOSOF\u00cdA TE\u00d3RICA Y PR\u00c1CTICA    CALENDARIO DE DEFENSAS DE TFM CONVOCATORIA SEPTIEMBRE 2021    Especialidad: L\u00d3GICA, HISTORIA Y FILOSOF\u00cdA DE LA CIENCIA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">M\u00c1STER UNIVERSITARIO EN FILOSOF\u00cdA TE\u00d3RICA Y PR\u00c1CTICA<br><br><br><br>CALENDARIO DE DEFENSAS DE TFM CONVOCATORIA SEPTIEMBRE 2021<br><br><br><br>Especialidad: L\u00d3GICA, HISTORIA Y FILOSOF\u00cdA DE LA CIENCIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><br><br>1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudiante: J\u00edmenez Bernal, Jaime<br><br>T\u00edtulo: Los dogwhistles y su presencia en la propaganda pol\u00edtica espa\u00f1ola<br><br>Tutor: Javier Gonz\u00e1lez de Prado Salas<br><br>Tribunal: Cristina Corredor Lanas y Javier Gonz\u00e1lez de Prado Salas<br><br>D\u00eda y hora: 7 de octubre a las 12,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudiante: Casuso Lomas, Mikel<br><br>T\u00edtulo: Justicia Algor\u00edtimica en el sistema judicial<br><br>Tutor: David Teira Serrano<br><br>Tribunal: Dr. D. Jos\u00e9 Juan Lucena Molina y Dr. D. David Teira Serrano<br><br>D\u00eda y hora: 7 de octubre a las 10,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudiante: Hidalgo Cebolla, Teresa<br><br>T\u00edtulo: La prostituci\u00f3n no es el oficio m\u00e1s antiguo del mundo<br><br>Tutor: David Teira Serrano<br><br>Tribunal: Paloma Atencia Linares y David Teira Serrano<br><br>D\u00eda y hora: 8 de octubre a las 10,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudiante: Prest, Shawn<br><br>T\u00edtulo: Opening the Sensory Gates. A Predictive Processing Account of Meditation and Learning<br><br>Tutor: Javier Gonz\u00e1lez de Prado Salas<br><br>Tribunal: Susana Mons\u00f3 Gil y Javier Gonz\u00e1lez de Prado Salas<br><br>D\u00eda y hora: 14 de octubre a las 11,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudiante: Carmona, Matilde<br><br>T\u00edtulo: La epilepsia, una enfermedad de frontera. Entre la objetividad cl\u00ednica y la subjetividad cultural. <br><br>Tutor: Cristian Saborido <br><br>Tribunal: Mar\u00eda Jim\u00e9nez Buedo y Cristian Saborido<br><br>D\u00eda y hora:14 de octubre a las 11.00 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudiante: Ortiz Rous, Sara<br><br>T\u00edtulo: Contribuciones de la explicaci\u00f3n funcional: de la biolog\u00eda a las ciencias sociales<br><br>Tutor: Mar\u00eda Jim\u00e9nez Buedo <br><br>Tribunal: Cristian Saborido y Mar\u00eda Jim\u00e9nez Buedo<br><br>D\u00eda y hora:14 de octubre a las 12.00 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudiante: Gonz\u00e1lez Berruga, Manuel \u00c1ngel<br><br>T\u00edtulo: Aproximaci\u00f3n a la Ontolog\u00eda de Markus Gabriel y Graham Harman<br><br>Tutor: Alejandro Escudero P\u00e9rez<br><br>Tribunal: Laura Herrero Olivera y Alejandro Escudero P\u00e9rez<br><br>D\u00eda y hora: 15 de octubre a las 11,00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudiante: Campos Prada, Diego<br><br>T\u00edtulo: El Algoritmo de la Racionalidad. Un An\u00e1lisis de la Racionalidad Artificial y el Desarrollo de Entidades Artificiales como Agentes Morales<br><br>Tutor: Francisco \u00c1lvarez <br><br>Tribunal: Francisco \u00c1lvarez y Eduardo Bustos<br><br>D\u00eda y hora: 20 de octubre a las 11.00 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">NOTA: Debido a la actual situaci\u00f3n sanitaria, todas las defensas se celebrar\u00e1n online mediante la aplicaci\u00f3n Teams. Se trata de un acto p\u00fablico y la asistencia es libre. Toda persona interesada en asistir a alguna de estas defensas, ha de contactar previamente con cristian.saborido@fsof.uned.es para recibir el enlace a la sesi\u00f3n online.<br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00c1STER UNIVERSITARIO EN FILOSOF\u00cdA TE\u00d3RICA Y PR\u00c1CTICA CALENDARIO DE DEFENSAS DE TFM CONVOCATORIA SEPTIEMBRE 2021 Especialidad: L\u00d3GICA, HISTORIA Y FILOSOF\u00cdA DE LA CIENCIA 1. Estudiante: J\u00edmenez Bernal, Jaime T\u00edtulo: Los dogwhistles y su presencia en la propaganda pol\u00edtica espa\u00f1ola Tutor: <a class=\"more-link\" href=\"https:\/\/blogs.uned.es\/lhfc\/2021\/10\/05\/master-universitario-en-filosofia-teorica-y-practica-calendario-de-defensas-de-tfm-convocatoria-septiembre-2021-especialidad-logica-historia-y-filosofia-de-la-ciencia\/\">Seguir leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":293,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-371","post","type-post","status-publish","format-standard","hentry","category-tfm"],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/comments?post=371"}],"version-history":[{"count":8,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/371\/revisions"}],"predecessor-version":[{"id":417,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/371\/revisions\/417"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/media?parent=371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/categories?post=371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/tags?post=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}