{"id":279,"date":"2021-02-24T12:38:44","date_gmt":"2021-02-24T12:38:44","guid":{"rendered":"http:\/\/blogs.uned.es\/lhfc\/?p=279"},"modified":"2021-02-24T12:40:38","modified_gmt":"2021-02-24T12:40:38","slug":"calendario-de-defensas-de-tfm-convocatoria-marzo-2021-master-universitario-en-filosofia-teorica-y-practica","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/lhfc\/2021\/02\/24\/calendario-de-defensas-de-tfm-convocatoria-marzo-2021-master-universitario-en-filosofia-teorica-y-practica\/","title":{"rendered":"CALENDARIO DE DEFENSAS DE TFM CONVOCATORIA MARZO 2021 \u2013 M\u00c1STER UNIVERSITARIO EN FILOSOF\u00cdA TE\u00d3RICA Y PR\u00c1CTICA"},"content":{"rendered":"<p>Estudiante: Sara Garc\u00eda Marcos<br \/>\nT\u00edtulo: A defence of Evidence Based Medicine<br \/>\nTutor: David Teira Serrano<br \/>\nTribunal: David Teira y Cristian Saborido<br \/>\nD\u00eda y hora: 2 de marzo a las 10:30<\/p>\n<p>Estudiante: Pablo Gella Montero<br \/>\nT\u00edtulo: La Biomatriz. un cambio de paradigma<br \/>\nTutor: V\u00edctor Luque Mart\u00edn<br \/>\nTribunal: V\u00edctor Luque Mart\u00edn, Cristian Saborido y Giorgio Airoldi<br \/>\nD\u00eda y hora: 4 de marzo a las 10:00<\/p>\n<p>Estudiante: Macarena Cabezas G\u00f3mez<br \/>\nT\u00edtulo: Condiciones de posibilidad para manipular un cerebro: Inteligencia Artificial y Redes Sociales.<br \/>\nTutor: Jes\u00fas Zamora Bonilla<br \/>\nTribunal: Jes\u00fas Zamora Bonilla y Paloma Atencia Linares<br \/>\nD\u00eda y hora: 5 de marzo a las 17:00<\/p>\n<p>Estudiante: Jorge Enrique Hern\u00e1ndez S\u00e1nchez<br \/>\nT\u00edtulo: El dilema del prisionero desde la perspectiva actual de la filosof\u00eda de las ciencias sociales<br \/>\nTutor: Mar\u00eda Jimenez Buedo<br \/>\nTribunal: Mar\u00eda Jim\u00e9nez Buedo y Francisco \u00c1lvarez \u00c1lvarez<br \/>\nD\u00eda y hora: 11 de marzo a las 10:30<\/p>\n<p>Estudiante: Daniel Gonz\u00e1lvez Ortu\u00f1o<br \/>\nT\u00edtulo: An\u00e1lisis de la intencionalidad colectiva en las organizaciones econ\u00f3micas<br \/>\nTutor: Mar\u00eda Jimenez Buedo<br \/>\nTribunal: Mar\u00eda Jim\u00e9nez Buedo y Francisco \u00c1lvarez \u00c1lvarez<br \/>\nD\u00eda y hora: 11 de marzo a las 11:30<\/p>\n<div class=\"entry-content\">\n<div>\n<div>\n<div>\n<div>\n<div>NOTA: Con motivo de las excepcionales circunstancias debidas a la crisis sanitaria de la COVID19, todas las defensas se llevar\u00e1n a cabo por videoconferencia.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estudiante: Sara Garc\u00eda Marcos T\u00edtulo: A defence of Evidence Based Medicine Tutor: David Teira Serrano Tribunal: David Teira y Cristian Saborido D\u00eda y hora: 2 de marzo a las 10:30 Estudiante: Pablo Gella Montero T\u00edtulo: La Biomatriz. un cambio de <a class=\"more-link\" href=\"https:\/\/blogs.uned.es\/lhfc\/2021\/02\/24\/calendario-de-defensas-de-tfm-convocatoria-marzo-2021-master-universitario-en-filosofia-teorica-y-practica\/\">Seguir leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":293,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-279","post","type-post","status-publish","format-standard","hentry","category-tfm"],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/comments?post=279"}],"version-history":[{"count":3,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/279\/revisions"}],"predecessor-version":[{"id":287,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/posts\/279\/revisions\/287"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/media?parent=279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/categories?post=279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/lhfc\/wp-json\/wp\/v2\/tags?post=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}