{"id":2335,"date":"2023-03-05T16:43:22","date_gmt":"2023-03-05T15:43:22","guid":{"rendered":"https:\/\/blogs.uned.es\/grupointer\/?page_id=2335"},"modified":"2026-01-28T13:37:25","modified_gmt":"2026-01-28T12:37:25","slug":"libros","status":"publish","type":"page","link":"https:\/\/blogs.uned.es\/grupointer\/libros\/","title":{"rendered":"Libros"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2335\" class=\"elementor elementor-2335\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c18a8af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c18a8af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0dea89\" data-id=\"d0dea89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-991b379 elementor-widget elementor-widget-heading\" data-id=\"991b379\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LIBROS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b5fee5 elementor-widget elementor-widget-text-editor\" data-id=\"4b5fee5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>7 libros coordinados por Teresa Aguado han sido incluidos, <a href=\"http:\/\/www.iesalc.unesco.org.ve\/index.php?option=com_content&amp;view=article&amp;id=22&amp;Itemid=405&amp;lang=es\" target=\"_blank\" rel=\"noopener\">tras su evaluaci\u00f3n<\/a>, en el portal del <a href=\"http:\/\/www.iesalc.unesco.org.ve\/index.php?option=com_content&amp;view=article&amp;id=1387&amp;Itemid=840&amp;lang=es&amp;resetfilters=0&amp;clearordering=0&amp;clearfilters=0\" target=\"_blank\" rel=\"noopener\">Observatorio de Diversidad Cultural e Interculturalidad<\/a> de UNESCO-IESALC.<\/p><hr \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a03e32 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3a03e32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6737879 elementor-widget elementor-widget-text-editor\" data-id=\"6737879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span class=\"x_ContentPasted0\" data-ogsc=\"black\">Gonz\u00e1lez, M.F. y \u00a0Ballesteros Vel\u00e1zquez, B. (Coords) (2023).\u00a0<i class=\"x_ContentPasted0\" data-ogsc=\"\">Comprender el mundo para (intentar) transformarlo. Una gu\u00eda posible para el an\u00e1lisis cualitativo de datos. <\/i>UNED.\u00a0<\/span>.<\/b> <b> <\/b><\/p><p>Nuestro prop\u00f3sito en esta obra era ofrecer un material de apoyo en los an\u00e1lisis de investigaciones cualitativas, sin ser la tarea anal\u00edtica una etapa independiente y con otra l\u00f3gica diferente al resto de fases de desarrollo del trabajo. Desde el inicio, somos investigadores-as cualitativos-as, tenemos la preocupaci\u00f3n por comprender c\u00f3mo otros y otras entienden el mundo y se desenvuelven en \u00e9l. Situamos esta comprensi\u00f3n tambi\u00e9n como requisito \u00e9tico y epistemol\u00f3gico para pensar formas de colaboraci\u00f3n que permitan contribuir a un mundo mejor. Por eso, entendemos que la tarea de analizar puede producir cierto v\u00e9rtigo, pero no debiera ser tanto o, tal vez, no tan diferente del respeto que infunde toda planificaci\u00f3n y trabajo de campo. Porque desde el inicio del planteamiento del proyecto de investigaci\u00f3n ya estamos inmersos en una espiral de pre-an\u00e1lisis y an\u00e1lisis.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-040f824 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"040f824\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-20a0c2e\" data-id=\"20a0c2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fcff39 elementor-widget elementor-widget-text-editor\" data-id=\"0fcff39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Ver ficha en la web de <a href=\"http:\/\/portal.uned.es\/portal\/page?_pageid=93,23377989&amp;_dad=portal&amp;_schema=PORTAL&amp;IdArticulo=0102100CT01A01\">Editorial UNED<\/a><\/p><p style=\"text-align: right\">Ver ficha en la <a href=\"https:\/\/www.librosuned.com\/LU29994\/Comprender-el-mundo-para-(intentar)-transformarlo--Una-gu%C3%ADa-posible-para-el-an%C3%A1lisis-cualitativo-de-datos.aspx\">librer\u00eda UNED<\/a><\/p><p style=\"text-align: right\">Descargar <a href=\"http:\/\/portal.uned.es\/Publicaciones\/htdocs\/pdf.jsp?articulo=0102100CT01A01\">\u00edndice y primeras p\u00e1ginas en pdf<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-363017b\" data-id=\"363017b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-affac6e elementor-widget elementor-widget-image\" data-id=\"affac6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/comrpender-el-mundo-q9z9n4xp6gku0rf9pui8dwm1vedet8eacmc21y9zo0.jpg\" title=\"comrpender el mundo\" alt=\"comrpender el mundo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca737e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca737e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8bd6a8\" data-id=\"b8bd6a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcac514 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bcac514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83e6e18 elementor-widget elementor-widget-text-editor\" data-id=\"83e6e18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"background-color: inherit;text-align: inherit\"><b>Aguado Odina, Mar\u00eda Teresa; Melero S\u00e1nchez, Hector; y Merodio Alonso, Guiomar<\/b><\/span><b>. (coords.). (2023). <\/b><b><i>Diversidad cultural y equidad en la escuela<\/i>. Madrid: UNED. ISBN: 9788436277746<\/b><b>.<\/b> <b> <\/b><\/p><p>Este texto se ha elaborado de forma espec\u00edfica como documento de estudio para la asignatura <em>Diversidad cultural y equidad en la escuela<\/em>, que forma parte del plan de estudios del Grado en Educaci\u00f3n Infantil impartido por la UNED. La premisa de la que se parte es que la diversidad cultural siempre est\u00e1 presente en todo grupo humano, es lo normal y no debemos utilizarla para justificar la desigualdad y la discriminaci\u00f3n. Lo cultural siempre se manifiesta en toda situaci\u00f3n educativa a trav\u00e9s de las interacciones entre las personas, pero a priori no podemos saber c\u00f3mo se va a manifestar. Se ha prestado un especial cuidado en incluir actividades y recursos que sean \u00fatiles para el pensamiento y la pr\u00e1ctica diaria en la escuela.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec39bfd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec39bfd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-819e02c\" data-id=\"819e02c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af118f8 elementor-widget elementor-widget-text-editor\" data-id=\"af118f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Ver ficha en la web de <a href=\"http:\/\/portal.uned.es\/portal\/page?_pageid=93,23377989&amp;_dad=portal&amp;_schema=PORTAL&amp;IdArticulo=6303109GR01A01\">Editorial UNED<\/a><\/p><p style=\"text-align: right\">Ver ficha en la <a href=\"https:\/\/www.librosuned.com\/LU30364\/Diversidad-cultural-y-equidad-en-la-escuela.aspx\">librer\u00eda UNED<\/a><\/p><p style=\"text-align: right\">Descargar <a href=\"http:\/\/portal.uned.es\/Publicaciones\/htdocs\/pdf.jsp?articulo=6303109GR01A01\">\u00edndice y primeras p\u00e1ginas en pdf<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8a7b569\" data-id=\"8a7b569\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10af86b elementor-widget elementor-widget-image\" data-id=\"10af86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"125\" height=\"177\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/2023\/05\/6303109GR01A01_portada_diversidad_infantil.jpeg\" class=\"attachment-large size-large wp-image-3853\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36cbf9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36cbf9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c62ff09\" data-id=\"c62ff09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8454fc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e8454fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bb3769 elementor-widget elementor-widget-text-editor\" data-id=\"5bb3769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Gil Jaurena, In\u00e9s, Goig Mart\u00ednez, Rosa y Barbas Coslado, \u00c1ngel. (coords.). (2021). <i>Animaci\u00f3n e intervenci\u00f3n sociocultural. Intervenci\u00f3n educativa en contextos sociales<\/i>. Madrid: UNED. <\/b><b>ISBN: 978-84-362-7696-1<\/b><b><span class=\"inplacedisplayid1siteid0\">.<\/span><\/b> <b> <\/b><\/p><p>La animaci\u00f3n sociocultural es una praxis socio-pedag\u00f3gica de dinamizaci\u00f3n de la participaci\u00f3n de la comunidad para el desarrollo personal y social. Este intento de definici\u00f3n sint\u00e9tica esconde una riqueza de enfoques, matices, metodolog\u00edas, principios, metas, que hacen de la animaci\u00f3n y la intervenci\u00f3n sociocultural un \u00e1mbito vivo de reflexi\u00f3n y pr\u00e1ctica. Este texto forma parte del material b\u00e1sico de estudio en la especialidad Animaci\u00f3n e Intervenci\u00f3n Sociocultural del M\u00e1ster en Intervenci\u00f3n Educativa en Contextos Sociales, impartido por la Universidad Nacional de Educaci\u00f3n a Distancia (UNED). A lo largo de seis cap\u00edtulos, los autores\/as (profesores\/as del m\u00e1ster) explican y analizan diferentes aspectos en relaci\u00f3n con la Animaci\u00f3n y la Intervenci\u00f3n Sociocultural.<\/p><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-416698d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"416698d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-16a6ce9\" data-id=\"16a6ce9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d50c5d elementor-widget elementor-widget-text-editor\" data-id=\"9d50c5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Ver ficha en la web de <a href=\"https:\/\/www.librosuned.com\/LU29243\/Animaci%C3%B3n-e-intervenci%C3%B3n-sociocultural--Intervenci%C3%B3n-educativa-en-contextos-sociales.aspx\">Editorial UNED<\/a><\/p><p style=\"text-align: right\">Descargar <a href=\"http:\/\/portal.uned.es\/Publicaciones\/htdocs\/pdf.jsp?articulo=2330805MR01A01\">\u00edndice y algunas p\u00e1ginas en pdf<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2ca0cc9\" data-id=\"2ca0cc9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18db38a elementor-widget elementor-widget-image\" data-id=\"18db38a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"125\" height=\"177\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/2023\/03\/1.jpeg\" class=\"attachment-large size-large wp-image-3223\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73df55b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73df55b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a455e6\" data-id=\"2a455e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02ec53b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"02ec53b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e009558 elementor-widget elementor-widget-text-editor\" data-id=\"e009558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Ballesteros, Bel\u00e9n y Abril, David. (compiladores.). (2019). <i>Diversidad, educaci\u00f3n y pol\u00edticas p\u00fablicas desde un enfoque intercultural<\/i>. Madrid: UNED. <\/b><b>ISBN: <\/b><b><span class=\"inplacedisplayid1siteid0\"> 978-84-09-06725-1.<\/span><\/b> <b> <\/b><\/p><p>Pol\u00edticas p\u00fablicas desde un enfoque intercultural es el lema utilizado en el seminario presencial del M\u00e1ster Eurolatinoamericano de Educaci\u00f3n Intercultural en el curso acad\u00e9mico 17-18. El tema fue propuesto con la intenci\u00f3n de animar un debate y una nueva conceptualizaci\u00f3n de \u00abeso\u00bb que se hace llamar \u00abpol\u00edticas p\u00fablicas\u00bb y que, parece, resultaran lejanas a nuestras pr\u00e1cticas cotidianas. Al asumir esta tem\u00e1tica, quisimos darnos la oportunidad de deconstruir esta idea y reconocernos en nuestro papel activo en la articulaci\u00f3n de pol\u00edticas p\u00fablicas, definidas como el compromiso y la satisfacci\u00f3n de servir a la gente. No es la pol\u00edtica de los partidos, es la capacidad de participar en la organizaci\u00f3n y decisi\u00f3n del bien com\u00fan, de atender a las preguntas elementales que dan sentido a nuestra vida social. Esta publicaci\u00f3n recoge toda una serie de experiencias compartidas, que articulamos ahora en una ponencia marco y dos ejes tem\u00e1ticos: pol\u00edticas p\u00fablicas y actores y escenarios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42d90e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42d90e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ff63c90\" data-id=\"ff63c90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f06543 elementor-widget elementor-widget-text-editor\" data-id=\"1f06543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Ver ficha en la web de <a href=\"https:\/\/www.librosuned.com\/LU27378\/Diversidad,-educaci%C3%B3n-y-pol%C3%ADticas-p%C3%BAblicas-desde-un-enfoque-intercultural.aspx\">Editorial UNED<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b07ffec\" data-id=\"b07ffec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9c7a49 elementor-widget elementor-widget-image\" data-id=\"b9c7a49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/2-scaled-q3s83bi505vqrbtue7ep2jtmqbpmw179re3oroh5cg.jpg\" title=\"2\" alt=\"2\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbd0a83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbd0a83\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08eddaa\" data-id=\"08eddaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b95a71c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b95a71c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5465bcd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5465bcd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7efc84b\" data-id=\"7efc84b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c4c8b3 elementor-widget elementor-widget-text-editor\" data-id=\"1c4c8b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Ballesteros, Bel\u00e9n. (coord.). (2019). <i>I<\/i><i>nvestigaci\u00f3n social desde la pr\u00e1ctica educativa<\/i>. Madrid: UNED. <\/b><b>ISBN: <\/b><b><span class=\"inplacedisplayid1siteid0\"> 978-84-362-7510-0.<\/span><\/b><b> <\/b><\/p><p>La investigaci\u00f3n en la pr\u00e1ctica educativa sit\u00faa el foco en su car\u00e1cter social, sea cual fuere el \u00e1mbito en el que se desarrolle. La educaci\u00f3n es social porque su inter\u00e9s est\u00e1 en la idea de dar poder a las personas: reconocerse poderosos, tener poder de decidir y poder de transformar las relaciones sociales. Desde esta perspectiva, la investigaci\u00f3n se convierte en estrategia privilegiada de indagaci\u00f3n y aprendizaje, autoafirm\u00e1ndose como investigaci\u00f3n social. Este car\u00e1cter social es el eje de la obra. Necesitamos una investigaci\u00f3n que ayude a comprender las pr\u00e1cticas sociales, las posibilidades y necesidades de los distintos contextos donde transcurre la acci\u00f3n, las alternativas de sistematizaci\u00f3n y transformaci\u00f3n de las acciones sociales. Una investigaci\u00f3n que pone en el centro a las personas y que configura a trav\u00e9s de ellas su sentido epistemol\u00f3gico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1da3316 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1da3316\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-9f67f79\" data-id=\"9f67f79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-509c3f3 elementor-widget elementor-widget-text-editor\" data-id=\"509c3f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Ver ficha en la web de <a href=\"https:\/\/www.librosuned.com\/LU24784\/Investigaci%C3%B3n-social-desde-la-pr%C3%A1ctica-educativa.aspx\">Editorial UNED<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-674fd9d\" data-id=\"674fd9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5bf745 elementor-widget elementor-widget-image\" data-id=\"b5bf745\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/3-q3s83g7byc26ddn0mrftx0mxp92gyipxg1d462a6hc.jpg\" title=\"Investig social  desde prac edu\" alt=\"Investig social  desde prac edu\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fecdaab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fecdaab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9abb708\" data-id=\"9abb708\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8514ab3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8514ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00de580 elementor-widget elementor-widget-text-editor\" data-id=\"00de580\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Mata Benito, Patricia; Gil Jaurena, In\u00e9s y <\/b><b>Aguado Odina, Teresa. (coords.). (2018). <i>Ciudadan\u00edas<\/i>. <i>Aprendiza<\/i><i>je de la c<\/i><i>iudadan\u00eda activ<\/i><i>a: d<\/i><i>isc<\/i><i>ursos, exp<\/i><i>eriencias y propues<\/i><i>tas educativas<\/i>. Madrid: UNED. ISBN:\u00a0<\/b> 978-84-362-7396-0<b>. <\/b><\/p><p>La desigualdad y la exclusi\u00f3n es el centro de la discusi\u00f3n y el debate pol\u00edtico y social contempor\u00e1neo. La construcci\u00f3n de una sociedad m\u00e1s justa, inclusiva y equitativa pasa necesariamente por el desarrollo de procesos de transformaci\u00f3n social basados en la participaci\u00f3n real, efectiva, democr\u00e1tica, en los que individuos y grupos puedan participar en condiciones de igualdad. Sin embargo, el modelo democr\u00e1tico experimenta en nuestros d\u00edas una expansi\u00f3n creciente unida a una crisis sin precedentes. Europa se halla sumida en un proceso hist\u00f3rico de integraci\u00f3n que trata de concretarse en un proyecto pol\u00edtico com\u00fan que garantice la convivencia pac\u00edfica de todos los ciudadanos europeos. De forma paralela, y a la vez, se observa en la ciudadan\u00eda un cierto desinter\u00e9s y desconfianza en las instituciones democr\u00e1ticas, as\u00ed como una escasa participaci\u00f3n en el juego pol\u00edtico establecido. En esta l\u00ednea, las orientaciones europeas enfatizan la necesidad de promover una \u00abciudadan\u00eda activa\u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-691adb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"691adb9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5d9ac37\" data-id=\"5d9ac37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b3513f elementor-widget elementor-widget-text-editor\" data-id=\"2b3513f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Ver ficha en la web de <a href=\"http:\/\/portal.uned.es\/portal\/page?_pageid=93,23377989&amp;_dad=portal&amp;_schema=PORTAL&amp;IdArticulo=2330628MR01A01\">Editorial UNED<\/a><\/p><p style=\"text-align: right\">Descargar <a href=\"http:\/\/portal.uned.es\/Publicaciones\/htdocs\/pdf.jsp?articulo=2330628MR01A01\">\u00edndice en pdf<\/a><\/p><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8a602b0\" data-id=\"8a602b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ba575b elementor-widget elementor-widget-image\" data-id=\"5ba575b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/4-q3sbzbkqxtj80gguvq09g7z7ydnrd300cc581cw6kw.png\" title=\"4\" alt=\"4\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69ca919 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69ca919\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-177f85f\" data-id=\"177f85f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d552656 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d552656\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19836ae elementor-widget elementor-widget-text-editor\" data-id=\"19836ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Aguado Odina, Teresa y Mata Benito, Patricia. (coords.). (2017). <i>Educaci\u00f3n Intercultural<\/i>. Madrid: UNED. ISBN: <\/b><b><span class=\"inplacedisplayid1siteid0\"> 978-84-362-7198-0<\/span><\/b><b>. <\/b><\/p><p>El enfoque intercultural se propone como mirada que nos permite comprender la compleja articulaci\u00f3n entre diversidad cultural e igualdad en educaci\u00f3n. Se reconoce la diversidad humana como normalidad, se sit\u00faa la diversidad cultural en el foco de la reflexi\u00f3n sobre educaci\u00f3n y se asume el compromiso \u00e9tico del educador por la equidad y la justicia social. La perspectiva intercultural es hermen\u00e9utica y pr\u00e1ctica, es comunicaci\u00f3n y relaci\u00f3n entre personas. La educaci\u00f3n intercultural no es un modelo a alcanzar, sino una perspectiva, una met\u00e1fora que nos permite comprender lo que pensamos, decimos y hacemos en relaci\u00f3n con la diversidad cultural y equidad en educaci\u00f3n. Lo intercultural no se presenta como adjetivo con el que calificar a profesores, escuelas, programas o recursos, sino que es el enfoque, la mirada intercultural, la que hace el objeto. Lo cultural emana y se construye en la interacci\u00f3n entre las personas. Desde estas premisas, se delimita la educaci\u00f3n intercultural.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03ffd61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03ffd61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-cb18bab\" data-id=\"cb18bab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1a918f elementor-widget elementor-widget-text-editor\" data-id=\"e1a918f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Ver ficha en la web de <a href=\"http:\/\/portal.uned.es\/portal\/page?_pageid=93,23377989&amp;_dad=portal&amp;_schema=PORTAL&amp;IdArticulo=6302409GR03A01\">Editorial UNED<\/a><\/p><p style=\"text-align: right\">\u00a0<\/p><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-773932d\" data-id=\"773932d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09fc956 elementor-widget elementor-widget-image\" data-id=\"09fc956\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/5-q3sc6g6orlai20449axeux824kiyqgaqbm8s1wbpe8.png\" title=\"5\" alt=\"5\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b21b4f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b21b4f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e860902\" data-id=\"e860902\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-782db1a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"782db1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab70990 elementor-widget elementor-widget-text-editor\" data-id=\"ab70990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><b>Directorate-General for Education, Youth, Sport and Culture,Education, Youth, Sport and Culture (European Commission)<\/b> (2017). <\/b><b><i>Preparing teachers for diversity. The role of initial teacher education: final report &#8211; Study<\/i>. Luxembourg: Publications Office of the European Union. ISBN: 978-92-79-63797-1<span style=\"font-weight: bold\">. (Coautora: Teresa Aguado)<br \/><\/span><\/b><\/p><p>Even though the diversity found in European societies is not a new phenomenon, its nature is rapidly changing. Europe is becoming increasingly diverse due to intra-European mobility, international migration and globalisation. These societal changes affect the educational landscape and organisation, and create both new opportunities and challenges for schools and other educational institutions. Recent studies show that intolerance and social exclusion are increasing both in schools and in society. The growing number of refugee, asylum seeker and migrant children entering Europe places specific demands on schools and teachers. These phenomena lead teachers to re-consider their everyday practices and strategies to meet the learning needs of these pupils.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41b3f5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41b3f5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a5bd2b3\" data-id=\"a5bd2b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3567b47 elementor-widget elementor-widget-text-editor\" data-id=\"3567b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Ver libro en <a href=\"https:\/\/publications.europa.eu\/en\/publication-detail\/-\/publication\/b347bf7d-1db1-11e7-aeb3-01aa75ed71a1\/language-en\">web de la Comisi\u00f3n Europea<\/a><\/p><p style=\"text-align: right\">\u00a0<\/p><p>\u00a0<\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eec1f33\" data-id=\"eec1f33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-769930f elementor-widget elementor-widget-image\" data-id=\"769930f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/5-q3s83g7byc26ddn0mrftx0mxp92gyipxg1d462a6hc.jpeg\" title=\"5\" alt=\"5\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29065a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29065a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9a1893\" data-id=\"e9a1893\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f735ac6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f735ac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa9a00e elementor-widget elementor-widget-text-editor\" data-id=\"aa9a00e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Mata Benito, Patricia; Ballesteros, Bel\u00e9n y del Olmo,\n              Margarita (Eds.). (2014). <\/b><b><i>Propuestas de\n                investigaci\u00f3n e intervenci\u00f3n desde un enfoque\n                participativo<\/i><\/b><b>. Madrid: UNED. ISBN: <\/b><b><font class=\"inplacedisplayid1siteid0\">978-<\/font>84-697-0623-7<\/b><span style=\"font-weight: bold\"><\/span><b style=\"font-weight:              bold\">. <\/b><\/p>\n          \n            \n            La investigaci\u00f3n social, especialmente la que se desarrolla\n            en contextos educativos, aspira a generar un conocimiento\n            capaz de mejorar las pr\u00e1cticas que analiza y a tener, por\n            tanto, un impacto positivo en los \u00e1mbitos estudiados. Sin\n            embargo, la vinculaci\u00f3n de la investigaci\u00f3n con la\n            intervenci\u00f3n educativa no se produce de forma autom\u00e1tica, en\n            muchos casos debido a diversos condicionantes que generan\n            una cierta distancia entre teor\u00eda y pr\u00e1ctica, entre el\n            investigador y los sujetos de estudio. Este libro recoge una\n            serie de trabajos compartidos por los participantes en el\n            Seminario del M\u00e1ster Euro-Latinoamericano de Educaci\u00f3n\n            Intercultural, celebrado en la UNED en marzo de 2014, que\n            exploran y proponen el enfoque participativo como una\n            perspectiva desde la que problematizar la separaci\u00f3n entre\n            investigaci\u00f3n e intervenci\u00f3n. Porque en toda investigaci\u00f3n\n            se interviene, con intenci\u00f3n o sin ella, y toda intervenci\u00f3n\n            implica un m\u00ednimo de indagaci\u00f3n.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3a8ba8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3a8ba8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-cac6b12\" data-id=\"cac6b12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c272ded elementor-widget elementor-widget-text-editor\" data-id=\"c272ded\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/digital.csic.es\/bitstream\/10261\/242182\/1\/Propuestas_investig_intervencion_desde_enfoque_participativo.pdf\">libro en pdf<\/a><\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e139b89\" data-id=\"e139b89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71c8a65 elementor-widget elementor-widget-image\" data-id=\"71c8a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/6-scaled-q3s83onvnudr9vaq9d3h1gi31pwrvsnih78hhjxmxc.jpg\" title=\"6\" alt=\"6\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efbd574 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efbd574\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5978a2f\" data-id=\"5978a2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0760c2b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0760c2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27b31d7 elementor-widget elementor-widget-text-editor\" data-id=\"27b31d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Ballesteros, Bel\u00e9n (coord.). (2014). <i>Taller de investigaci\u00f3n cualitativa<\/i>. Madrid: UNED. ISBN: <\/b><b><span class=\"inplacedisplayid1siteid0\"> 978-84-362-6905-5<\/span><\/b><b>. <\/b><\/p><p>La mirada cualitativa hace posible comprender los procesos sociales desde la perspectiva de quienes los protagonizan. Procesos que son complejos, interrelacionales y din\u00e1micos. As\u00ed, el an\u00e1lisis desde el enfoque cualitativo abre un di\u00e1logo intersubjetivo entre el investigador y la situaci\u00f3n que estudia, construyendo nuevas interpretaciones que permiten cuestionar, comprender, actuar\u2026 desde otras l\u00f3gicas alternativas a la explicaci\u00f3n \u00fanica. Este libro sit\u00faa la investigaci\u00f3n cualitativa como foco, indagando en sus propias motivaciones, en sus dilemas y en sus retos. En la organizaci\u00f3n propuesta se diferencian tres partes en las cuales se abordan los aspectos conceptuales y metodol\u00f3gicos que creemos necesarios para pensar, plantear y desarrollar proyectos desde esta perspectiva de investigaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9787f65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9787f65\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f10a5e0\" data-id=\"f10a5e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fd674b elementor-widget elementor-widget-text-editor\" data-id=\"0fd674b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">\u00a0<\/p><p style=\"text-align: right\">Disponible en formato electr\u00f3nico (pdf): <a href=\"https:\/\/digital.csic.es\/bitstream\/10261\/242118\/1\/Olmo_y_Osuna-2014-Introduccio%CC%81n_a_la_investigacio%CC%81n_etnogra%CC%81fica.pdf\">e-uned.es<\/a><\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b96fe2c\" data-id=\"b96fe2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48a9668 elementor-widget elementor-widget-image\" data-id=\"48a9668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/7-q3s83v8qzomrj5166xxv0wub7f0cdodmu3svuhnvps.jpg\" title=\"7\" alt=\"7\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e85b76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e85b76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d34460\" data-id=\"2d34460\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44425f2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"44425f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cfec5e elementor-widget elementor-widget-text-editor\" data-id=\"1cfec5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>del Olmo, Margarita y Osuna, Carmen (Eds.). (2014). <i>\u00bfQu\u00e9 tiene que decir la Etnograf\u00eda sobre el abandono escolar?<\/i> Madrid: <\/b><b>Traficantes de sue\u00f1os. ISBN: <\/b><b> <span class=\"inplacedisplayid1siteid0\">978-<\/span>84-96453-85-2<\/b><b>. <\/b><\/p><p>Los trabajos reunidos en este volumen tienen su inicio en la llamada que hicimos en el <i>III Congreso de Etnograf\u00eda y Educaci\u00f3n<\/i> (CSIC, Julio de 2013) con el t\u00edtulo: \u00bfQu\u00e9 tiene que decir la etnograf\u00eda sobre el abandono escolar?, dirigida a las personas que est\u00e1n trabajando en el tema desde la perspectiva etnogr\u00e1fica y que estuvieran interesadas en compartir ideas y conclusiones parciales. Esta pregunta parafraseaba el t\u00edtulo de un trabajo anterior <i>What Do Anthropologists Have to Say About Dropouts? <\/i>porque nuestra intenci\u00f3n era continuar la misma l\u00ednea de discusi\u00f3n que abri\u00f3 aquel grupo de antrop\u00f3logos dedicados a la educaci\u00f3n: qu\u00e9 es lo que la etnograf\u00eda puede aportar espec\u00edficamente al tema del abandono escolar. Nosotras, sin embargo, no encuadramos la pregunta en la tradici\u00f3n de la antropolog\u00eda como disciplina, como hab\u00edan hecho estos autores, sino que hemos preferido formularla desde la metodolog\u00eda, entendi\u00e9ndola como un espacio interdisciplinar que reune personas interesadas en el tema, pero que proceden de disciplinas diferentes: sociolog\u00eda, antropolog\u00eda, pedagog\u00eda, etc. Creemos que la interdisciplinariedad que permite nuestra pregunta formulada metodol\u00f3gicamente nos obliga a hacer m\u00e1s expl\u00edcitas la ideas que asumimos y, de esta forma, m\u00e1s comunicables.<br \/>Estamos convencidas de que esta interdisciplinariedad ha enriquecido considerablemente la conclusiones que todas las personas juntas fuimos capaces de pensar, articular y comunicar a lo largo de la sesi\u00f3n del simposium dedicada a la discusi\u00f3n. Aquellas ideas a las que contribuyeron tanto los ponentes como el p\u00fablico que particip\u00f3 en el di\u00e1logo las recogemos al final del libro, a modo de conclusiones parciales y con el prop\u00f3sito de abrir nuevas v\u00edas de discusi\u00f3n y reflexi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c27a81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c27a81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-2250853\" data-id=\"2250853\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0d0eff elementor-widget elementor-widget-text-editor\" data-id=\"b0d0eff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Descargar <a href=\"http:\/\/www.proyectos.cchs.csic.es\/integracion\/sites\/proyectos.cchs.csic.es.integracion\/files\/abandono_copia.pdf\">libro en pdf<\/a><\/p><div>\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6f0e8d9\" data-id=\"6f0e8d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf989eb elementor-widget elementor-widget-image\" data-id=\"bf989eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/8-q3s83w6l6io1uqzt1gchlelrssvpldhd68gdbrmhjk.jpg\" title=\"8\" alt=\"8\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-145034f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"145034f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f71ce2e\" data-id=\"f71ce2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f77ad elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"62f77ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faa1aef elementor-widget elementor-widget-text-editor\" data-id=\"faa1aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Mata Benito, Patricia; Ballesteros Vel\u00e1zquez, Bel\u00e9n y Gil Jaurena, In\u00e9s (Eds.). (2014). <i>Aprendizaje de la ciudadan\u00eda y la participaci\u00f3n<\/i>. Madrid: <\/b><b>Traficantes de sue\u00f1os. ISBN: <\/b><b> <span class=\"inplacedisplayid1siteid0\">978-<\/span>84-96453-87-6<\/b><b>. <\/b><\/p><p>Este libro recoge algunas de las aportaciones que tuvimos la oportunidad de presentar y debatir en el Simposio dedicado al aprendizaje de la ciudadan\u00eda y la participaci\u00f3n, en el marco del <i>III Congreso de Etnograf\u00eda y Educaci\u00f3n<\/i>, celebrado en Madrid, en el Instituto de Ciencias Sociales y Humanas del CSIC, en el mes de julio de 2013. Esta convocatoria nos permiti\u00f3 reunir a un grupo de investigadoras e investigadores que, desde distintas \u00e1reas disciplinares y a trav\u00e9s de perspectivas diversas, comparten nuestro inter\u00e9s en los discursos y los procesos educativos a trav\u00e9s de los cuales nos construimos como ciudadanos y ciudadanas, especialmente en aquellos que se orientan al desarrollo de una participaci\u00f3n cr\u00edtica y a la transformaci\u00f3n social.<br \/>El aprendizaje de la ciudadan\u00eda y la participaci\u00f3n acontece en diferentes espacios que, de manera<br \/>m\u00e1s o menos expl\u00edcita (o m\u00e1s o menos formal\/informal) se presentan como espacios educativos.<br \/>Uno de los escenarios educativos por excelencia es el \u00e1mbito escolar. Pero, \u00bfc\u00f3mo es el aprendizaje<br \/>de la ciudadan\u00eda y la participaci\u00f3n en este entorno? \u00bfQu\u00e9 se ense\u00f1a sobre la ciudadan\u00eda en el contexto<br \/>escolar? \u00bfY la participaci\u00f3n? \u00bfQu\u00e9 papel ocupan en el curriculum?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8d6b7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8d6b7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-9bd9a81\" data-id=\"9bd9a81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f925bc elementor-widget elementor-widget-text-editor\" data-id=\"7f925bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/www.academia.edu\/64815221\/Aprendizaje_de_la_ciudadan%C3%ADa_y_la_participaci%C3%B3n\">libro en pdf<\/a><\/p><div>\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d8e81ac\" data-id=\"d8e81ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e524f4 elementor-widget elementor-widget-image\" data-id=\"3e524f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/9-q3s83z03r0rwtkvpkzkdavw5kyht8gsk6metrlib0w.jpg\" title=\"9\" alt=\"9\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d09a33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d09a33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e35f05\" data-id=\"8e35f05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f59af9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7f59af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be84b85 elementor-widget elementor-widget-text-editor\" data-id=\"be84b85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><b>Osuna, Carmen<\/b> y Mata Benito, Patricia (Eds.). (2014). <i>Gesti\u00f3n del acceso al<br \/>campo y devoluci\u00f3n de los resultados.<\/i> Madrid: Traficantes de sue\u00f1os. ISBN: <\/b><b> 978-84-96453-93-6<\/b><b style=\"font-weight: bold\">. <\/b><\/p><p>Los textos compilados en este libro son producto de una reelaboraci\u00f3n de algunos de los trabajos presentados en el <i>III Congreso de Etnograf\u00eda y Educaci\u00f3n<\/i>. Como docentes e investigadoras nos interesa profundizar en el marco \u00e9tico de la producci\u00f3n del conocimiento y, en ese sentido, aprovechamos esta ocasi\u00f3n para hacer un llamamiento a que colegas de diferentes disciplinas, y que emplearan la etnograf\u00eda y el trabajo de campo como metodolog\u00eda, nos ayudaran a pensar en voz alta sobre los principales dilemas y retos a los que nos enfrentamos, tanto en el momento de acceder al campo, como en relaci\u00f3n con la devoluci\u00f3n de los resultados o de las conclusiones de nuestras investigaciones.<br \/>Tuvimos la gran suerte de contar con interesantisimas aportaciones de personas que no s\u00f3lo compartieron sus trabajos de campo y dilemas sino que ayudaron a generar un ambiente de di\u00e1logo y reflexi\u00f3n que en algunos momentos tom\u00f3 un cierto cariz cat\u00e1rtico: \u201ca m\u00ed tambi\u00e9n me pas\u00f3\u201d, \u201c\u00bfy qu\u00e9 hiciste\u201d?, \u201c\u00bfqu\u00e9 les dijiste?\u201d fueron preguntas surgidas durante el debate, fruto de intereses, inquietudes y hasta pesadillas compartidas en relaci\u00f3n con alguna cuesti\u00f3n no del todo bien resuelta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1a6483 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1a6483\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-102ebe0\" data-id=\"102ebe0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45ea915 elementor-widget elementor-widget-text-editor\" data-id=\"45ea915\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Descargar <a href=\"https:\/\/e-spacio.uned.es\/bitstreams\/56c500f1-0e5e-4b25-9e64-1bd7678552f2\/download\">libro en pdf<\/a><\/p><div>\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2884140\" data-id=\"2884140\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1212f25 elementor-widget elementor-widget-image\" data-id=\"1212f25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/10-q3s841tmbivrserm4is90d6jd43wvk3r70da7fe4i8.jpg\" title=\"10\" alt=\"10\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-771828e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"771828e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74aa3fc\" data-id=\"74aa3fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9046b29 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9046b29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f656eb4 elementor-widget elementor-widget-text-editor\" data-id=\"f656eb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Cucal\u00f3n Tirado, Pilar (Ed.). (2014). <i>Etnograf\u00eda de la escuela y la interseccionalidad.<\/i> Madrid: Traficantes de sue\u00f1os. ISBN: 978-84-96453-90-1<\/b><b style=\"font-weight: bold\">. <\/b><\/p><p>Este libro compila los trabajos presentados en el simposio Etnograf\u00eda de la Escuela y la Interseccionalidad en el seno del <i>III Congreso Internacional de Etnograf\u00eda y Educaci\u00f3n<\/i>. La jornada aport\u00f3 sugerentes e importantes reflexiones y debates.<br \/>A trav\u00e9s de los diversos textos pudimos pensar sobre las diferentes formas de analizar las realidades escolares desde una perspectiva interseccional, pero tambi\u00e9n sobre sus transformaciones. Esta \u00faltima es una cuesti\u00f3n que las autoras y autores han ido avanzado a lo largo de sus textos. Como coordinadora, sent\u00ed que la falta de tiempo nos entorpec\u00eda profundizar en las l\u00edneas de reflexi\u00f3n que plante\u00e1bamos, pero espero que \u00e9stas y otras sean desarrolladas a partir de esta publicaci\u00f3n y futuros encuentros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ad5eb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ad5eb5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5df24b5\" data-id=\"5df24b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96815b7 elementor-widget elementor-widget-text-editor\" data-id=\"96815b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/e-spacio.uned.es\/entities\/publication\/73517fbe-1325-4756-9ee6-060c3da5e0cf\">libro en pdf<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e6c85bf\" data-id=\"e6c85bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e75d33a elementor-widget elementor-widget-image\" data-id=\"e75d33a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/11-scaled-q3s84fx761f2mk74u6vnjrmg9w6f30nq8y5kekt7ww.jpg\" title=\"11\" alt=\"11\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-625faf0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"625faf0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8d3bd4\" data-id=\"d8d3bd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de5272b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"de5272b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d75bd7 elementor-widget elementor-widget-text-editor\" data-id=\"8d75bd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Malik, Beatriz; Senra, Mar\u00eda y Mamolar, Pilar. (2013). <i>Asesoramiento y consulta en educaci\u00f3n social<\/i>. Madrid: UNED. Colecci\u00f3n Grado. ISBN: <\/b><span style=\"font-weight: bold\">978-84-362-6552-1<\/span><b style=\"font-weight: bold\">. <\/b><\/p><p>La obra gira en torno a dos ideas centrales: el papel de los educadores sociales como agentes dinamizadores de procesos educativos y transformativos, y el cambio de enfoque en la intervenci\u00f3n, desde modelos prescriptivos y directivos hacia otros m\u00e1s colaborativos en los que las personas y comunidades implicadas asumen un rol activo en su propio aprendizaje y en la transformaci\u00f3n de su entorno.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a84e04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a84e04\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-798f257\" data-id=\"798f257\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-086e8b7 elementor-widget elementor-widget-text-editor\" data-id=\"086e8b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Disponible en formato electr\u00f3nico (pdf o epub): <a href=\"https:\/\/www.librosuned.com\/LU13213\/Asesoramiento-y-consulta-en-Educaci%C3%B3n-Social.aspx\">e-uned.es<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c6065a9\" data-id=\"c6065a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76b2a8c elementor-widget elementor-widget-image\" data-id=\"76b2a8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/12-q3s84r79g1uihvqr0br6dorzeimtndwiahze5wchu8.jpg\" title=\"12\" alt=\"12\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92e9354 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92e9354\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f3a7df\" data-id=\"0f3a7df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16b5279 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"16b5279\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd57749 elementor-widget elementor-widget-text-editor\" data-id=\"fd57749\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Ballesteros Vel\u00e1zquez, Bel\u00e9n y Gil Jaurena, In\u00e9s (coords.). (2012). <span style=\"font-style: italic\">Diversidad cultural y eficacia de la escuela. Un repertorio de buenas pr\u00e1cticas en centros de educaci\u00f3n obligatoria<\/span>. Madrid: Ministerio de Educaci\u00f3n. Colecci\u00f3n Entre Manos n\u00ba 3. ISBN: <\/b> <b>978-84-369-5116-5<\/b><b style=\"font-weight: bold\">. <\/b><\/p><p>El objeto del estudio que recoge esta publicaci\u00f3n es la consideraci\u00f3n de que la educaci\u00f3n debe atender a las diferencias culturales de los alumnos, tanto por razones axiol\u00f3gicas derivadas de los principios asumidos por sociedades que defienden derechos de igualdad, equidad y participaci\u00f3n social, como porque es la garant\u00eda que permita alcanzar objetivos educativos esenciales, como son la construcci\u00f3n de la propia identidad cultural y la igualdad de oportunidades en el acceso de todos a los bienes y recursos socioeducativos disponibles. La finalidad del proyecto es contribuir a la mejora de la escuela mediante la elaboraci\u00f3n y difusi\u00f3n de un repertorio de buenas pr\u00e1cticas desarrolladas en centros educativos espa\u00f1oles de los niveles obligatorios. Se entiende que una escuela eficaz es aquella que obtiene buenos resultados de todos los estudiantes m\u00e1s all\u00e1 de lo esperable en funci\u00f3n de su rendimiento inicial y de sus caracter\u00edsticas sociales, econ\u00f3micas y culturales. Con esta finalidad se propone revisar el concepto de \u00abbuenas pr\u00e1cticas\u00bb escolares y la noci\u00f3n de logros educativos de los estudiantes. A partir de esta revisi\u00f3n inicial, se identifican y ejemplifican aquellas pr\u00e1cticas escolares que se muestran eficaces en el logro de buenos resultados educativos en los estudiantes m\u00e1s all\u00e1 de cu\u00e1l sea su marco cultural de referencia. Por \u00faltimo, se describen y difunden tales pr\u00e1cticas en un repertorio que pueda ser utilizado por profesores\/as y responsables educativos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79be841 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79be841\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-466a61f\" data-id=\"466a61f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d78cf6e elementor-widget elementor-widget-text-editor\" data-id=\"d78cf6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">\u00a0Descargar <a href=\"https:\/\/www.libreria.educacion.gob.es\/libro\/diversidad-cultural-y-eficacia-de-la-escuela-un-repertorio-de-buenas-practicas-en-centros-de-educacion-obligatoria_180993\/\">libro en pdf<\/a><\/p><p style=\"text-align: right\">Descargar rese\u00f1a de Auxiliadora Sales Ciges en <i>Intercultural Education, 24<\/i>(6), 605-606. Diciembre 2013, (en ingl\u00e9s). <a href=\"http:\/\/dx.doi.org\/10.1080\/14675986.2013.867104\">http:\/\/dx.doi.org\/10.1080\/14675986.2013.867104<\/a><\/p><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8764e9d\" data-id=\"8764e9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fe81ea elementor-widget elementor-widget-image\" data-id=\"3fe81ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/13-q3s84t2xtpx353o0pckfioawladk2s3yyrad4g9phs.jpg\" title=\"13\" alt=\"13\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73ec5dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73ec5dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7517e1\" data-id=\"e7517e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-850cf0e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"850cf0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93a38f1 elementor-widget elementor-widget-text-editor\" data-id=\"93a38f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Hern\u00e1ndez S\u00e1nchez, Caridad (coord.). (2012). Racismo y educaci\u00f3n. De la invisibilidad a la evidencia. Madrid: Editorial Complutense. ISBN: <\/b> <strong>978-84-99381145<\/strong><b>. <\/b><\/p><p>\u00bfEst\u00e1 el \u201cracismo oculto\u201d presente en nuestras aulas? \u00bfSomos conscientes de ello y de lo que significa? \u201c\u2026 hablar de racismo no es f\u00e1cil. Es una realidad compleja que est\u00e1 presente en nuestra experiencia cotidiana\u2026\u201d. Esta frase responde y refleja el contenido de este libro. En sus p\u00e1ginas se abordan experiencias concretas del racismo, analizando sus caracter\u00edsticas y su impacto social, especialmente en el \u00e1mbito educativo. Adem\u00e1s, se ponen de manifiesto las dificultades que existen para reconocer la presencia del racismo, as\u00ed como los problemas que plantea su tratamiento. La obra se dirige fundamentalmente a los especialistas en educaci\u00f3n y quienes comparten la idea de que es necesario mejorar los niveles de sensibilizaci\u00f3n sobre estos temas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d245422 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d245422\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-b4ea9fb\" data-id=\"b4ea9fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3db019 elementor-widget elementor-widget-text-editor\" data-id=\"f3db019\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Disponible en <a href=\"https:\/\/repositorio.comillas.edu\/jspui\/bitstream\/11531\/41249\/1\/2012%20LIBRO%20RACISMO.pdf\">formato e-book <\/a><\/p><p style=\"text-align: right\"><span style=\"font-size: 1.2em;background-color: inherit;text-align: inherit\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1d073fa\" data-id=\"1d073fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21a4de4 elementor-widget elementor-widget-image\" data-id=\"21a4de4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/14-scaled-q3s84znt5k63edegmxeti4n4qzh4knu3bnurhdzya8.jpg\" title=\"14\" alt=\"14\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7352843 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7352843\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a7b24a\" data-id=\"3a7b24a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a47f161 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a47f161\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9928e8f elementor-widget elementor-widget-text-editor\" data-id=\"9928e8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Malik, Beatriz; Lobo, Luisa; \u00c1vila, Adriana y Espinosa, Victoria (coords.). (2010). <i>Un M\u00e1ster en Educaci\u00f3n Intercultural para Europa y Am\u00e9rica Latina: Necesidades, Curr\u00edculo e Implantaci\u00f3n<\/i>. Madrid: Proyecto ALFA. ISBN: 978-9989-192-02-9<\/b><b>. <\/b><\/p><p>Este trabajo subraya el valor de los hallazgos del proyecto INTER-Alfa. Su finalidad general es poner el esfuerzo y la experiencia del grupo a disposici\u00f3n de otras instituciones o universidades que puedan estar interesadas en el establecimiento de relaciones de cooperaci\u00f3n internacional y, en particular, de aquellas interesadas en el \u00e1rea de la Educaci\u00f3n Intercultural. Estas experiencias resultar\u00e1n del mismo modo interesantes para los futuros estudiantes del programa de M\u00e1ster.<\/p><p>El libro presenta la experiencia de cada instituci\u00f3n participante, as\u00ed como del grupo completo, en el proceso de dise\u00f1o del Postgrado Euro-Latinoamericano en Educaci\u00f3n Intercultural. Tanto los resultados del An\u00e1lisis de Necesidades como las experiencias vividas respecto al logro de los convenios institucionales constituyen ejemplos interesantes de acciones pr\u00e1cticas en pro de la internacionalizaci\u00f3n de las universidades y los programas de educaci\u00f3n a distancia, as\u00ed como de la creaci\u00f3n de programas educativos con un enfoque intercultural.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d32c368 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d32c368\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-00660aa\" data-id=\"00660aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e72163a elementor-widget elementor-widget-text-editor\" data-id=\"e72163a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/2024\/12\/LIBRO-I-PROYECTO-ALFA-UN-MASTER-EN-EDUCACION-INTERCULTURAL_PROCESO1.pdf\">libro en pdf<\/a><\/p><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b80949e\" data-id=\"b80949e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ee5ce5 elementor-widget elementor-widget-image\" data-id=\"7ee5ce5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/15-q3s853f5wwb8ot900z1bs3oz4iylfg90o6gpehudlc.jpg\" title=\"15\" alt=\"15\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b5910e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b5910e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ab6314\" data-id=\"4ab6314\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dc3713 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3dc3713\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3b5c05 elementor-widget elementor-widget-text-editor\" data-id=\"d3b5c05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Aguado Odina, Teresa (coord.). (2010). <span style=\"font-style: italic\">Diversidad e igualdad en educaci\u00f3n<\/span>. Madrid: UNED. Colecci\u00f3n Grado. ISBN: <\/b><span style=\"font-weight: bold\">978-84-362-6122-6<\/span><b style=\"font-weight: bold\">. <\/b><\/p><p>Este texto plantea c\u00f3mo miramos y entendemos la diversidad en educaci\u00f3n; c\u00f3mo esta mirada determina lo que esperamos y hacemos como educadores, y las complejas relaciones entre diversidad e igualdad en educaci\u00f3n.<br \/>La premisa de la que partimos es que la diversidad es normalidad, basta con conocerla; mientras que la igualdad implica un compromiso \u00e9tico por parte de los educadores.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94edf3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94edf3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c50f428\" data-id=\"c50f428\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6df3af1\" data-id=\"6df3af1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e30eb31 elementor-widget elementor-widget-text-editor\" data-id=\"e30eb31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">\u00a0<\/p><p style=\"text-align: right\">Ver ficha en la web de <a href=\"http:\/\/portal.uned.es\/portal\/page?_pageid=93,23377993&amp;_dad=portal&amp;_schema=PORTAL&amp;_piref93_23376063_93_23377993_23377993.next_page=\/htdocs\/ficha.jsp?IdArticulo=6301210GR01A01\">Editorial UNED<\/a><\/p><p style=\"text-align: right\">\u00a0<\/p><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0281812\" data-id=\"0281812\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21cbc61 elementor-widget elementor-widget-image\" data-id=\"21cbc61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/16-q3s8584cv2hoav269j2gmkia3gbfhxroctq4svneq8.jpg\" title=\"16\" alt=\"16\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4e04f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4e04f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d1e2d1\" data-id=\"0d1e2d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fdd452 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8fdd452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-112aab3 elementor-widget elementor-widget-text-editor\" data-id=\"112aab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>del Olmo, Margarita (ed.). (2010). <span style=\"font-style: italic\">Dilemas \u00e9ticos en antropolog\u00eda. Las entretelas del trabajo de campo etnogr\u00e1fico<\/span>. Madrid: Trotta. Colecci\u00f3n: Estructuras y Procesos. Antropolog\u00eda. <\/b> <b> ISBN: <\/b><span style=\"font-weight: bold\"> 978-84-9879-171-6<\/span><b style=\"font-weight: bold\">. <\/b><\/p><p>Cada uno de los cap\u00edtulos que re\u00fane este libro es una invitaci\u00f3n a abrir la discusi\u00f3n sobre \u00e9tica en el trabajo de campo etnogr\u00e1fico, desde un punto de vista diferente. Algunas de las perspectivas son coincidentes con otras en cuanto a los temas y a la forma de abordarlos, pero otras veces est\u00e1n en franca contradicci\u00f3n. Esto es as\u00ed porque no hemos resuelto nada; no se trataba tampoco de resolver nada. Lo que se pretend\u00eda era poner encima de la mesa, de una forma honesta, todo aquello que nos hab\u00eda incomodado, para lo que hab\u00edamos encontrado solamente soluciones parciales o precarias, o hab\u00edamos dejado francamente sin resolver. Este ejercicio supone darle la vuelta a la tela para ver las costuras, los remiendos y los errores, lo que implica una buena dosis de humildad y a veces un doloroso ejercicio de escarbar en la intimidad y dejar expuesto lo que normalmente se oculta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-390704c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"390704c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1f39e6b\" data-id=\"1f39e6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f03f51d\" data-id=\"f03f51d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47583fd elementor-widget elementor-widget-text-editor\" data-id=\"47583fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">\u00a0<\/p><p style=\"text-align: right\">Descargar<a href=\"https:\/\/digital.csic.es\/bitstream\/10261\/261828\/1\/dilemas-eticos-antropologia.pdf\"> libro en pdf<\/a><\/p><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-46dfe76\" data-id=\"46dfe76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a63bec5 elementor-widget elementor-widget-image\" data-id=\"a63bec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/17-q3s85axvfklj9oy2t2acc1snvlxj512vd7ol8pj87k.jpg\" title=\"17\" alt=\"17\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-858107a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"858107a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea50d13\" data-id=\"ea50d13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2d63d5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b2d63d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27a4dde elementor-widget elementor-widget-text-editor\" data-id=\"27a4dde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>del Olmo, Margarita. (2010). <span style=\"font-style: italic\">Re-Shaping Kids Through Public Policy on Diversity. Lessons from Madrid<\/span>. Madrid\/Vienna: Navreme Publications. Vol. 11. ISBN: <\/b><span style=\"font-weight: bold\">978-9989-192-19-7<\/span><b style=\"font-weight: bold\">. <\/b><\/p><p>Esta monograf\u00eda recoge los resultados del trabajo de campo realizado en las \u00abAulas de Enlace\u00bb, una medida de la Consejer\u00eda de la Comunidad de Madrid para acoger a los alumnos que se incorporan desde el extranjero durante el curso escolar. El objetivo es analizar los efectos de este programa educativo en la vida cotidiana de los chicos y chicas de una Aula de Enlace de Secundaria en un colegio concertado de la Comunidad de Madrid y los efectos en su trayectoria escolar. El an\u00e1lisis inscribe el programa en un contexto m\u00e1s amplio que incluye otros programas similares en el estado espa\u00f1ol y lo emplaza en un marco comparativo que incluye medidas semejantes en Viena (Austria) y en Texas (Estados Unidos); todo con la intenci\u00f3n de abrir un debate sobre las pol\u00edticas educativas en Europa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe9cb8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe9cb8e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f47ec88\" data-id=\"f47ec88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e47434 elementor-widget elementor-widget-text-editor\" data-id=\"6e47434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Ficha bibliogr\u00e1fica <a href=\"http:\/\/hdl.handle.net\/10261\/26301\">aqu\u00ed<\/a><\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/digital.csic.es\/bitstream\/10261\/26301\/1\/Re-Shaping%20Kids-MdelOlmo.pdf\">libro en pdf<\/a><\/p><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-144175f\" data-id=\"144175f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd0e27b elementor-widget elementor-widget-image\" data-id=\"dd0e27b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/18-scaled-q3s85ep86wqok4sm73wum0ui95ezzthspqaj5tdnio.jpg\" title=\"18\" alt=\"18\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b831bad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b831bad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1957e90\" data-id=\"1957e90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be0cc60 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"be0cc60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22102c1 elementor-widget elementor-widget-text-editor\" data-id=\"22102c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Aguado Odina, Teresa (coord.). (2010). Diversidad cultural y logros de los estudiantes en educaci\u00f3n obligatoria. Lo que sucede en las escuelas. Madrid: MEC-UNED. Estudios del CREADE n\u00ba 4. ISBN: <\/b>978-84-369-4858-5<b>. <\/b><\/p><p>La educaci\u00f3n, de forma prioritaria en la etapa obligatoria, debe atender a la diversidad cultural de los estudiantes. La escuela sigue siendo hoy por hoy una v\u00eda insustituible para lograr objetivos valiosos en sociedades que defienden principios de participaci\u00f3n y justicia social. Este documento presenta un resumen de la investigaci\u00f3n sobre la diversidad cultural de los estudiantes realizada durante el periodo 2003\/2006. El grupo de investigaci\u00f3n est\u00e1 constituido por profesores y estudiantes miembros del Grupo INTER de investigaci\u00f3n en educaci\u00f3n intercultural, adscrito como Centro de Investigaci\u00f3n al Instituto Universitario de Investigaci\u00f3n de la UNED. El informe se ha estructurado en diez cap\u00edtulos, en los que se apunta la finalidad, el plan de trabajo y la metodolog\u00eda, se analizan los resultados de la investigaci\u00f3n y se discuten las oportunidades, obst\u00e1culos y desaf\u00edos planteados en el estudio en torno a dichas cuestiones<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d5ecd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d5ecd6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-65bbcac\" data-id=\"65bbcac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9df1ceb elementor-widget elementor-widget-text-editor\" data-id=\"9df1ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">\u00a0<\/p><p style=\"text-align: right\">Ficha bibliogr\u00e1fica UNED <a href=\"http:\/\/portal.uned.es\/portal\/page?_pageid=93,23375984,93_23375985&amp;_dad=portal&amp;_schema=PORTAL&amp;_piref93_23376059_93_23375984_23375984.next_page=\/htdocs\/ficha.jsp?IdArticulo=0180154CO01A01\">aqu\u00ed<\/a><\/p><div class=\"notranslate\" style=\"background: initial;background-blend-mode: initial;border: initial;border-radius: initial;float: initial;clear: initial;vertical-align: initial;overflow: initial;columns: initial;column-fill: initial;column-rule: initial;column-span: initial;filter: initial;font: initial;border-collapse: initial;caption-side: initial;border-spacing: initial;color: initial;text-transform: initial;text-indent: initial;text-align: right;letter-spacing: initial;cursor: initial;margin: initial;padding: initial;flex-flow: initial;flex: initial;width: initial;min-width: initial;max-width: initial;height: initial;min-height: initial;max-height: initial;object-fit: initial;object-position: initial;gap: initial;text-decoration: initial\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0ff7a75\" data-id=\"0ff7a75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5385868 elementor-widget elementor-widget-image\" data-id=\"5385868\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/19-q3s85jef52x466lsfnxzghnt82ru2b0gedjyk76onk.jpg\" title=\"19\" alt=\"19\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5149b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5149b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-916be7a\" data-id=\"916be7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e084e0c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e084e0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff3e4c4 elementor-widget elementor-widget-text-editor\" data-id=\"ff3e4c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Aguado Odina, Teresa y del Olmo, Margarita (eds.). (2009). <span style=\"font-style: italic\">Intercultural education. Perspectives and proposals<\/span>. Madrid: Proyecto ALFA. ISBN: 978-84-613-5087-2. <\/b><\/p><p>Se trata de la versi\u00f3n en ingl\u00e9s de la obra realizada en el marco del <span style=\"font-style: italic\">proyecto INTER. Postgraduate Euro-Latinamerican Programme in Intercultural Education<\/span>, financiado por el Programa Alfa de la Uni\u00f3n Europea (ALFA II-0534-A). Re\u00fane una serie de trabajos de distintos autores que consideramos pueden ser \u00fatiles para provocar la reflexi\u00f3n sobre qu\u00e9 es, qu\u00e9 objetivos tiene, para qu\u00e9 sirve y qu\u00e9 desaf\u00edos implica entender la Educaci\u00f3n desde una perspectiva intercultural. Est\u00e1 dividido en dos partes: Perspectivas, que agrupa los trabajos m\u00e1s te\u00f3ricos y Propuestas, que dirigen la atenci\u00f3n hacia las pr\u00e1cticas educativas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d19b23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d19b23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ae341b7\" data-id=\"ae341b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2e8c6e elementor-widget elementor-widget-text-editor\" data-id=\"f2e8c6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">\u00a0<\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/www.academia.edu\/13011816\/Educaci%C3%B3n_intercultural_Perspectivas_y_propuestas\">libro en pdf<\/a><\/p><div class=\"notranslate\" style=\"background: initial;background-blend-mode: initial;border: initial;border-radius: initial;float: initial;clear: initial;vertical-align: initial;overflow: initial;columns: initial;column-fill: initial;column-rule: initial;column-span: initial;filter: initial;font: initial;border-collapse: initial;caption-side: initial;border-spacing: initial;color: initial;text-transform: initial;text-indent: initial;text-align: right;letter-spacing: initial;cursor: initial;margin: initial;padding: initial;flex-flow: initial;flex: initial;width: initial;min-width: initial;max-width: initial;height: initial;min-height: initial;max-height: initial;object-fit: initial;object-position: initial;gap: initial;text-decoration: initial\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ff4a1a\" data-id=\"7ff4a1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18289de elementor-widget elementor-widget-image\" data-id=\"18289de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/AnyConv.com__20-1-q3sbwjxutdqttshl1ixt3x4czjaup60gmmzr60zwwg.jpg\" title=\"AnyConv.com__20\" alt=\"AnyConv.com__20\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70574c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70574c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d32fdf1\" data-id=\"d32fdf1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-263fdd9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"263fdd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8601c5 elementor-widget elementor-widget-text-editor\" data-id=\"c8601c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Aguado Odina, Teresa y del Olmo, Margarita (coord.). (2009). <span style=\"font-style: italic\">Educaci\u00f3n intercultural. Perspectivas y propuestas<\/span>. Madrid: Ramon Areces. ISBN: 978-84-8004-952-8.<\/b><\/p><p>Este libro re\u00fane una serie de documentos que consideramos pueden ser \u00fatiles para provocar la reflexi\u00f3n sobre qu\u00e9 es, qu\u00e9 objetivos tiene, para qu\u00e9 sirve y que desaf\u00edos implica una educaci\u00f3n que sea intercultural. Los autores de los mismos son profesores del M\u00e1ster Euro-Latinoamericano en Educaci\u00f3n Intercultural, el cual se ha dise\u00f1ado gracias a un Proyecto ALFA (Comisi\u00f3n Europea, 2007\/2009) en el que han participado instituciones de M\u00e9xico, Chile, Colombia, Ecuador, Austria, Reino Unido, Irlanda, Letonia y Espa\u00f1a (<a href=\"https:\/\/www2.uned.es\/grupointer\/www.programainteralfa.org\">www.programainteralfa.org<\/a>).<\/p><p>INDICE: Educaci\u00f3n intercultural. Perspectivas y propuestas.-<\/p><p>PERSPECTIVAS.- El enfoque intercultural como met\u00e1fora de la diversidad en educaci\u00f3n.- Ciudadan\u00eda y participaci\u00f3n democr\u00e1tica. Sobre las condiciones de posibilidad de una sociedad intercultural.- El discurso intercultural ante el paradigma de la diversidad.- La perspectiva antropol\u00f3gica de la diversidad cultural en Educaci\u00f3n.- Interculturalidad. Una habilidad necesaria del siglo XXI.- A vueltas con el relativismo cultural.- Identidades m\u00faltiples de personas y grupos \u00bfun concepto \u00fatil para evitar la xenophobia?.- El negocio de las diferencias.- Una propuesta para entender las del racismo.- Aprendizaje del g\u00e9nero en la sociedad actual.-<\/p><p>PROPUESTAS.- Enfoque intercultural y pr\u00e1ctica escolar. Escenarios en la Comunidad de Madrid.- Aprendizaje cooperativo y colaborativo.- Construcci\u00f3n curricular para espacios de di\u00e1logo intercultural.- Evaluaci\u00f3n de proyectos. Qu\u00e9 es y por qu\u00e9 lo hacemos.- Tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n (TIC) en Educaci\u00f3n Intercultural.- Los demonios se olvidaron de m\u00ed. De racismo y experiencias en el proceso de cambio constitucional en Bolivia.- Trayectorias escolares \u00abexcepcionales\u00bb. An\u00e1lisis discursivo de algunas experiencias educativas.- Cultura y praxis juvenil. Una decodificaci\u00f3n de las culturas juveniles pospol\u00edticas actuales.- Diversidad cultural y libros de texto.- Cuerpo femenino y diversidad cultural. El caso de la \u00abmutilaci\u00f3n genital femenina\u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-769641f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"769641f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-4fcca1a\" data-id=\"4fcca1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d96f1b2 elementor-widget elementor-widget-text-editor\" data-id=\"d96f1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Venta de libro <a href=\"https:\/\/www.cerasa.es\/libro\/educacion-intercultural_49918\/\">Editorial Areces <br \/><\/a><\/p><p style=\"text-align: right\">\u00a0<\/p><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-005effa\" data-id=\"005effa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a082ba elementor-widget elementor-widget-image\" data-id=\"9a082ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/AnyConv.com__21-1-q3sbwkvp07s45eg7w1cfoevtkx67wv46yrn8nayiq8.jpg\" title=\"AnyConv.com__21\" alt=\"AnyConv.com__21\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cfaf29 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cfaf29\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf4e2ca\" data-id=\"cf4e2ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc07de6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bc07de6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-450f105 elementor-widget elementor-widget-text-editor\" data-id=\"450f105\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>T\u00e9llez, Jos\u00e9 Antonio (coord.). (2008). <span style=\"font-style: italic\">Educaci\u00f3n intercultural: miradas multidisciplinares<\/span>. Madrid: CIDE\/Catarata. <\/b><b>Colecci\u00f3n Cuadernos de Educaci\u00f3n Intercultural. <\/b><b>ISBN: <\/b> <span style=\"font-weight: bold;font-family: Verdana, Arial, Helvetica, sans-serif;font-size: small\">978-84-8319-372-3.<\/span><\/p><p>Abordar la educaci\u00f3n intercultural desde m\u00faltiples miradas es el prop\u00f3sito de esta selecci\u00f3n de art\u00edculos entretejidos. Desde disciplinas complementarias como la Filosof\u00eda la Antropolog\u00eda, la Etnograf\u00eda, la Sociolog\u00eda, la Educaci\u00f3n o la Historia como aproximaci\u00f3n al concepto de ciudadan\u00eda, el editor busca espacios para la reflexi\u00f3n. C\u00f3mo han influ\u00eddo los postulados y las cr\u00edticas del posmodernismo en el mundo acad\u00e9mico y en el devenir de la Antropolog\u00eda como disciplina y pr\u00e1ctica o cu\u00e1les fueron los procesos que han llevado a la creencia de que el trabajo de campo no recoge informaci\u00f3n sino que la produce, son algunas de las herramientas propuestas. El an\u00e1lisis de la interculturalidad desde los procesos migratorios nos acerca al pluralismo cultural y a la educaci\u00f3n: una escuela democr\u00e1tica necesita de la uni\u00f3n entre lo emocional y lo cognitivo. Su separaci\u00f3n es algo ficticio y artificial que induce a procesos de exclusi\u00f3n y desigualdad. Una \u00faltima reflexi\u00f3n nos lleva a plantear la definici\u00f3n tradicional de ciudadano como \u00abun miembro de una comunidad de iguales que participa directa o indirectamente en el ejercicio del poder pol\u00edtico a trav\u00e9s de las libertades de expresi\u00f3n, asociaci\u00f3n y organizaci\u00f3n, y de la participaci\u00f3n de la cosa p\u00fablica\u00bb como insuficiente, siendo necesario complementarla y ampliarla. Este car\u00e1cter diferenciador y no universalista de la ciudadan\u00eda puede funcionar como factor discriminatorio. La complementariedad de los art\u00edculos seleccionados nos ofrece una perspectiva amplia, conjunta, pluridisciplinar y enriquecedora sobre las dudas y los retos que nos plantea una sociedad muiticultural interconectada, de cara a un futuro que ser\u00e1 diverso o no ser\u00e1.<br \/>Participan en el libro: Jos\u00e9 A. T\u00e9llez (coord.), Jes\u00fas M. D\u00edaz \u00c1lvarez, Fernando Monge, Margarita del Olmo Pintado, Jennifer Lucko, Sara Morgenstern, \u00c1gueda Herv\u00e1s Alonso, Marta Irurozqui Victoriano.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-511427e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"511427e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-667ae1f\" data-id=\"667ae1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-260c821 elementor-widget elementor-widget-text-editor\" data-id=\"260c821\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Ficha del libro en\u00a0 <a href=\"https:\/\/traficantes.net\/libros\/educaci%C3%B3n-intercultural-1\">Editorial Traficantes de Sue\u00f1os <\/a><\/p><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c892292\" data-id=\"c892292\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9685cf0 elementor-widget elementor-widget-image\" data-id=\"9685cf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/AnyConv.com__22-1-q3sbwkvp07s45eg7w1cfoevtkx67wv46yrn8nayiq8.jpg\" title=\"AnyConv.com__22\" alt=\"AnyConv.com__22\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-459918a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"459918a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea7a61c\" data-id=\"ea7a61c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a2997c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3a2997c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7409f5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7409f5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-6955e6f\" data-id=\"6955e6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf150e0 elementor-widget elementor-widget-text-editor\" data-id=\"cf150e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Grupo Inter. (2007). Racism: A Teenagers&#8217; Perspective. Results of Preliminary Research from Madrid [Racismo, adolescencia e inmigraci\u00f3n. Im\u00e1genes y experiencia del racismo en adolescentes y j\u00f3venes]. Viena: Navreme. ISBN: 9989-50-051-7.<br \/><\/b><\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/scholar.dominican.edu\/cgi\/viewcontent.cgi?article=1006&amp;context=education-faculty-scholarship\">libro en pdf<\/a><\/p><div class=\"notranslate\">\u00a0<\/div><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e952ea9\" data-id=\"e952ea9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d3239f elementor-widget elementor-widget-image\" data-id=\"1d3239f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/23-q3s85p1ga34u3udliqdqvg8kse01chmuf5gvfuybm8.jpg\" title=\"23\" alt=\"23\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b153862 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b153862\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e438cde\" data-id=\"e438cde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23c0d56 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"23c0d56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-137c1b7 elementor-widget elementor-widget-text-editor\" data-id=\"137c1b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Grupo Inter. (2007). Racismo: qu\u00e9 es y c\u00f3mo se afronta. Una Gu\u00eda para hablar de racismo. Madrid: Pearson. ISBN: 978-84-205-5326-9. <\/b><\/p><p>No es f\u00e1cil hablar de racismo. Es una realidad compleja que est\u00e1 presente en nuestra experiencia diaria, tanto dentro como fuera de los \u00e1mbitos educativos; y, sin embargo, su existencia es habitualmente negada.<\/p><p>Cualquiera que sea la diversidad que exista en los distintos \u00e1mbitos de la vida, la \u00fanica forma de abordarla es reconocerla como normal y no convertirla en una excusa para discriminar o justificar el fracaso de la escuela con determinados estudiantes.<\/p><p>Esta gu\u00eda pretende ayudar tanto a j\u00f3venes como profesionales a afrontar el tema del racismo para que no se convierta en un problema.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d48f66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d48f66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a72f38e\" data-id=\"a72f38e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-288b515 elementor-widget elementor-widget-text-editor\" data-id=\"288b515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right\">Descargar <a href=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/2024\/12\/GUIA-RACISMO.pdf\">libro en pdf<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cebbdc9\" data-id=\"cebbdc9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da349a6 elementor-widget elementor-widget-image\" data-id=\"da349a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/Screenshot_8-qydwrk5n2yvamrk38srap65gp4xcornz792xruju4w.png\" title=\"Screenshot_8\" alt=\"Screenshot_8\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f8bf23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f8bf23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e78c840\" data-id=\"e78c840\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58e9908 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"58e9908\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a972c3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a972c3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-4963b76\" data-id=\"4963b76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d38c437 elementor-widget elementor-widget-text-editor\" data-id=\"d38c437\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Grupo Inter. (2006). Educaci\u00f3n Intercultural: necesidades de formaci\u00f3n de profesorado desde la perspectiva europea \/ Intercultural Education: teacher training needs from a european perspective. Madrid: Estudios de la UNED. ISBN: 84-362-5119-9. <\/b><\/p><p style=\"text-align: right\">Ficha bibliogr\u00e1fica <a href=\"https:\/\/www.libreriacasatomada.es\/es\/libro\/educacion-intercultural-necesidades-de-formacion-del-profesorado-desde-una-perspectiva-europea-intercultural-education-teacher-training-needs-from-an-europea_4750310061\">aqu\u00ed<\/a><\/p><div>\u00a0<\/div><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7aca5fc\" data-id=\"7aca5fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68512cf elementor-widget elementor-widget-image\" data-id=\"68512cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/26-q3s85ruyul8p2o9i29lmkxiykjm4zky1fjfbvou53k.gif\" title=\"26\" alt=\"26\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-739d8d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"739d8d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e39c375\" data-id=\"e39c375\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1b9c05 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f1b9c05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2887f3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2887f3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-921d4d5\" data-id=\"921d4d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83ac89b elementor-widget elementor-widget-text-editor\" data-id=\"83ac89b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Grupo Inter. (2006).<span style=\"font-style: italic\"> Gu\u00eda INTER: una gu\u00eda practica para aplicar la educaci\u00f3n intercultural en la escuela<\/span>. Madrid: MEC\/CIDE. ISBN: 84-369-4243-4.<\/b><\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/www.libreria.educacion.gob.es\/libro\/guia-inter-una-guia-practica-para-aplicar-la-educacion-intercultural-en-la-escuela_183520\/\">libro en pdf<\/a><\/p><p>Primer Premio Aula 2007 al mejor libro de educaci\u00f3n y divulgaci\u00f3n educativa, en la modalidad de obras sobre pr\u00e1ctica educativa o de divulgaci\u00f3n cient\u00edfica que puedan despertar y fomentar el inter\u00e9s en los j\u00f3venes, Ministerio de Educaci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4609a63\" data-id=\"4609a63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aa13e9 elementor-widget elementor-widget-image\" data-id=\"1aa13e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/27-q3s85sst1f9zea84ws095faf5xhi7a1rro2tcysqxc.gif\" title=\"27\" alt=\"27\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffa9e95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffa9e95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcdb5d6\" data-id=\"dcdb5d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7469e90 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7469e90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb7aff7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb7aff7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e8fcf48\" data-id=\"e8fcf48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60fea27 elementor-widget elementor-widget-text-editor\" data-id=\"60fea27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Grupo Inter. (2006). <span style=\"font-style: italic\">Culture is our focus, diversity is our normality. INTER guide to implement intercultural education<\/span>. Viena: Navreme. ISBN: 9989-50-041-X.<br \/><\/b><\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/digital.csic.es\/bitstream\/10261\/28765\/1\/CultureIsOurFocus.pdf\">libro en pdf<\/a><\/p><div>\u00a0<\/div><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-378c6d4\" data-id=\"378c6d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b9417e elementor-widget elementor-widget-image\" data-id=\"1b9417e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/28-q3s85uohf3ck1i5elstiaetccp88mo98fxdsbipykw.jpg\" title=\"28\" alt=\"28\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ea30e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ea30e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd102bb\" data-id=\"dd102bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b833224 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b833224\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0295e10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0295e10\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-17aefa8\" data-id=\"17aefa8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93aa3df elementor-widget elementor-widget-text-editor\" data-id=\"93aa3df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Grupo INTER. (2005). Gu\u00eda INTER. Una gu\u00eda pr\u00e1ctica para aplicar la educaci\u00f3n intercultural en la escuela<\/b>.<\/p><p style=\"text-align: right\">Descargar <a href=\"https:\/\/www.libreria.educacion.gob.es\/libro\/guia-inter-una-guia-practica-para-aplicar-la-educacion-intercultural-en-la-escuela_183520\/\">libro en pdf<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f3ec0b\" data-id=\"2f3ec0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8425182 elementor-widget elementor-widget-image\" data-id=\"8425182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/29-q3s85vmblxdud441gb84uwksy33ludcys219ssokeo.jpg\" title=\"29\" alt=\"29\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c4a78b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c4a78b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1394272\" data-id=\"1394272\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f1730a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0f1730a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7eb53a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7eb53a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-c1aadb0\" data-id=\"c1aadb0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a79b9d0 elementor-widget elementor-widget-text-editor\" data-id=\"a79b9d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Hern\u00e1ndez, C. y del Olmo, M. (2005): <span style=\"font-style: italic\">Antropolog\u00eda en el aula<\/span>.<br \/>Madrid: Editorial S\u00edntesis.<\/b><\/p><p style=\"text-align: left\">Este es un libro dedicado a facilitar la dif\u00edcil tarea de ense\u00f1ar en una sociedad multicultural. Se trata de una propuesta did\u00e1ctica, secuenciada por niveles y ciclos educativos, enfocada desde la Antropolog\u00eda como perspectiva v\u00e1lida a la hora de elaborar conceptos y herramientas para ense\u00f1ar en las aulas con un alumnado cultural y socialmente diverso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-67bc900\" data-id=\"67bc900\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fddaeb elementor-widget elementor-widget-image\" data-id=\"3fddaeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/30-q3s85wk5srf4oq2oatmrfec9jgyz22gp46ora2n68g.jpg\" title=\"30\" alt=\"30\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6846a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6846a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48d7f78\" data-id=\"48d7f78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c16da2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3c16da2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a262eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a262eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a246d6d\" data-id=\"a246d6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a37c888 elementor-widget elementor-widget-text-editor\" data-id=\"a37c888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>T\u00e9llez, J. A., Malik, B., Mata, P. y Sutil, I. (2005): <span style=\"font-style: italic\">Orientaci\u00f3n intercultural<\/span>. Madrid: Sanz y Torres. <\/b> <span class=\"inplacedisplayid1siteid0\" style=\"font-weight: bold\">ISBN: 84-96094-64-2.<\/span><\/p><p>En este libro est\u00e1 dedicado al desarrollo de competencias interculturales tanto de profesores, alumnos como de principalmente de los orientadores educativos. Se plantea un modelo de orientaci\u00f3n denominado colaborativo-dinamizador que intente gestionar y hacer participe al resto de profesionales y miembros de la comunidad educativa en su quehacer diario. Se reflexiona a partir de un concepto amplio de cultura en torno a temas de amplio calado que influyen y determinan muchas de las acciones que se desarrollan en las aulas, como pueden ser las pol\u00edticas educativas o las teor\u00edas sobre la ense\u00f1anza y el aprendizaje.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-66f7d04\" data-id=\"66f7d04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ae995b elementor-widget elementor-widget-image\" data-id=\"8ae995b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/31-q3s85yfu6fhpbxzxzug0kdv6q8pphgo5sfzq8mkdw0.jpg\" title=\"31\" alt=\"31\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fb8365 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fb8365\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9bde19e\" data-id=\"9bde19e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18a9287 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"18a9287\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af2b5c5 elementor-widget elementor-widget-text-editor\" data-id=\"af2b5c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Aguado Odina, Teresa, Gil Jaurena, In\u00e9s y Mata Benito, Patricia. (2005). Educaci\u00f3n intercultural: una propuesta para la transformaci\u00f3n de la escuela.\u00a0 Madrid: CIDE\/Catarata. <\/b><b>Colecci\u00f3n Cuadernos de Educaci\u00f3n Intercultural. <\/b><b>ISBN: 978-84-831-9243-6. <\/b><\/p><p>Seguir atribuy\u00e9ndole a la escuela un papel reproductor adaptado a las necesidades de una sociedad neutralizante es olvidarse de que las sociedades son movedizas, de que las culturas nacen del intercambio y son agentes de dinamizaci\u00f3n de los espacios compartidos. La educaci\u00f3n intercultural, tal como la enfoca este manual, no nace en reacci\u00f3n al cambio en la escuela, ni es una medida paliativa contra el virus de la diversidad: es un planteamiento valiente para la construcci\u00f3n de la escuela del futuro. Un planteamiento integral que propone pautas concretas de actuaci\u00f3n, tanto desde el aula (ofreciendo metodolog\u00edas y pr\u00e1cticas escolares renovadas) como desde el \u00e1mbito institucional y de pol\u00edticas educativas. Esta obra abarca los fundamentos conceptuales de interculturalidad, las pol\u00edticas deseables para favorecer un giro pedag\u00f3gico en la formaci\u00f3n del profesorado, el an\u00e1lisis del funcionamiento organizativo de los centros educativos y de sus principales retos futuros y las redes que enlazan los distintos componentes de la comunidad educativa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a73e708 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a73e708\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-419e7e0\" data-id=\"419e7e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-536bb34 elementor-widget elementor-widget-text-editor\" data-id=\"536bb34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: right\">Ver ficha t\u00e9cnica <a href=\"https:\/\/www.libreria.educacion.gob.es\/libro\/educacion-intercultural-una-propuesta-para-la-transformacion-de-la-escuela_174246\/\">libreria<\/a><\/p><p style=\"text-align: right\">\u00a0<\/p><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6cbcfe6\" data-id=\"6cbcfe6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df0295a elementor-widget elementor-widget-image\" data-id=\"df0295a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/32-q3s85zdod9iznjykucun4vmnbml2p5rw4kn7pwizps.gif\" title=\"32\" alt=\"32\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75ce59f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75ce59f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be34e97\" data-id=\"be34e97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-854782c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"854782c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86e03ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86e03ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-2b27667\" data-id=\"2b27667\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d20af2 elementor-widget elementor-widget-text-editor\" data-id=\"0d20af2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Malik Li\u00e9vano, Beatriz y Herraz Ramos, Mercedes. (2005). Mediaci\u00f3n intercultural en contextos socio-educativos. M\u00e1laga: Aljibe. <\/b> <span class=\"inplacedisplayid1siteid0\">ISBN: <\/span>84-9700-320-9<span class=\"inplacedisplayid1siteid0\">.<\/span><\/p><p>Extracto de contenido: mediaci\u00f3n intercultural: bases conceptuales e introducci\u00f3n; mentes en relaci\u00f3n; estereotipo y prejuicio; cultura y diferencias culturales; diversidad cultural y derechos humanos I: derechos sociales b\u00e1sicos, g\u00e9nero, religi\u00f3n y familia; diversidad cultural y derechos humanos II: derecho a la educaci\u00f3n; la escuela intercultural; t\u00e9cnicas de resoluci\u00f3n de conflictos; comunicaci\u00f3n interpersonal y comunicaci\u00f3n intercultural; evaluaci\u00f3n y desarrollo de la competencia de la comunicaci\u00f3n intercultural.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9d57ab3\" data-id=\"9d57ab3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7edaa3 elementor-widget elementor-widget-image\" data-id=\"b7edaa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/33-q3s860bik3k9z5x7ov99pde3x0gfwuvmgpap76hljk.jpg\" title=\"33\" alt=\"33\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-841c836 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"841c836\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee99b2f\" data-id=\"ee99b2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8fd40d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d8fd40d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf9948f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf9948f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-0ff8f9c\" data-id=\"0ff8f9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf91fb8 elementor-widget elementor-widget-text-editor\" data-id=\"cf91fb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Aguado, Teresa. (2003): Pedagog\u00eda Intercultural. Mc-Graw Hill, Madrid.<\/b><\/p><p>El texto propone adoptar un enfoque intercultural al abordar cuestiones relevantes en pedagog\u00eda, tanto en el \u00e1mbito de la reflexi\u00f3n como en el de la investigaci\u00f3n y la pr\u00e1ctica. Si consideramos que la diversidad cultural no es algo nuevo, sino que siempre ha estado presente de forma m\u00e1s o menos visible en todo grupo humano, \u00bfpor qu\u00e9 es ahora y en determinados contextos sociales donde esta diversidad se ha hecho expl\u00edcita y se ha tomado como objeto de an\u00e1lisis? \u00c9stas y otras cuestiones en torno al tema son las que el texto aborda. No se trata de dar recetas sino de promover un modo de pensamiento sobre las cuestiones que tienen que ver con la diversidad en educaci\u00f3n, las cuales siempre describen situaciones din\u00e1micas y complejas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d8ad9ce\" data-id=\"d8ad9ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4d04eb elementor-widget elementor-widget-image\" data-id=\"d4d04eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/34-q3s86276xrmumduhdw2iucx13s76c9334ylo5qet74.jpg\" title=\"34\" alt=\"34\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8e82c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8e82c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7700a3\" data-id=\"d7700a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-821c068 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"821c068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4f9835 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4f9835\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5800dce\" data-id=\"5800dce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4863e64 elementor-widget elementor-widget-text-editor\" data-id=\"4863e64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Aguado, T; Jim\u00e9nez-Fr\u00edas, R; Sacrist\u00e1n, A; Gil, J.A; Ballesteros, B; Malik, B; S\u00e1nchez, M. (1999): Diversidad cultural e igualdad escolar. Un modelo para el diagn\u00f3stico y desarrollo de actuaciones educativas en contextos escolares multiculturales. Series de Investigaci\u00f3n, 141, MEC\/CIDE, Madrid.<br \/><\/b><\/p><p style=\"text-align: right\">Ver <a href=\"https:\/\/www.libreria.educacion.gob.es\/libro\/diversidad-cultural-e-igualdad-escolar-un-modelo-para-el-diagnostico-y-desarrollo-de-actuaciones-educativas-en-contextos-escolares-multiculturales_164994\/\">ficha de la publicaci\u00f3n<\/a><\/p><p style=\"text-align: right\">Primer Premio de Investigaci\u00f3n Educativa 1998 del Ministerio de Educaci\u00f3n<\/p><div class=\"notranslate\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-67de904\" data-id=\"67de904\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e04898 elementor-widget elementor-widget-image\" data-id=\"4e04898\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blogs.uned.es\/grupointer\/wp-content\/uploads\/sites\/377\/elementor\/thumbs\/35-q3s863514lo4xzt48eh5euohp62jjy6th395n0df0w.jpg\" title=\"35\" alt=\"35\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18f2375 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18f2375\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b3a2ea\" data-id=\"7b3a2ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba51533 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ba51533\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LIBROS 7 libros coordinados por Teresa Aguado han sido incluidos, tras su evaluaci\u00f3n, en el portal del Observatorio de Diversidad Cultural e Interculturalidad de UNESCO-IESALC. Gonz\u00e1lez, M.F. y \u00a0Ballesteros Vel\u00e1zquez, B. (Coords) (2023).\u00a0Comprender el mundo para (intentar) transformarlo. Una gu\u00eda posible para el an\u00e1lisis cualitativo de datos. UNED.\u00a0. Nuestro prop\u00f3sito en esta obra era ofrecer [&hellip;]<\/p>\n","protected":false},"author":7641,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2335","page","type-page","status-publish","czr-hentry"],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/grupointer\/wp-json\/wp\/v2\/pages\/2335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/grupointer\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.uned.es\/grupointer\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/grupointer\/wp-json\/wp\/v2\/users\/7641"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/grupointer\/wp-json\/wp\/v2\/comments?post=2335"}],"version-history":[{"count":109,"href":"https:\/\/blogs.uned.es\/grupointer\/wp-json\/wp\/v2\/pages\/2335\/revisions"}],"predecessor-version":[{"id":6225,"href":"https:\/\/blogs.uned.es\/grupointer\/wp-json\/wp\/v2\/pages\/2335\/revisions\/6225"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/grupointer\/wp-json\/wp\/v2\/media?parent=2335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}