{"id":583,"date":"2017-10-20T07:37:16","date_gmt":"2017-10-20T07:37:16","guid":{"rendered":"http:\/\/blogs.uned.es\/gesp\/?p=583"},"modified":"2017-10-20T07:37:16","modified_gmt":"2017-10-20T07:37:16","slug":"romper-el-marco-espana","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/","title":{"rendered":"Romper el marco \u00abEspa\u00f1a\u00bb"},"content":{"rendered":"<p>por <a href=\"http:\/\/www.ucm.es\/castromil\/\">Ant\u00f3n R. Castromil<\/a><\/p>\n<p>La \u201ccuesti\u00f3n catalana\u201d ha sido abordada desde muchos puntos de vista: legal, pol\u00edtico, internacional, de convivencia\u2026 A m\u00ed me gustar\u00eda a\u00f1adir <strong>un poco m\u00e1s de combustible<\/strong> a un debate que conviene alimentar y mantener, ya que nos va mucho en ello en tanto que sociedad.<\/p>\n<p>Lo que se propone aqu\u00ed tiene que ver con un elemento anal\u00edtico adicional que apunta a la construcci\u00f3n de los significados entre los ciudadanos. \u00bfQu\u00e9 significan los marcos \u201cEspa\u00f1a\u201d y \u201cCatalunya\u201d en tanto que elementos interpretativos de los hechos pol\u00edticos y sociales que estamos viviendo? \u00bf<strong>C\u00f3mo han sido construidos y qu\u00e9 caracter\u00edsticas presentan?<\/strong><\/p>\n<p>La cuesti\u00f3n tiene su importancia, ya que se trata de abordar la problem\u00e1tica de c\u00f3mo <strong>los ciudadanos construyen sus universos significativos<\/strong>. Sus filias, sus fobias, sus miedos, enfados y alegr\u00edas.<\/p>\n<p>Me da la sensaci\u00f3n de que, en el fondo, el \u201c<strong>choque de trenes<\/strong>\u201d entre Espa\u00f1a y Catalunya tiene mucho que ver con la construcci\u00f3n de lo que \u201cCatalunya\u201d y \u201cEspa\u00f1a\u201d significan en la mente de todos nosotros.<\/p>\n<p>Ofrecemos aqu\u00ed algunas hip\u00f3tesis para el debate. El principal elemento de \u00e9xito del encuadre \u201cCatalunya\u201d quiz\u00e1 tenga que ver son su car\u00e1cter interclasista, mucho m\u00e1s que con cuestiones culturales t\u00edpicas del nacionalismo m\u00e1s esencialista.<\/p>\n<p>Es decir, la idea de que Catalunya es <strong>una naci\u00f3n con derecho a decidir su futuro <\/strong>de manera aut\u00f3noma ha sido aceptada por los m\u00e1s diversos estratos sociales.<\/p>\n<p>Y ha hecho posible lo impensable: que la izquierda independentista cl\u00e1sica (ERC), los independentistas antisistema (CUP) y la derecha nacionalista burguesa (PDeCAT) remen en la misma direcci\u00f3n.<\/p>\n<p>De este modo, el encuadre soberanista catal\u00e1n ha sido capaz de desplazar la l\u00ednea de conflicto cl\u00e1sica que hab\u00eda enfrentado a estos actores desde lo ideol\u00f3gico-clasista a lo nacional, naciendo as\u00ed <strong>el denominado \u201cproc\u00e9s\u201d.<\/strong><\/p>\n<p>Da la sensaci\u00f3n de que estos actores (y algunos movimientos sociales y organizaciones circundantes) han sido capaces de llevar a cabo un proceso de simplificaci\u00f3n del encuadre \u201cCatalunya\u201d.<\/p>\n<p>Parece evidente que el significante \u201cCatalunya\u201d ha relajado cuestiones esencialistas cl\u00e1sicas. Quedan fuera o bastante marginadas del debate p\u00fablico la lengua, la cultura y literatura catalanas o la historia com\u00fan que enra\u00edza en el alma del pueblo catal\u00e1n.<\/p>\n<p>Todo ello cede espacio (aunque no desaparece del todo) a cuestiones de \u00e1mbito pol\u00edtico. Pero un \u00e1mbito pol\u00edtico que, a su vez, podr\u00edamos definir como de \u201c<strong>baja intensidad<\/strong>\u201d. El derecho a decidir ha podido ser suscrito por sectores sociales muy diversos.<\/p>\n<p>Con estas nuevas reglas de juego, ciudadanos muy diferentes han podido<br \/>\n<em>comprar\u00a0<\/em><strong>el redefinido encuadre \u201cCatalunya\u201d<\/strong>. Se trata de un universo significativo mucho m\u00e1s pobre, pero m\u00e1s incluyente y, en definitiva, m\u00e1s potente.<\/p>\n<p>Proceso contrario parece que sufre el encuadre \u201cEspa\u00f1a\u201d. Sigue conteniendo un componente excluyente que lastra su aplicabilidad en amplios sectores sociales, sobre todo en el universo simb\u00f3lico de la izquierda y en ciertos territorios denominados \u201chist\u00f3ricos\u201d.<\/p>\n<p>Se podr\u00eda argumentar que \u201cEspa\u00f1a\u201d en tanto que marco que organiza la experiencia y empuja al ciudadano a la acci\u00f3n dispone de un campo de aplicaci\u00f3n mucho m\u00e1s limitado y pobre.<\/p>\n<p>Habr\u00eda que estudiar el encuadre a fondo, pero, en una primera mirada, descubrimos en \u00e9l cuestiones como el centralismo castellano, restos de tradiciones en declive (como el catolicismo y la tauromaquia, por ejemplo) y <strong>un claro tufo pol\u00edtico conservador<\/strong>. Todos estos elementos (y algunos otros que el lector pueda incorporar) parecen asediar al universo significativo \u201cEspa\u00f1a\u201d.<\/p>\n<p>Si esto es as\u00ed, el \u201c<strong>choque de trenes<\/strong>\u201d al que hac\u00edamos referencia hace s\u00f3lo un momento se podr\u00eda estar produciendo entre una locomotora perfectamente engrasada y a toda velocidad (Catalunya) y un vetusto tren de cercan\u00edas achacoso y taciturno (Espa\u00f1a).<\/p>\n<p>Quiz\u00e1 esta circunstancia explique el empe\u00f1o del gobierno del Partido Popular por tratar el \u201c<strong>problema catal\u00e1n<\/strong>\u201d desde una perspectiva exclusivamente legalista y policial. Parece que desde Moncloa son conscientes que en el terreno pol\u00edtico tienen todas las de perder. Por eso utilizan el parapeto en apariencia impermeable de la Constituci\u00f3n y el Tribunal Constitucional.<\/p>\n<p>Una posible soluci\u00f3n para que este enfrentamiento de encuadres Espa\u00f1a\/Catalunya deje de ser un juego de suma cero tiene que ver con la necesidad imperiosa que tenemos de romper el actual marco \u201cEspa\u00f1a\u201d.<\/p>\n<p>De igual modo que los catalanes han sido capaces de redefinir la idea de \u201cCatalunya\u201d para coser en ella todo un \u201cproc\u00e9s\u201d soberanista, desde Espa\u00f1a se necesita abrir a nuevos sectores sociales la idea de pa\u00eds.<\/p>\n<p>Hoy en d\u00eda definirse como espa\u00f1ol contin\u00faa siendo tarea ardua para muchos ciudadanos, lo que da clara muestra del car\u00e1cter excluyente del encuadre. Pero los marcos, como dir\u00eda el soci\u00f3logo canadiense Erving Goffman, tambi\u00e9n sufren crisis de aplicabilidad, de manera que, en muchas ocasiones, terminan rompi\u00e9ndose.<\/p>\n<p>Debemos romper el encuadre monol\u00edtico \u201cEspa\u00f1a\u201d. Desgastarlo para, inmediatamente despu\u00e9s, transformarlo en lugar de encuentro e intersecci\u00f3n de sectores sociales, pol\u00edtica e ideol\u00f3gicamente diversos.<\/p>\n<p>Un nuevo marco que sea capaz de crear fisuras en el actual encuadre \u201cCatalunya\u201d,<strong> rob\u00e1ndole adeptos<\/strong>. Ciudadanos que pudieren resultar atra\u00eddos por una nueva visi\u00f3n de una Espa\u00f1a abierta, plural, multinacional y pluriling\u00fce, en la que la diferencia sea vista como un valor y no como un factor de desconfianza.<\/p>\n<p>Pero claro, para ello se necesita que la izquierda espa\u00f1ola se implique en el proyecto y que la derecha acepte dejar de secuestrar el encuadre \u201cEspa\u00f1a\u201d. Ni una ni otra posibilidad parecen demasiado factibles. Sin embargo, la urgencia del momento hist\u00f3rico que vivimos parece aconsejarlo antes de que el tiempo se agote.<\/p>\n<p>Art\u00edculo originariamente publicado el 06\/10\/2017 en <a href=\"https:\/\/www.infolibre.es\/noticias\/opinion\/plaza_publica\/2017\/10\/29\/romper_marco_espana_70299_2003.html\">infolibre<\/a>.<script><\/p>\n<p><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Ant\u00f3n R. Castromil La \u201ccuesti\u00f3n catalana\u201d ha sido abordada desde muchos puntos de vista: legal, pol\u00edtico, internacional, de convivencia\u2026 A m\u00ed me gustar\u00eda a\u00f1adir un poco m\u00e1s de combustible a un debate que conviene alimentar y mantener, ya que nos va mucho en ello en tanto que sociedad. Lo que se propone aqu\u00ed tiene [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[255],"tags":[15,19,13,11,21,17],"class_list":["post-583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudadania-accion-colectiva-y-participacion","tag-catalunya","tag-clase-social","tag-espana","tag-framing","tag-modelo-de-estado","tag-nacionalismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Romper el marco &quot;Espa\u00f1a&quot; - Grupo de Estudios sobre Sociedad y Pol\u00edtica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Romper el marco &quot;Espa\u00f1a&quot; - Grupo de Estudios sobre Sociedad y Pol\u00edtica\" \/>\n<meta property=\"og:description\" content=\"por Ant\u00f3n R. Castromil La \u201ccuesti\u00f3n catalana\u201d ha sido abordada desde muchos puntos de vista: legal, pol\u00edtico, internacional, de convivencia\u2026 A m\u00ed me gustar\u00eda a\u00f1adir un poco m\u00e1s de combustible a un debate que conviene alimentar y mantener, ya que nos va mucho en ello en tanto que sociedad. Lo que se propone aqu\u00ed tiene [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo de Estudios sobre Sociedad y Pol\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-20T07:37:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2017\/10\/senyera_estelada_toro-de-osborne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"677\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GESP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrupoEstudios\" \/>\n<meta name=\"twitter:site\" content=\"@GrupoEstudios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GESP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/\"},\"author\":{\"name\":\"GESP\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/person\\\/ecd18a39405b70f35f53c2f5fed98526\"},\"headline\":\"Romper el marco \u00abEspa\u00f1a\u00bb\",\"datePublished\":\"2017-10-20T07:37:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/\"},\"wordCount\":1000,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2017\\\/10\\\/senyera_estelada_toro-de-osborne.jpg\",\"keywords\":[\"Catalunya\",\"clase social\",\"Espa\u00f1a\",\"framing\",\"modelo de estado\",\"nacionalismo\"],\"articleSection\":[\"Ciudadan\u00eda, acci\u00f3n colectiva y participaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/\",\"name\":\"Romper el marco \\\"Espa\u00f1a\\\" - Grupo de Estudios sobre Sociedad y Pol\u00edtica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2017\\\/10\\\/senyera_estelada_toro-de-osborne.jpg\",\"datePublished\":\"2017-10-20T07:37:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2017\\\/10\\\/senyera_estelada_toro-de-osborne.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2017\\\/10\\\/senyera_estelada_toro-de-osborne.jpg\",\"width\":677,\"height\":452},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/romper-el-marco-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Romper el marco \u00abEspa\u00f1a\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#website\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\",\"name\":\"Grupo de Estudios sobre Sociedad y Pol\u00edtica\",\"description\":\"P\u00e1gina web del Grupo de Estudios sobre Sociedad y Pol\u00edtica (GESP)\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\"},\"alternateName\":\"GESP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\",\"name\":\"GESP\",\"alternateName\":\"Grupo de Estudios Sobre Sociedad y Pol\u00edtica\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/07\\\/GESP.png\",\"contentUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/07\\\/GESP.png\",\"width\":1000,\"height\":1000,\"caption\":\"GESP\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/GrupoEstudios\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/person\\\/ecd18a39405b70f35f53c2f5fed98526\",\"name\":\"GESP\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Romper el marco \"Espa\u00f1a\" - Grupo de Estudios sobre Sociedad y Pol\u00edtica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/","og_locale":"es_ES","og_type":"article","og_title":"Romper el marco \"Espa\u00f1a\" - Grupo de Estudios sobre Sociedad y Pol\u00edtica","og_description":"por Ant\u00f3n R. Castromil La \u201ccuesti\u00f3n catalana\u201d ha sido abordada desde muchos puntos de vista: legal, pol\u00edtico, internacional, de convivencia\u2026 A m\u00ed me gustar\u00eda a\u00f1adir un poco m\u00e1s de combustible a un debate que conviene alimentar y mantener, ya que nos va mucho en ello en tanto que sociedad. Lo que se propone aqu\u00ed tiene [&hellip;]","og_url":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/","og_site_name":"Grupo de Estudios sobre Sociedad y Pol\u00edtica","article_published_time":"2017-10-20T07:37:16+00:00","og_image":[{"width":677,"height":452,"url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2017\/10\/senyera_estelada_toro-de-osborne.jpg","type":"image\/jpeg"}],"author":"GESP","twitter_card":"summary_large_image","twitter_creator":"@GrupoEstudios","twitter_site":"@GrupoEstudios","twitter_misc":{"Escrito por":"GESP","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/#article","isPartOf":{"@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/"},"author":{"name":"GESP","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/person\/ecd18a39405b70f35f53c2f5fed98526"},"headline":"Romper el marco \u00abEspa\u00f1a\u00bb","datePublished":"2017-10-20T07:37:16+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/"},"wordCount":1000,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.uned.es\/gesp\/#organization"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2017\/10\/senyera_estelada_toro-de-osborne.jpg","keywords":["Catalunya","clase social","Espa\u00f1a","framing","modelo de estado","nacionalismo"],"articleSection":["Ciudadan\u00eda, acci\u00f3n colectiva y participaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/","url":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/","name":"Romper el marco \"Espa\u00f1a\" - Grupo de Estudios sobre Sociedad y Pol\u00edtica","isPartOf":{"@id":"https:\/\/blogs.uned.es\/gesp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/#primaryimage"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2017\/10\/senyera_estelada_toro-de-osborne.jpg","datePublished":"2017-10-20T07:37:16+00:00","breadcrumb":{"@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/#primaryimage","url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2017\/10\/senyera_estelada_toro-de-osborne.jpg","contentUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2017\/10\/senyera_estelada_toro-de-osborne.jpg","width":677,"height":452},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.uned.es\/gesp\/romper-el-marco-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.uned.es\/gesp\/"},{"@type":"ListItem","position":2,"name":"Romper el marco \u00abEspa\u00f1a\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/blogs.uned.es\/gesp\/#website","url":"https:\/\/blogs.uned.es\/gesp\/","name":"Grupo de Estudios sobre Sociedad y Pol\u00edtica","description":"P\u00e1gina web del Grupo de Estudios sobre Sociedad y Pol\u00edtica (GESP)","publisher":{"@id":"https:\/\/blogs.uned.es\/gesp\/#organization"},"alternateName":"GESP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.uned.es\/gesp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.uned.es\/gesp\/#organization","name":"GESP","alternateName":"Grupo de Estudios Sobre Sociedad y Pol\u00edtica","url":"https:\/\/blogs.uned.es\/gesp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/07\/GESP.png","contentUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/07\/GESP.png","width":1000,"height":1000,"caption":"GESP"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/GrupoEstudios"]},{"@type":"Person","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/person\/ecd18a39405b70f35f53c2f5fed98526","name":"GESP"}]}},"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/comments?post=583"}],"version-history":[{"count":1,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/583\/revisions"}],"predecessor-version":[{"id":585,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/583\/revisions\/585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/media\/587"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/media?parent=583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/categories?post=583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/tags?post=583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}