{"id":2671,"date":"2026-05-18T21:59:32","date_gmt":"2026-05-18T19:59:32","guid":{"rendered":"https:\/\/blogs.uned.es\/gesp\/?p=2671"},"modified":"2026-05-18T21:59:34","modified_gmt":"2026-05-18T19:59:34","slug":"gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/","title":{"rendered":"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" id=\"block-267a8368-18a7-49e3-aad9-cdc8d8b13760\">19\/05\/2026 &#8211; Carolina Schillagi, Universidad Nacional de General Sarmiento-Universidad del Gran Rosario (Argentina)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde hace varias d\u00e9cadas asistimos a transformaciones en las sensibilidades hacia la vulnerabilidad y el sufrimiento. Aquello que Fassin y Rechtman (2010) llamaron el imperio del trauma y Wiewiorka (2023) un \u201cgiro antropol\u00f3gico\u201d, tiene como contrapartida la relevancia de la figura de la v\u00edctima como condici\u00f3n moral contempor\u00e1nea. Estas transformaciones fueron a la par de distintas formas de institucionalizaci\u00f3n del acompa\u00f1amiento a personas y colectivos dolientes. Los estados y las organizaciones humanitarias desplegaron todo un conjunto de normas, agencias y dispositivos de atenci\u00f3n que en cada contexto nacional y regional adquirieron una impronta espec\u00edfica y dieron cuenta de la progresiva importancia del sufrimiento social como objeto de las pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este escenario, los efectos pol\u00edticos que estos procesos implican son una cuesti\u00f3n de inter\u00e9s para la reflexi\u00f3n sociol\u00f3gica. Podemos, entonces, pensarlos a trav\u00e9s de algunos ejes de an\u00e1lisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>I.<\/strong> La vulnerabilidad y el riesgo como rasgos de la vida social contempor\u00e1nea contribuyeron a la centralidad del sufrimiento provocado por violencias, da\u00f1os, cat\u00e1strofes y delitos de distinto tipo. Situaciones y acontecimientos que en el pasado se explicaban a trav\u00e9s de la idea del infortunio, el destino o el azar, en las sociedades de la modernidad tard\u00eda fueron paulatinamente atribuidas a causas racionales y vinculadas a la responsabilidad humana por acci\u00f3n u omisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el escenario contempor\u00e1neo de creciente protagonismo de la v\u00edctima como personaje p\u00fablico, el sufrimiento se asimila a la vulnerabilidad. Se trata de una situaci\u00f3n parad\u00f3jica o cuanto menos ambigua pues a la v\u00edctima, en tanto sujeto fr\u00e1gil y expuesto al da\u00f1o o la violencia se le otorgan cuidados y acompa\u00f1amiento pero, al mismo tiempo, se le exige autonom\u00eda y gobierno de s\u00ed misma para salir adelante. Lo cierto es que la tr\u00edada <em>vulnerabilidad-sufrimiento-v\u00edctima<\/em> conforma un encadenamiento sem\u00e1ntico sobre el que se monta una idea muy potente: todas las v\u00edctimas, en mayor o menor grado, son vulnerables porque sufren. Y si son vulnerables su voz (social) es una voz d\u00e9bil. La agencia resulta, entonces, alejada de sus posibilidades. En base a esto emerge toda una discusi\u00f3n sobre la relaci\u00f3n entre vulnerabilidad y agencia de las v\u00edctimas (Mart\u00ednez, 2019). Esa discusi\u00f3n tiene como trasfondo una pregunta: \u00bfqu\u00e9 efectos pol\u00edticos tiene el tipo de subjetividad que presupone el gobierno del sufrimiento?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las respuestas posibles son muchas y ninguna es concluyente. Se trata de un debate en curso, tanto pol\u00edtico como acad\u00e9mico. Existen cr\u00edticas y an\u00e1lisis que recogen algunas aristas de este problema complejo. Por ejemplo, aquellos que hacen hincapi\u00e9 en la eficacia pol\u00edtica del sufrimiento y la vulnerabilidad (y, por ende, la victimizaci\u00f3n) como las formas por excelencia en las que, en el contexto del \u201ccapitalismo emocional\u201d es posible obtener legitimidad y apoyo social. Es interesante c\u00f3mo en este caso el foco est\u00e1 puesto en el rol que tiene la vulnerabilidad en moldear el yo como una figura p\u00fablica de sufrimiento que produce efectos pol\u00edticos de reconocimiento. Para Chouliaraki (2021), las dos grandes narrativas que dieron sustento a esta \u201cpol\u00edtica afectiva del dolor\u201d son el psicoan\u00e1lisis y los derechos humanos. Aunque basadas en reg\u00edmenes afectivos distintos como la empat\u00eda y la indignaci\u00f3n, ambas tienen en com\u00fan estimular en el p\u00fablico una respuesta inmediata al dolor al precio de suprimir la pregunta sobre el contexto en el que se producen los reclamos y reivindicaciones. Y eso es, precisamente, lo que est\u00e1 en el coraz\u00f3n de su eficacia pol\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s enfocados en realidades de los pa\u00edses del Cono Sur de Am\u00e9rica Latina, otros <a href=\"https:\/\/nuso.org\/articulo\/izquierda-memoria-futuro-transicion-dictaduras-historia\/\">an\u00e1lisis&nbsp; <\/a>argumentan que tanto el lenguaje de los derechos humanos como el de la compasi\u00f3n, han moldeado los procesos de transici\u00f3n a la democracia y los ciclos progresistas de las primeras d\u00e9cadas del siglo XXI al punto de conformar un sentido com\u00fan que tiende a opacar la idea de lucha por la transformaci\u00f3n de las condiciones estructurales que fueron corro\u00eddas por las pol\u00edticas neoliberales. En la medida en que los gobiernos interpretan las demandas sociales en clave de reparaci\u00f3n y de alivio al sufrimiento de distintos tipos de v\u00edctimas (v\u00eda pol\u00edticas p\u00fablicas y leyes de garant\u00edas y derechos espec\u00edficos o sectoriales) estos an\u00e1lisis advierten sobre el debilitamiento de la centralidad del sujeto colectivo como agente del cambio social y pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s debamos preguntarnos entonces qu\u00e9 tipo de relaci\u00f3n posible podemos pensar entre v\u00edctima, vulnerabilidad y agencia que pueda sortear, aunque m\u00e1s no sea en parte, la visi\u00f3n determinista o un\u00edvoca que termina imponiendo el sufrimiento o el trauma si se los considera como inherentes a las subjetividades contempor\u00e1neas. Por ejemplo, pensar la agencia de los y las vulnerables despegada de la figura de la v\u00edctima como estatus y como condici\u00f3n \u00fanicamente individual, desprendida del entramado social-colectivo. Ello implica pensar esta figura en su contingencia radical, como proceso socialmente producido, vinculado a condiciones materiales concretas as\u00ed como a trayectorias y legados pol\u00edticos locales y por lo tanto con m\u00e1rgenes de acci\u00f3n que son singulares y no generales. Por otro lado, tambi\u00e9n podemos pensar la cuesti\u00f3n de la <a href=\"https:\/\/static.ides.org.ar\/archivo\/artic34.pdf\">ambivalencia del sufrimiento<\/a> como fuente de vulnerabilidad, de aislamiento, de impotencia pero tambi\u00e9n como un modo de construcci\u00f3n de la agencia y, por lo tanto, de su potencial capacidad para crear v\u00ednculos, comunidad y visiones del mundo m\u00e1s o menos compartidas (Schillagi, 2011). Si nos apoyamos en estas claves de lectura o si recogemos el desaf\u00edo de pensar en otras formas de acercarnos a la agencia o las posibilidades de acci\u00f3n y de lenguajes de los sujetos vulnerables, es posible que avizoremos efectos pol\u00edticos distintos de los que ya han sido se\u00f1alados y generar -o continuar y profundizar- una discusi\u00f3n al respecto.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>II.<\/strong> El gobierno del sufrimiento involucra la gesti\u00f3n, es decir, la forma en que el Estado tramita y lleva adelante un conjunto de acciones y de decisiones respecto de poblaciones afectadas por diferentes tipos de hechos da\u00f1osos. As\u00ed como antes plante\u00e1bamos las implicancias pol\u00edticas con relaci\u00f3n a las subjetividades, la idea del gobierno del sufrimiento tambi\u00e9n nos invita a pensar la cuesti\u00f3n de las pr\u00e1cticas y los usos que movilizan los agentes estatales (saberes, lenguajes, <em>expertise<\/em>) cuando las personas toman contacto con los dispositivos. \u00bfQu\u00e9 cuestiones podemos dejar planteadas para sugerir algunas pistas de an\u00e1lisis en casos emp\u00edricos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Las <em>tecnolog\u00edas de gobierno<\/em> en las que se apoya el funcionamiento de los dispositivos son cruciales para entender el tipo de sujeto que moldean las pr\u00e1cticas y usos que el Estado pone en marcha. Por ejemplo, los registros escritos o documentos que se utilizan no son meros tr\u00e1mites administrativos; son tecnolog\u00edas polif\u00f3nicas (distintas voces de t\u00e9cnicos, profesionales y funcionarias narran ese paso por el dispositivo a la manera de un diario). Tecnolog\u00edas, dec\u00edamos, que construyen la subjetividad de la v\u00edctima, moldean sus contornos como un sujeto sufriente y vulnerable que necesita tutela. Como dice Fassin (2006) \u201clos relatos pat\u00e9ticos\u201d frente a los agentes del Estado tienen efectos en el proceso de subjetivaci\u00f3n y de sujeci\u00f3n, es decir, en la construcci\u00f3n de s\u00ed y en el sometimiento al Estado. El dispositivo, encarnado en protocolos, archivos y lugares f\u00edsicos se entreteje con mundos locales que desaf\u00edan las formas de intervenci\u00f3n y sus sentidos. Esos mundos locales no son s\u00f3lo las trayectorias biogr\u00e1ficas de las personas (en las que se basan las agencias estatales para atenderlas y delinear sus intervenciones, es decir, para gobernarlas) sino tambi\u00e9n los mundos fabricados entre disciplinas y saberes profesionales que forman parte de lo que llamamos el aparato estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Los<a href=\"https:\/\/revistas.ungs.edu.ar\/index.php\/po\/article\/view\/1093\/1336\"><em>saberes disciplinarios en pr\u00e1ctica<\/em><\/a><em>. <\/em>En las rutinas diarias del trabajo con v\u00edctimas las fronteras profesionales suelen desdibujarse. Los abogados hacen \u00abescucha\u00bb y los psic\u00f3logos gestionan tr\u00e1mites habitacionales o tramitan documentos de identidad. Se produce as\u00ed un saber-hacer h\u00edbrido donde la formaci\u00f3n disciplinaria original (por lo general el derecho, la psicolog\u00eda, el trabajo social) se transforma en una \u00abespecificidad de oficio\u00bb moldeada por la urgencia y, no pocas veces, la escasez de recursos. El trabajo de los y las profesionales en el Estado no s\u00f3lo adquiere ribetes particulares en cuanto a las exigencias pr\u00e1cticas de la gesti\u00f3n diaria en contacto con el dolor y el sufrimiento (forzando frecuentemente los l\u00edmites del tipo de intervenci\u00f3n m\u00e1s distanciada que caracteriza al quehacer profesional tradicional) sino que trae aparejados tensiones pol\u00edticas que gravitan en las l\u00f3gicas profesionales y contribuyen a una selectividad y jerarquizaci\u00f3n de las personas y grupos que son validados y acompa\u00f1ados en su calidad de v\u00edctimas. En esa interacci\u00f3n entre el estado y los \u201cmundos de v\u00edctimas\u201d (Gatti, 2017), es necesario poner el foco anal\u00edtico, tomando distancia de una visi\u00f3n normativa para poder comprender las pr\u00e1cticas disimuladas bajo el lenguaje en apariencia uniforme y t\u00e9cnico o las rutinas burocr\u00e1ticas estandarizadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los m\u00e1rgenes de maniobra del accionar estatal -m\u00e1rgenes que emergen en los resquicios de las rutinas burocr\u00e1ticas, sobre todo en la forma en que se ponen en marcha saberes y modos de actuaci\u00f3n por fuera de los protocolos- es donde debemos indagar para comprender c\u00f3mo un modelo integral de atenci\u00f3n a las v\u00edctimas se plasma y qu\u00e9 tipo de efectos tiene en las poblaciones y sujetos que entran en contacto con los dispositivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Referencias bibliogr\u00e1ficas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chouliaraki, L. (2021). Victimhood: The affective politics of vulnerability. <em>European Journal of Cultural Studies, 24<\/em>(1), 10\u201327. <a href=\"https:\/\/doi.org\/10.1177\/1367549420979316\">https:\/\/doi.org\/10.1177\/1367549420979316<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fassin, D. (2006). Souffrir par le social, gouverner par l\u2019\u00e9coute: Une configuration s\u00e9mantique de l\u2019action publique. <em>Politix, 73<\/em>(1), 137\u2013157. <a href=\"https:\/\/doi.org\/10.3917\/pox.073.0137\">https:\/\/doi.org\/10.3917\/pox.073.0137<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fassin, D., &amp; Rechtman, R. (2010). <em>L\u2019empire du traumatisme: Enqu\u00eate sur la condition de victime<\/em>. Flammarion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gatti, G. (Ed.). (2017). <em>Un mundo de v\u00edctimas<\/em>. Anthropos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mart\u00ednez, M. (2019). Una breve (y no muy sistem\u00e1tica) aproximaci\u00f3n a la noci\u00f3n de agencia desde la vulnerabilidad. <em>Papeles del CEIC, 2019<\/em>(1), Art\u00edculo 205, 1\u20139. <a href=\"https:\/\/doi.org\/10.1387\/pceic.20616\">https:\/\/doi.org\/10.1387\/pceic.20616<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schillagi, C. (2011). Sufrimiento y lazo social: Algunas reflexiones sobre la naturaleza ambivalente del dolor. <em>Pr\u00e1cticas de Oficio. Investigaci\u00f3n y Reflexi\u00f3n en Ciencias Sociales, 7\/8<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wieviorka, M. (2023). El surgimiento de las v\u00edctimas. En D. Zenobi (Comp.), <em>V\u00edctimas: Debates sobre una condici\u00f3n contempor\u00e1nea<\/em>. Teseo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>19\/05\/2026 &#8211; Carolina Schillagi, Universidad Nacional de General Sarmiento-Universidad del Gran Rosario (Argentina) Desde hace varias d\u00e9cadas asistimos a transformaciones en las sensibilidades hacia la vulnerabilidad y el sufrimiento. Aquello que Fassin y Rechtman (2010) llamaron el imperio del trauma y Wiewiorka (2023) un \u201cgiro antropol\u00f3gico\u201d, tiene como contrapartida la relevancia de la figura de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[113],"class_list":["post-2671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-y-cultura-politica","tag-participacion-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas? - Grupo de Estudios sobre Sociedad y Pol\u00edtica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas? - Grupo de Estudios sobre Sociedad y Pol\u00edtica\" \/>\n<meta property=\"og:description\" content=\"19\/05\/2026 &#8211; Carolina Schillagi, Universidad Nacional de General Sarmiento-Universidad del Gran Rosario (Argentina) Desde hace varias d\u00e9cadas asistimos a transformaciones en las sensibilidades hacia la vulnerabilidad y el sufrimiento. Aquello que Fassin y Rechtman (2010) llamaron el imperio del trauma y Wiewiorka (2023) un \u201cgiro antropol\u00f3gico\u201d, tiene como contrapartida la relevancia de la figura de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo de Estudios sobre Sociedad y Pol\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-18T19:59:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-18T19:59:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/05\/aetjartj.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"blogsunedes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrupoEstudios\" \/>\n<meta name=\"twitter:site\" content=\"@GrupoEstudios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"blogsunedes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/\"},\"author\":{\"name\":\"blogsunedes\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/person\\\/251abc71d1a0d51e5b326f38f9049c50\"},\"headline\":\"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas?\",\"datePublished\":\"2026-05-18T19:59:32+00:00\",\"dateModified\":\"2026-05-18T19:59:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/\"},\"wordCount\":1828,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/05\\\/aetjartj.jpg\",\"keywords\":[\"participaci\u00f3n pol\u00edtica\"],\"articleSection\":[\"Comunicaci\u00f3n y cultura pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/\",\"name\":\"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas? - Grupo de Estudios sobre Sociedad y Pol\u00edtica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/05\\\/aetjartj.jpg\",\"datePublished\":\"2026-05-18T19:59:32+00:00\",\"dateModified\":\"2026-05-18T19:59:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/05\\\/aetjartj.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/05\\\/aetjartj.jpg\",\"width\":567,\"height\":424},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#website\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\",\"name\":\"Grupo de Estudios sobre Sociedad y Pol\u00edtica\",\"description\":\"P\u00e1gina web del Grupo de Estudios sobre Sociedad y Pol\u00edtica (GESP)\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\"},\"alternateName\":\"GESP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\",\"name\":\"GESP\",\"alternateName\":\"Grupo de Estudios Sobre Sociedad y Pol\u00edtica\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/07\\\/GESP.png\",\"contentUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/07\\\/GESP.png\",\"width\":1000,\"height\":1000,\"caption\":\"GESP\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/GrupoEstudios\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/person\\\/251abc71d1a0d51e5b326f38f9049c50\",\"name\":\"blogsunedes\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas? - Grupo de Estudios sobre Sociedad y Pol\u00edtica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas? - Grupo de Estudios sobre Sociedad y Pol\u00edtica","og_description":"19\/05\/2026 &#8211; Carolina Schillagi, Universidad Nacional de General Sarmiento-Universidad del Gran Rosario (Argentina) Desde hace varias d\u00e9cadas asistimos a transformaciones en las sensibilidades hacia la vulnerabilidad y el sufrimiento. Aquello que Fassin y Rechtman (2010) llamaron el imperio del trauma y Wiewiorka (2023) un \u201cgiro antropol\u00f3gico\u201d, tiene como contrapartida la relevancia de la figura de [&hellip;]","og_url":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/","og_site_name":"Grupo de Estudios sobre Sociedad y Pol\u00edtica","article_published_time":"2026-05-18T19:59:32+00:00","article_modified_time":"2026-05-18T19:59:34+00:00","og_image":[{"width":567,"height":424,"url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/05\/aetjartj.jpg","type":"image\/jpeg"}],"author":"blogsunedes","twitter_card":"summary_large_image","twitter_creator":"@GrupoEstudios","twitter_site":"@GrupoEstudios","twitter_misc":{"Escrito por":"blogsunedes","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/#article","isPartOf":{"@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/"},"author":{"name":"blogsunedes","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/person\/251abc71d1a0d51e5b326f38f9049c50"},"headline":"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas?","datePublished":"2026-05-18T19:59:32+00:00","dateModified":"2026-05-18T19:59:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/"},"wordCount":1828,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.uned.es\/gesp\/#organization"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/05\/aetjartj.jpg","keywords":["participaci\u00f3n pol\u00edtica"],"articleSection":["Comunicaci\u00f3n y cultura pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/","url":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/","name":"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas? - Grupo de Estudios sobre Sociedad y Pol\u00edtica","isPartOf":{"@id":"https:\/\/blogs.uned.es\/gesp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/#primaryimage"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/05\/aetjartj.jpg","datePublished":"2026-05-18T19:59:32+00:00","dateModified":"2026-05-18T19:59:34+00:00","breadcrumb":{"@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/#primaryimage","url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/05\/aetjartj.jpg","contentUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/05\/aetjartj.jpg","width":567,"height":424},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.uned.es\/gesp\/gobierno-del-sufrimiento-y-vulnerabilidad-como-podemos-pensar-la-agencia-de-las-victimas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.uned.es\/gesp\/"},{"@type":"ListItem","position":2,"name":"Gobierno del sufrimiento y vulnerabilidad: \u00bfc\u00f3mo podemos pensar la agencia de las v\u00edctimas?"}]},{"@type":"WebSite","@id":"https:\/\/blogs.uned.es\/gesp\/#website","url":"https:\/\/blogs.uned.es\/gesp\/","name":"Grupo de Estudios sobre Sociedad y Pol\u00edtica","description":"P\u00e1gina web del Grupo de Estudios sobre Sociedad y Pol\u00edtica (GESP)","publisher":{"@id":"https:\/\/blogs.uned.es\/gesp\/#organization"},"alternateName":"GESP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.uned.es\/gesp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.uned.es\/gesp\/#organization","name":"GESP","alternateName":"Grupo de Estudios Sobre Sociedad y Pol\u00edtica","url":"https:\/\/blogs.uned.es\/gesp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/07\/GESP.png","contentUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/07\/GESP.png","width":1000,"height":1000,"caption":"GESP"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/GrupoEstudios"]},{"@type":"Person","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/person\/251abc71d1a0d51e5b326f38f9049c50","name":"blogsunedes"}]}},"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/2671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/comments?post=2671"}],"version-history":[{"count":2,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/2671\/revisions"}],"predecessor-version":[{"id":3037,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/2671\/revisions\/3037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/media\/2673"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/media?parent=2671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/categories?post=2671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/tags?post=2671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}