{"id":1175,"date":"2019-04-23T12:26:31","date_gmt":"2019-04-23T12:26:31","guid":{"rendered":"http:\/\/blogs.uned.es\/gesp\/?p=1175"},"modified":"2019-05-01T21:06:36","modified_gmt":"2019-05-01T21:06:36","slug":"analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/","title":{"rendered":"An\u00e1lisis de Problemas Sociales de nuestro tiempo &#8211; Jornadas UNED 2019"},"content":{"rendered":"<p>Los d\u00edas 26 y 27 de abril tendr\u00e1n lugar las jornadas \u00abAn\u00e1lisis de Problemas Sociales de nuestro tiempo\u00bb, organizadas por la UNED y m\u00e1s concretamente por el M\u00e1ster en Problemas Sociales, el departamento de Sociolog\u00eda III y el programa de Doctorado de Problemas Sociales.<\/p>\n<p style=\"padding-left: 30px\"><strong>VIERNES 26 DE ABRIL<\/strong><br \/>\n<strong>9.00\/9.30. PRESENTACI\u00d3N DE LAS JORNADAS<\/strong>: JOS\u00c9 ANTONIO D\u00cdAZ MARTINEZ, VER\u00d3NICA D\u00cdAZ MORENO Y JULIO BORDAS.<br \/>\n9.30\/10.30: PONENCIA ROBERT FISHMAN: \u201cPr\u00e1cticas democr\u00e1ticas en perspectiva comparada: Espa\u00f1a y Portugal, dos maneras de afrontar la crisis econ\u00f3mica y pol\u00edtica\u201d. (Profesor CONEX-Marie Curie de Ciencia Pol\u00edtica y Sociolog\u00eda Universidad Carlos III)<\/p>\n<p style=\"padding-left: 30px\"><strong>10.30 14.00: PRIMERA MESA REDONDA: AFRONTAR LOS PROBLEMAS DESDE LA POL\u00cdTICA.<\/strong><br \/>\nMODERADORA: MAR\u00cdA JES\u00daS FUNES<br \/>\nMAR\u00cdA JES\u00daS FUNES: Las relaciones entre los ciudadanos y la pol\u00edtica (Profesora Titular de Sociolog\u00eda UNED).<br \/>\nEDUARDO ROMANOS: Afrontar los problemas desde los movimientos sociales: la pol\u00edtica de la concienciaci\u00f3n y la protesta. (Profesor Contratado Doctor de Sociolog\u00eda Universidad Complutense de Madrid).<br \/>\nOSCAR IGLESIAS: Afrontar los problemas desde el poder central: Democracia, ciudadan\u00eda y parlamento. (Profesor Asociado de Sociolog\u00eda UNED)<br \/>\nTOM\u00c1S ALBERICH: Afrontar los problemas desde la pol\u00edtica local y la participaci\u00f3n no institucional (Profesor Titular de Sociolog\u00eda UNED)<br \/>\n12.30: 12.45. Descanso<br \/>\n12.45- 14.00. Debate<\/p>\n<p style=\"padding-left: 30px\"><strong>15:30-19.00: SEGUNDA MESA REDONDA: PROBLEMAS SOCIALES ACTUALES<\/strong><br \/>\nMODERADORA: VER\u00d3NICA D\u00cdAZ MORENO<br \/>\nOSCAR JAIME: \u201cDelincuencia y crisis\u201d. (Profesor Titular de Sociolog\u00eda UNED).<br \/>\nVER\u00d3NICA D\u00cdAZ MORENO: El problema del suicidio juvenil en Espa\u00f1a (Profesora Contratada Doctora de Sociolog\u00eda UNED)<br \/>\nVIOLANTE MARTINEZ Y MARIA MARTINEZ Violencia de G\u00e9nero desde la perspectiva feminista y sociol\u00f3gica. (Profesora Titular de Sociolog\u00eda UNED y Profesora Ayudante Doctora de Sociolog\u00eda UNED)<br \/>\nHILDE SANCHEZ MORALES: Discapacidad y exclusi\u00f3n social (Catedr\u00e1tica de Sociolog\u00eda UNED)<br \/>\n17.45-18.00: DESCANSO<br \/>\n18.00 A 19.00: DEBATE.<\/p>\n<p style=\"padding-left: 30px\"><strong>S\u00c1BADO 27 de abril<\/strong><br \/>\n<strong>10.00-13.30. TERCERA MESA REDONDA: TRABAJO Y MIGRACIONES<\/strong><br \/>\nMODERADOR: Julio Bordas<br \/>\nJULIO BORDAS: \u00bfTrabajo decente o trabajo indecente? (coordinador del Programa de Doctorado An\u00e1lisis de los problemas sociales UNED)<br \/>\nJOS\u00c9 ANTONIO D\u00cdAZ: Innovaci\u00f3n tecnol\u00f3gica y desempleo (Director del Departamento de Sociolog\u00eda III (Tendencias Sociales) UNED)<\/p>\n<p style=\"padding-left: 30px\">JAVIER PINILLA y PILAR NOVA: Crisis laboral y seguridad y salud en el trabajo. (Director del Instituto Nacional de Seguridad e Higiene en el Trabajo y Directora del Centro de Formaci\u00f3n Avanzada en Relaciones Laborales y Estudios Sindicales (UNED)<br \/>\nSERGIO BARCIELA: Situaci\u00f3n laboral de las personas migrantes en la agricultura, hosteler\u00eda y servicio dom\u00e9stic (Equipo de migraciones de C\u00e1ritas Espa\u00f1ola: Universidad de Comillas)<br \/>\nROSA SORIANO: La situaci\u00f3n laboral de los marroqu\u00edes en Espa\u00f1a (I.P. del proyecto relocalizaci\u00f3n industrial y migraci\u00f3n de la Universidad de Granada)<\/p>\n<p>Para m\u00e1s informaci\u00f3n consultar el documento\u00a0<a href=\"http:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2019\/04\/Jornadas-departamento-Sociolog\u00eda-III-2019.pdf\">Jornadas departamento Sociolog\u00eda III (2019)<\/a><script><\/p>\n<p><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los d\u00edas 26 y 27 de abril tendr\u00e1n lugar las jornadas \u00abAn\u00e1lisis de Problemas Sociales de nuestro tiempo\u00bb, organizadas por la UNED y m\u00e1s concretamente por el M\u00e1ster en Problemas Sociales, el departamento de Sociolog\u00eda III y el programa de Doctorado de Problemas Sociales. VIERNES 26 DE ABRIL 9.00\/9.30. PRESENTACI\u00d3N DE LAS JORNADAS: JOS\u00c9 ANTONIO [&hellip;]<\/p>\n","protected":false},"author":1413,"featured_media":1189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,4],"tags":[],"class_list":["post-1175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades","category-comunicacion-y-cultura-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>An\u00e1lisis de Problemas Sociales de nuestro tiempo - Jornadas UNED 2019 - Grupo de Estudios sobre Sociedad y Pol\u00edtica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lisis de Problemas Sociales de nuestro tiempo - Jornadas UNED 2019 - Grupo de Estudios sobre Sociedad y Pol\u00edtica\" \/>\n<meta property=\"og:description\" content=\"Los d\u00edas 26 y 27 de abril tendr\u00e1n lugar las jornadas \u00abAn\u00e1lisis de Problemas Sociales de nuestro tiempo\u00bb, organizadas por la UNED y m\u00e1s concretamente por el M\u00e1ster en Problemas Sociales, el departamento de Sociolog\u00eda III y el programa de Doctorado de Problemas Sociales. VIERNES 26 DE ABRIL 9.00\/9.30. PRESENTACI\u00d3N DE LAS JORNADAS: JOS\u00c9 ANTONIO [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo de Estudios sobre Sociedad y Pol\u00edtica\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-23T12:26:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-01T21:06:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2019\/04\/UNED_Sociolog\u00eda.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"206\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"galonso7\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrupoEstudios\" \/>\n<meta name=\"twitter:site\" content=\"@GrupoEstudios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"galonso7\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/\"},\"author\":{\"name\":\"galonso7\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/person\\\/a451d78347903372e2f1f0974f314eba\"},\"headline\":\"An\u00e1lisis de Problemas Sociales de nuestro tiempo &#8211; Jornadas UNED 2019\",\"datePublished\":\"2019-04-23T12:26:31+00:00\",\"dateModified\":\"2019-05-01T21:06:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/\"},\"wordCount\":484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2019\\\/04\\\/UNED_Sociolog\u00eda.gif\",\"articleSection\":[\"ACTIVIDADES\",\"Comunicaci\u00f3n y cultura pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/\",\"name\":\"An\u00e1lisis de Problemas Sociales de nuestro tiempo - Jornadas UNED 2019 - Grupo de Estudios sobre Sociedad y Pol\u00edtica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2019\\\/04\\\/UNED_Sociolog\u00eda.gif\",\"datePublished\":\"2019-04-23T12:26:31+00:00\",\"dateModified\":\"2019-05-01T21:06:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2019\\\/04\\\/UNED_Sociolog\u00eda.gif\",\"contentUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2019\\\/04\\\/UNED_Sociolog\u00eda.gif\",\"width\":206,\"height\":98},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00e1lisis de Problemas Sociales de nuestro tiempo &#8211; Jornadas UNED 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#website\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\",\"name\":\"Grupo de Estudios sobre Sociedad y Pol\u00edtica\",\"description\":\"P\u00e1gina web del Grupo de Estudios sobre Sociedad y Pol\u00edtica (GESP)\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\"},\"alternateName\":\"GESP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#organization\",\"name\":\"GESP\",\"alternateName\":\"Grupo de Estudios Sobre Sociedad y Pol\u00edtica\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/07\\\/GESP.png\",\"contentUrl\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2026\\\/07\\\/GESP.png\",\"width\":1000,\"height\":1000,\"caption\":\"GESP\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/GrupoEstudios\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.uned.es\\\/gesp\\\/#\\\/schema\\\/person\\\/a451d78347903372e2f1f0974f314eba\",\"name\":\"galonso7\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lisis de Problemas Sociales de nuestro tiempo - Jornadas UNED 2019 - Grupo de Estudios sobre Sociedad y Pol\u00edtica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/","og_locale":"es_ES","og_type":"article","og_title":"An\u00e1lisis de Problemas Sociales de nuestro tiempo - Jornadas UNED 2019 - Grupo de Estudios sobre Sociedad y Pol\u00edtica","og_description":"Los d\u00edas 26 y 27 de abril tendr\u00e1n lugar las jornadas \u00abAn\u00e1lisis de Problemas Sociales de nuestro tiempo\u00bb, organizadas por la UNED y m\u00e1s concretamente por el M\u00e1ster en Problemas Sociales, el departamento de Sociolog\u00eda III y el programa de Doctorado de Problemas Sociales. VIERNES 26 DE ABRIL 9.00\/9.30. PRESENTACI\u00d3N DE LAS JORNADAS: JOS\u00c9 ANTONIO [&hellip;]","og_url":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/","og_site_name":"Grupo de Estudios sobre Sociedad y Pol\u00edtica","article_published_time":"2019-04-23T12:26:31+00:00","article_modified_time":"2019-05-01T21:06:36+00:00","og_image":[{"width":206,"height":98,"url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2019\/04\/UNED_Sociolog\u00eda.gif","type":"image\/gif"}],"author":"galonso7","twitter_card":"summary_large_image","twitter_creator":"@GrupoEstudios","twitter_site":"@GrupoEstudios","twitter_misc":{"Escrito por":"galonso7","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/#article","isPartOf":{"@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/"},"author":{"name":"galonso7","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/person\/a451d78347903372e2f1f0974f314eba"},"headline":"An\u00e1lisis de Problemas Sociales de nuestro tiempo &#8211; Jornadas UNED 2019","datePublished":"2019-04-23T12:26:31+00:00","dateModified":"2019-05-01T21:06:36+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/"},"wordCount":484,"commentCount":0,"publisher":{"@id":"https:\/\/blogs.uned.es\/gesp\/#organization"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2019\/04\/UNED_Sociolog\u00eda.gif","articleSection":["ACTIVIDADES","Comunicaci\u00f3n y cultura pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/","url":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/","name":"An\u00e1lisis de Problemas Sociales de nuestro tiempo - Jornadas UNED 2019 - Grupo de Estudios sobre Sociedad y Pol\u00edtica","isPartOf":{"@id":"https:\/\/blogs.uned.es\/gesp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/#primaryimage"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2019\/04\/UNED_Sociolog\u00eda.gif","datePublished":"2019-04-23T12:26:31+00:00","dateModified":"2019-05-01T21:06:36+00:00","breadcrumb":{"@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/#primaryimage","url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2019\/04\/UNED_Sociolog\u00eda.gif","contentUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2019\/04\/UNED_Sociolog\u00eda.gif","width":206,"height":98},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.uned.es\/gesp\/analisis-de-problemas-sociales-de-nuestro-tiempo-jornadas-uned-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.uned.es\/gesp\/"},{"@type":"ListItem","position":2,"name":"An\u00e1lisis de Problemas Sociales de nuestro tiempo &#8211; Jornadas UNED 2019"}]},{"@type":"WebSite","@id":"https:\/\/blogs.uned.es\/gesp\/#website","url":"https:\/\/blogs.uned.es\/gesp\/","name":"Grupo de Estudios sobre Sociedad y Pol\u00edtica","description":"P\u00e1gina web del Grupo de Estudios sobre Sociedad y Pol\u00edtica (GESP)","publisher":{"@id":"https:\/\/blogs.uned.es\/gesp\/#organization"},"alternateName":"GESP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.uned.es\/gesp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.uned.es\/gesp\/#organization","name":"GESP","alternateName":"Grupo de Estudios Sobre Sociedad y Pol\u00edtica","url":"https:\/\/blogs.uned.es\/gesp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/07\/GESP.png","contentUrl":"https:\/\/blogs.uned.es\/gesp\/wp-content\/uploads\/sites\/21\/2026\/07\/GESP.png","width":1000,"height":1000,"caption":"GESP"},"image":{"@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/GrupoEstudios"]},{"@type":"Person","@id":"https:\/\/blogs.uned.es\/gesp\/#\/schema\/person\/a451d78347903372e2f1f0974f314eba","name":"galonso7"}]}},"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/1175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/users\/1413"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/comments?post=1175"}],"version-history":[{"count":2,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/1175\/revisions"}],"predecessor-version":[{"id":1179,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/posts\/1175\/revisions\/1179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/media\/1189"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/media?parent=1175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/categories?post=1175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/gesp\/wp-json\/wp\/v2\/tags?post=1175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}