{"id":1317,"date":"2021-12-21T08:53:11","date_gmt":"2021-12-21T07:53:11","guid":{"rendered":"https:\/\/blogs.uned.es\/compedigi\/?p=1317"},"modified":"2021-12-21T08:53:13","modified_gmt":"2021-12-21T07:53:13","slug":"nuevo-curso-capacitacion-de-formadores-en-la-competencia-digital-en-seguridad-en-la-red","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/compedigi\/2021\/12\/21\/nuevo-curso-capacitacion-de-formadores-en-la-competencia-digital-en-seguridad-en-la-red\/","title":{"rendered":"Nuevo curso: Capacitaci\u00f3n de formadores en la Competencia Digital en Seguridad en la Red"},"content":{"rendered":"\n<p><strong>Trabajo de CUATRO grandes temas o subcompetencias;<\/strong> Protecci\u00f3n de informaci\u00f3n y datos personales, protecci\u00f3n de la identidad digital, protecci\u00f3n de los contenidos digitales, medidas de seguridad y uso responsable y seguro de la tecnolog\u00eda.<\/p>\n\n\n\n<p><strong>Descripci\u00f3n y<\/strong> <strong>objetivos:<\/strong> El curso tiene como finalidad el fortalecimiento y la movilizaci\u00f3n de las competencias digitales adquiridas durante la capacitaci\u00f3n virtual para la protecci\u00f3n de informaci\u00f3n y datos personales, protecci\u00f3n de la identidad digital, protecci\u00f3n de los contenidos digitales, medidas de seguridad y uso responsable y seguro de la tecnolog\u00eda. Para ello, los participantes deber\u00e1n aprender a seleccionar y utilizar diferentes medios tecnol\u00f3gicos de protecci\u00f3n personal, laboral y del medioambiente, teniendo en cuenta los destinatarios espec\u00edficos y metas, adaptando estrategias y modos de acci\u00f3n; mostrando un comportamiento responsable en los medios digitales, adaptando su discurso y pr\u00e1ctica al contexto y \u00e1mbito en el que se encuentren inmersos.<\/p>\n\n\n\n<p><strong>Dirigido a<\/strong>:<\/p>\n\n\n\n<p>&#8211; Pertenecer al personal permanente de las administraciones p\u00fablicas de alguno de los pa\u00edses participantes (Am\u00e9rica Latina y Caribe &#8211; ALC) <\/p>\n\n\n\n<p>&#8211; Gestores, personal t\u00e9cnico y profesional cient\u00edfico y\/o de apoyo en los siguientes \u00e1mbitos de actuaci\u00f3n; gesti\u00f3n general del sector p\u00fablico y sus capacidades, educaci\u00f3n, administraci\u00f3n, ciencia, tecnolog\u00eda e innovaci\u00f3n, principalmente.<\/p>\n\n\n\n<p><strong>Pa\u00edses de los participantes\/destinatarios: <\/strong>Argentina; Bolivia; Brasil; Chile; Colombia; Costa Rica; Cuba; Dominica; Ecuador; El Salvador; Granada; Guatemala; Honduras; M\u00e9xico; Nicaragua; Panam\u00e1; Paraguay; Per\u00fa; Puerto Rico; Rep\u00fablica Dominicana; Uruguay; Venezuela<\/p>\n\n\n\n<p><strong>Requisitos:<\/strong><\/p>\n\n\n\n<p>a) Completar formulario de inscripci\u00f3n. <\/p>\n\n\n\n<p>b) Adjuntar Carta Aval de la Instituci\u00f3n donde labora (ver plantilla en Convocatoria). Adjuntar CV. <\/p>\n\n\n\n<p>d) Adjuntar Propuesta Proyecto de Intervenci\u00f3n (incorporada en el mismo archivo que el CV).<\/p>\n\n\n\n<p><strong>Contenidos y Metodolog\u00eda:<\/strong> Cuatro bloques de contenido. Se abordar\u00e1n desde tres niveles (General, Profundizaci\u00f3n y desarrollo y Aplicaci\u00f3n). <\/p>\n\n\n\n<p>1.- Protecci\u00f3n de dispositivos. <\/p>\n\n\n\n<p>2.- Protecci\u00f3n de datos personales y de identidad digital. <\/p>\n\n\n\n<p>3.- Protecci\u00f3n de la salud y del bienestar. <\/p>\n\n\n\n<p>4.- Protecci\u00f3n medioambiental. La estrategia metodol\u00f3gica se denomina PBL (<em>Problem-based learning<\/em>). Al inicio de la formaci\u00f3n, cada participante presentar\u00e1 una situaci\u00f3n problem\u00e1tica en su entorno laboral. Al finalizar la formaci\u00f3n cada participante presentar\u00e1 un proyecto de intervenci\u00f3n sobre la soluci\u00f3n (total o parcial) de la situaci\u00f3n problem\u00e1tica de su entorno laboral presentada al inicio, en el que se aplique el \u00e1rea competencial en SEGURIDAD EN LA RED).<\/p>\n\n\n\n<p><strong>Coste de la matr\u00edcula:<\/strong> Sin coste<\/p>\n\n\n\n<p><strong>Tipo de ayuda:<\/strong> Aula Virtual (material metodol\u00f3gico, t\u00e9cnico e inform\u00e1tico).<\/p>\n\n\n\n<p><strong>Certificaci\u00f3n<\/strong>: Se entregar\u00e1 certificados a los participantes que cumplan los siguientes requisitos: <\/p>\n\n\n\n<p>1. Asistencia a las sesiones sincr\u00f3nicas. <\/p>\n\n\n\n<p>2. Participaci\u00f3n en las intervenciones asincr\u00f3nicas que se realizar\u00e1n en el espacio de comunicaci\u00f3n de la plataforma virtual. <\/p>\n\n\n\n<p>3. Realizaci\u00f3n de las actividades formativas dise\u00f1adas en cada uno de los bloques de contenido. <\/p>\n\n\n\n<p>4. Realizaci\u00f3n de la actividad de evaluaci\u00f3n final (Proyecto de Intervenci\u00f3n).<\/p>\n\n\n\n<p><strong>Coordinaci\u00f3n de la actividad por parte de la entidad organizadora:<\/strong> Ana Mar\u00eda Mart\u00edn Cuadrado Profesora Titular Universitaria, Facultad de Educaci\u00f3n, Departamento Did\u00e1ctica, Organizaci\u00f3n Escolar y Did\u00e1cticas Especiales +34 661204653 &#8211;  <a rel=\"noreferrer noopener\" href=\"mailto:amartin@edu.uned.es\" target=\"_blank\">amartin@edu.uned.es<\/a><\/p>\n\n\n\n<p><strong>Coordinaci\u00f3n de la actividad por parte de AECID<\/strong>: Karina Olachea (<a href=\"mailto:elvi.olachea@aecid.es\" target=\"_blank\" rel=\"noreferrer noopener\">elvi.olachea@aecid.es<\/a>)<\/p>\n\n\n\n<p><strong>Actividades asociadas:<\/strong> A trav\u00e9s de la plataforma de UNED ABIERTA, en: <a rel=\"noreferrer noopener\" href=\"https:\/\/iedra.uned.es\/\" target=\"_blank\">https:\/\/iedra.uned.es\/<\/a> se est\u00e1 ofreciendo formaci\u00f3n en competencia digital a docentes, en formato NOOC. <\/p>\n\n\n\n<p>&#8211; Capacitaci\u00f3n de formadores en la Competencia Digital de: <\/p>\n\n\n\n<p>a) Informaci\u00f3n y Alfabetizaci\u00f3n Informacional. <\/p>\n\n\n\n<p>b) Comunicaci\u00f3n y Colaboraci\u00f3n <\/p>\n\n\n\n<p>c) Contenidos digitales &#8211; Presentaci\u00f3n de proyectos en territorios de ALC &#8211; Programa de radio sobre Proyecto de Capacitaci\u00f3n de formadores en competencias digitales<\/p>\n\n\n\n<p><strong>Pol\u00edtica de transparencia y calidad:<\/strong> Se valorar\u00e1, de forma principal, la Propuesta de Proyecto de Intervenci\u00f3n en cuanto a un problema detectado en el contexto laboral, avalado por la Instituci\u00f3n, y que sea factible su resoluci\u00f3n o mejora a trav\u00e9s de la capacitaci\u00f3n. Para ello, al postularse deber\u00e1 aportar al momento de la postulaci\u00f3n la Propuesta de Proyecto en la plantilla que encontrar\u00e1 en el Programa del Curso (p\u00e1gs. 5 a 8).<\/p>\n\n\n\n<p><strong>Comunidad Tem\u00e1tica:<\/strong> Cohesi\u00f3n Social<\/p>\n\n\n\n<p><strong>Materia:<\/strong> Educaci\u00f3n<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/intercoonecta.aecid.es\/aplicaciones\/cvc\/_layouts\/15\/intercoonecta\/login.aspx?ReturnUrl=%2faplicaciones%2fcvc%2f_layouts%2f15%2fAuthenticate.aspx%3fSource%3d%252Faplicaciones%252Fcvc%252Farea%252Dprivada%252Finscripcion%252Dactividad%253FidActividad%253D139307&amp;Source=%2Faplicaciones%2Fcvc%2Farea%2Dprivada%2Finscripcion%2Dactividad%3FidActividad%3D139307\" target=\"_blank\" rel=\"noreferrer noopener\">ACCEDE PARA LA INSCRIPCI\u00d3N<\/a><\/div>\n<\/div>\n\n\n\n<p>Organiz<strong>a<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/intercoonecta.aecid.es\/PublishingImages\/Socios%20de%20conocimiento\/uned.jpg\" alt=\"UNED - Universidad Nacional de Educaci\u00f3n a Distancia (Espa\u00f1a)\" title=\"UNED - Universidad Nacional de Educaci\u00f3n a Distancia (Espa\u00f1a)\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/intercoonecta.aecid.es\/PublishingImages\/Socios%20de%20conocimiento\/OEI.png\" alt=\"OEI - Organizaci\u00f3n de Estados Iberoamericanos para la Educaci\u00f3n, la Ciencia y la Cultura\" title=\"OEI - Organizaci\u00f3n de Estados Iberoamericanos para la Educaci\u00f3n, la Ciencia y la Cultura\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/intercoonecta.aecid.es\/PublishingImages\/Socios%20de%20conocimiento\/CABb.png\" alt=\"CAB - Convenio Andr\u00e9s Bello\" title=\"CAB - Convenio Andr\u00e9s Bello\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> El curso tiene como finalidad el fortalecimiento y la movilizaci\u00f3n de las competencias digitales adquiridas durante la capacitaci\u00f3n virtual para la protecci\u00f3n de informaci\u00f3n y datos personales, protecci\u00f3n de la identidad digital, protecci\u00f3n de los contenidos digitales, medidas de seguridad y uso responsable y seguro de la tecnolog\u00eda. <\/p>\n","protected":false},"author":7393,"featured_media":1323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,7],"tags":[33,23,21],"class_list":["post-1317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos","category-noticias","tag-competencia-digital","tag-formacion-2","tag-investigacion"],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/posts\/1317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/users\/7393"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/comments?post=1317"}],"version-history":[{"count":4,"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/posts\/1317\/revisions"}],"predecessor-version":[{"id":1329,"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/posts\/1317\/revisions\/1329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/media\/1323"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/media?parent=1317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/categories?post=1317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/compedigi\/wp-json\/wp\/v2\/tags?post=1317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}