{"id":565,"date":"2020-06-18T13:40:27","date_gmt":"2020-06-18T11:40:27","guid":{"rendered":"http:\/\/blogs.uned.es\/aps\/?p=565"},"modified":"2020-06-18T13:40:27","modified_gmt":"2020-06-18T11:40:27","slug":"pedagogas-os-solidarias-os-una-iniciativa-en-tiempos-de-pandemia-por-estudiantes-y-egresadas-os-de-la-facultad-de-educacion-uned","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/aps\/2020\/06\/18\/pedagogas-os-solidarias-os-una-iniciativa-en-tiempos-de-pandemia-por-estudiantes-y-egresadas-os-de-la-facultad-de-educacion-uned\/","title":{"rendered":"Pedagogas\/os solidarias\/os: una iniciativa en tiempos de pandemia por estudiantes y egresadas\/os de la Facultad de Educaci\u00f3n (UNED)"},"content":{"rendered":"<p style=\"text-align: justify\">Desde la Facultad de Educaci\u00f3n de la UNED, algunas\/os estudiantes y egresadas\/os se han organizado durante el confinamiento para \u00abayudar a todas aquellas familias que est\u00e1n teniendo dificultades para atender a sus hij@s, debido al estado de alarma provocado por el COVID-19\u00bb, como afirman en su p\u00e1gina de Facebook <a href=\"https:\/\/www.facebook.com\/Pedagogos-Solidarios-108466384141543\/\">Pedagogos Solidarios<\/a>. Mediante este servicio comunitario, los aprendizajes como estudiantes y\/o profesionales del \u00e1rea (socio)educativa est\u00e1n siendo muy significativos.\u00a0 Nos lo cuentan ellas\/os mismas\/os en unas breves l\u00edneas que han tenido la generosidad de compartir con la Oficina de ApS de la UNED y que reproducimos a continuaci\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><i>&lt;&lt; Cuando nos embarcamos en el proyecto pedagogos solidarios, lo hicimos poniendo nuestro coraz\u00f3n y energ\u00eda a disposici\u00f3n de la sociedad, una sociedad que de repente se hab\u00eda parado.\u00a0<\/i><i>Sin que nadie lo esperase, de pronto un d\u00eda el mundo dej\u00f3 de caminar a esa velocidad vertiginosa que nos lleva a diario de un sitio para otro, sin saber muy bien porqu\u00e9.\u00a0Fueron momentos de mucha incertidumbre, nuestras vidas hab\u00edan dado un vuelco y no sab\u00edamos por d\u00f3nde empezar a organizarlas, en ese instante supimos que era necesario aportar nuestro granito de arena en aquel caos que, sin avisar, se hab\u00eda instalado en nuestras vidas, y la mejor forma de hacerlo era desde nuestra profesionalidad y vocaci\u00f3n.<\/i><\/p>\n<p style=\"text-align: justify\"><i><br \/>\nSin lugar a dudas, la experiencia est\u00e1 resultando gratificante y muy enriquecedora, tanto a nivel profesional, una de nuestras compa\u00f1eras de equipo ha realizado su TFG en relaci\u00f3n a uno de los temas que tratamos, en concreto el bullying; como a nivel personal.\u00a0Tenemos la sensaci\u00f3n de estar desarrollando una labor social que es muy necesaria y hemos percibido mucha calidez y agradecimiento por parte de las familias que han solicitado nuestra ayuda.\u00a0<\/i><i>Las familias que est\u00e1n contactando con nosotros han sufrido diversas dificultades, desde la imposibilidad de conciliar su vida laboral con las tareas acad\u00e9micas de sus hijos, ya sea por falta de tiempo o de conocimientos, hasta un gran abanico de problemas emocionales que no saben c\u00f3mo gestionar, problemas de bullying, dislexia , valores morales y colectivos de refugiados; es ah\u00ed donde nuestra labor como equipo entra en juego, donde volcamos toda nuestra voluntad de ser un servicio de ayuda altruista para una sociedad que est\u00e1 sufriendo, tratando de paliar ese sufrimiento en la mediad de lo posible.<\/i><\/p>\n<p style=\"text-align: justify\"><i><br \/>\nNos sentimos privilegiadas por disponer de las herramientas que nos permiten intentar que el d\u00eda a d\u00eda de estas personas sea un poco m\u00e1s sencillo, m\u00e1s llevadero, y m\u00e1s feliz.\u00a0Somos conscientes de que este episodio, afortunadamente, pasar\u00e1, pero a\u00fan as\u00ed nuestro esp\u00edritu va m\u00e1s all\u00e1 de ser una ayuda puntual para el momento, si de algo ha servido esta experiencia ha sido para destapar la gran cantidad de problemas sociales a los que se enfrentan diariamente muchas personas, y es por eso, que estamos decididas a continuar con el proyecto mientras haya una sola persona que pueda beneficiarse de nuestra ayuda.<\/i><\/p>\n<p style=\"text-align: justify\"><i><br \/>\nNo queremos desaprovechar la ocasi\u00f3n de decirle al mundo que la capacidad de resiliencia del ser humano nos hace grandes, que saldremos fortalecidos de esta experiencia, y que las lecciones aprendidas en estos duros momentos nos servir\u00e1n en el futuro para ser mejores personas, m\u00e1s emp\u00e1ticos y solidarios con nuestro alrededor.\u00a0<\/i><i>Mucha fuerza para todos y no os quepa la menor duda que superaremos este trance y creceremos como sociedad. &gt;&gt;<\/i><\/p>\n<p style=\"text-align: justify\"><i><br \/>\nPedagogos solidarios.<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Facultad de Educaci\u00f3n de la UNED, algunas\/os estudiantes y egresadas\/os se han organizado durante el confinamiento para \u00abayudar a todas aquellas familias que est\u00e1n teniendo dificultades para atender a sus hij@s, debido al estado de alarma provocado por el COVID-19\u00bb, como afirman en su p\u00e1gina de Facebook Pedagogos Solidarios. Mediante este servicio comunitario, los aprendizajes como estudiantes y\/o profesionales del \u00e1rea (socio)educativa est\u00e1n siendo muy significativos.\u00a0 Nos lo cuentan ellas\/os mismas\/os en unas breves l\u00edneas que han tenido la generosidad de compartir con la Oficina de ApS de la UNED y que reproducimos a continuaci\u00f3n: &nbsp; &lt;&lt; Cuando nos embarcamos en el proyecto pedagogos solidarios, lo hicimos poniendo nuestro coraz\u00f3n y energ\u00eda a disposici\u00f3n de la sociedad, una sociedad que de repente se hab\u00eda parado.\u00a0Sin que nadie lo esperase, de pronto un d\u00eda el mundo dej\u00f3 de caminar a esa velocidad vertiginosa que nos lleva a diario de un sitio para otro, sin saber muy bien porqu\u00e9.\u00a0Fueron momentos de mucha incertidumbre, nuestras vidas hab\u00edan dado un vuelco y no sab\u00edamos por d\u00f3nde empezar a organizarlas, en ese instante supimos que era necesario aportar nuestro granito de arena en aquel caos que, sin avisar, se hab\u00eda instalado en nuestras vidas, y la mejor forma de hacerlo era desde nuestra profesionalidad y vocaci\u00f3n. Sin lugar a dudas, la experiencia est\u00e1 resultando gratificante y muy enriquecedora, tanto a nivel profesional, una de nuestras compa\u00f1eras de equipo ha realizado su TFG en relaci\u00f3n a uno de los temas que tratamos, en concreto el bullying; como a nivel personal.\u00a0Tenemos la sensaci\u00f3n de estar desarrollando una labor social que es muy necesaria y hemos percibido mucha calidez y agradecimiento por parte de las familias que han solicitado nuestra ayuda.\u00a0Las familias que est\u00e1n contactando con nosotros han sufrido diversas dificultades, desde la imposibilidad de conciliar su vida laboral con las tareas acad\u00e9micas de sus hijos, ya sea por falta de tiempo o de conocimientos, hasta un gran abanico de problemas emocionales que no saben c\u00f3mo gestionar, problemas de bullying, dislexia , valores morales y colectivos de refugiados; es ah\u00ed donde nuestra labor como equipo entra en juego, donde volcamos toda nuestra voluntad de ser un servicio de ayuda altruista para una sociedad que est\u00e1 sufriendo, tratando de paliar ese sufrimiento en la mediad de lo posible. Nos sentimos privilegiadas por disponer de las herramientas que nos permiten intentar que el d\u00eda a d\u00eda de estas personas sea un poco m\u00e1s sencillo, m\u00e1s llevadero, y m\u00e1s feliz.\u00a0Somos conscientes de que este episodio, afortunadamente, pasar\u00e1, pero a\u00fan as\u00ed nuestro esp\u00edritu va m\u00e1s all\u00e1 de ser una ayuda puntual para el momento, si de algo ha servido esta experiencia ha sido para destapar la gran cantidad de problemas sociales a los que se enfrentan diariamente muchas personas, y es por eso, que estamos decididas a continuar con el proyecto mientras haya una sola persona que pueda beneficiarse de nuestra ayuda. No queremos desaprovechar la ocasi\u00f3n de decirle al mundo que la capacidad de resiliencia del ser humano nos hace grandes, que saldremos fortalecidos de esta experiencia, y que las lecciones aprendidas en estos duros momentos nos servir\u00e1n en el futuro para ser mejores personas, m\u00e1s emp\u00e1ticos y solidarios con nuestro alrededor.\u00a0Mucha fuerza para todos y no os quepa la menor duda que superaremos este trance y creceremos como sociedad. &gt;&gt; Pedagogos solidarios. &nbsp; &nbsp;<\/p>\n","protected":false},"author":7129,"featured_media":569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/posts\/565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/users\/7129"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/comments?post=565"}],"version-history":[{"count":2,"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/posts\/565\/revisions"}],"predecessor-version":[{"id":573,"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/posts\/565\/revisions\/573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/media\/569"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/media?parent=565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/categories?post=565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/aps\/wp-json\/wp\/v2\/tags?post=565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}