{"id":6033,"date":"2024-03-04T08:56:16","date_gmt":"2024-03-04T07:56:16","guid":{"rendered":"https:\/\/blogs.uned.es\/alumni\/?p=6033"},"modified":"2024-03-04T09:47:32","modified_gmt":"2024-03-04T08:47:32","slug":"el-coie-de-la-uned-entrega-sus-premios-de-emprendimiento-y-companero-mentor","status":"publish","type":"post","link":"https:\/\/blogs.uned.es\/alumni\/2024\/03\/04\/el-coie-de-la-uned-entrega-sus-premios-de-emprendimiento-y-companero-mentor\/","title":{"rendered":"El COIE de la UNED entrega sus Premios de Emprendimiento y Compa\u00f1ero mentor"},"content":{"rendered":"<p><span style=\"color: #000000\">El <strong><a href=\"https:\/\/www.uned.es\/universidad\/inicio\/unidad\/coie.html\" target=\"_blank\" rel=\"noopener\">Centro de Orientaci\u00f3n, Informaci\u00f3n y Empleo (COIE)<\/a><\/strong> de la Universidad Nacional de Educaci\u00f3n a Distancia (UNED) celebr\u00f3 la entrega de los premios anuales de emprendimiento y compa\u00f1ero mentor en una ceremonia llena de reconocimientos y emociones.<\/span><\/p>\n<p><span style=\"color: #000000\">En esta ocasi\u00f3n, el COIE reconoci\u00f3 el esfuerzo y la creatividad de los estudiantes emprendedores que han destacado por sus proyectos innovadores. Los premios de emprendimiento fueron entregados a aquellos estudiantes que han demostrado habilidades excepcionales en el desarrollo de sus propias iniciativas empresariales, destacando en \u00e1reas tan diversas como la tecnolog\u00eda, la salud, la educaci\u00f3n y el medio ambiente.<\/span><\/p>\n<p>Asimismo, se otorgaron los premios al compa\u00f1ero mentor, en los cuales se reconoci\u00f3 la labor de aquellos estudiantes que han brindado un apoyo invaluable a sus compa\u00f1eros, gui\u00e1ndolos y motiv\u00e1ndolos en su trayectoria acad\u00e9mica y profesional.<\/p>\n<p>En palabras de la Dra. Ana V\u00e1zquez, directora del COIE de la UNED: \u00abEstamos orgullosos de poder reconocer el talento y el compromiso de nuestros estudiantes. Los premios de emprendimiento y compa\u00f1ero mentor reflejan el esp\u00edritu de colaboraci\u00f3n y excelencia que caracteriza a nuestra comunidad universitaria\u00bb.<\/p>\n<p>Los galardonados expresaron su gratitud por el reconocimiento recibido y destacaron la importancia del apoyo y la orientaci\u00f3n que reciben por parte del COIE de la UNED en su camino hacia el \u00e9xito profesional.<\/p>\n<p>La ceremonia de entrega de premios cont\u00f3 con la participaci\u00f3n de autoridades acad\u00e9micas, profesores y estudiantes, quienes celebraron juntos los logros y el talento de la comunidad universitaria de la UNED.<\/p>\n<p>El COIE de la UNED reafirma as\u00ed su compromiso de promover el esp\u00edritu emprendedor y el desarrollo profesional de sus estudiantes, brind\u00e1ndoles las herramientas y el apoyo necesarios para alcanzar sus metas y convertirse en l\u00edderes en sus respectivos campos.<\/p>\n<p><a href=\"https:\/\/comunicacion.uned.es\/news\/show\/112531\/el-coie-de-la-uned-entrega-sus-premios-de-emprendimiento-y-companero-mentor.html\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"color: #000000\">MAS INFORMACI\u00d3N<\/span><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centro de Orientaci\u00f3n, Informaci\u00f3n y Empleo (COIE) de la Universidad Nacional de Educaci\u00f3n a Distancia (UNED) celebr\u00f3 la entrega de los premios anuales de emprendimiento y compa\u00f1ero mentor en &hellip; <a href=\"https:\/\/blogs.uned.es\/alumni\/2024\/03\/04\/el-coie-de-la-uned-entrega-sus-premios-de-emprendimiento-y-companero-mentor\/\" title=\"El COIE de la UNED entrega sus Premios de Emprendimiento y Compa\u00f1ero mentor\" class=\"read-more\">Read More<\/a><\/p>\n","protected":false},"author":7191,"featured_media":6035,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/posts\/6033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/users\/7191"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/comments?post=6033"}],"version-history":[{"count":2,"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/posts\/6033\/revisions"}],"predecessor-version":[{"id":6047,"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/posts\/6033\/revisions\/6047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/media\/6035"}],"wp:attachment":[{"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/media?parent=6033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/categories?post=6033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.uned.es\/alumni\/wp-json\/wp\/v2\/tags?post=6033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}